{"id":12007,"date":"2014-05-09T12:50:03","date_gmt":"2014-05-09T11:50:03","guid":{"rendered":"http:\/\/www.doulkeridis.be\/blog\/?p=12007"},"modified":"2026-04-14T16:47:08","modified_gmt":"2026-04-14T15:47:08","slug":"les-occupations-temporaires-des-experiences-a-partager","status":"publish","type":"post","link":"https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/","title":{"rendered":"Les occupations temporaires: des exp\u00e9riences \u00e0 partager"},"content":{"rendered":"<p><a href=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2014\/05\/DSC00977.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-12010\" alt=\"DSC00977\" src=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2014\/05\/DSC00977-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2014\/05\/DSC00977-300x199.jpg 300w, https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2014\/05\/DSC00977-1024x680.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Les occupations temporaires font d\u00e9sormais partie des dispositifs en R\u00e9gion Bruxelles-Capitale pour faire face aux d\u00e9fis sociaux que vivent de nombreux bruxellois. La F\u00e9BUL lui consacrait un colloque d&rsquo;une journ\u00e9e \u00e0 destination des acteurs de terrain du secteur de l&rsquo;insertion par le logement, du logement social et des d\u00e9cideurs politiques. Ce colloque m&rsquo;a donn\u00e9 l&rsquo;occasion de rappeler les importantes \u00e9volutions qui ont vu le jour sous cette l\u00e9gislature: lancement d&rsquo;occupations temporaires dans le logement social, inscription des occupations temporaires dans le code du logement, lancement d&rsquo;une agence occupation temporaire r\u00e9gionale.<\/p>\n<p>Sous cette l\u00e9gislature, la R\u00e9gion de Bruxelles-Capitale a pris en main de mani\u00e8re particuli\u00e8rement volontaire la question du logement. Les budgets ont \u00e9t\u00e9 renforc\u00e9 de mani\u00e8re significative et les dispositifs existants ont \u00e9t\u00e9 amplifi\u00e9s. Cependant, la R\u00e9gion reste confront\u00e9e \u00e0 une r\u00e9alit\u00e9 choquante: de grandes surfaces b\u00e2ties sont inoccup\u00e9es. Que ce soit des bureaux vides, des \u00e9tages au-dessus des commerces ou des logements \u00e0 l&rsquo;abandon, ces situations ne sont pas acceptables dans une R\u00e9gion comme la n\u00f4tre qui fait face \u00e0 un boom d\u00e9mographique et qui a besoin de nouvelles r\u00e9ponses.<\/p>\n<p>Pour cette raison, j&rsquo;ai tenu \u00e0 mettre en place de nouveaux dispositifs afin de mobiliser ses espaces b\u00e2ties en faveur du logement. J&rsquo;ai notamment mis en place une cellule inoccup\u00e9es au sein de l&rsquo;administration qui identifie les logements vides en R\u00e9gion bruxelloise. Cette cellule manie autant la carotte que le b\u00e2ton. En effet, son but premier est de remettre sur le march\u00e9 ces logements afin qu&rsquo;il retrouve leur fonction premi\u00e8re: accueillir des habitants.<\/p>\n<p>Face \u00e0 la probl\u00e9matique de l&rsquo;inoccupation, certaines associations et certains collectifs d\u00e9cident plus radicalement de mettre en place des occupations. Avant que je ne devienne Secr\u00e9taire d&rsquo;Etat au Logement, l&rsquo;attitude des autorit\u00e9s r\u00e9gionales n&rsquo;\u00e9tait pas toujours des plus conciliatrices. J&rsquo;ai tenu \u00e0 changer l&rsquo;approche de la R\u00e9gion et j&rsquo;ai voulu accompagner ce ph\u00e9nom\u00e8ne par une s\u00e9rie de dispositifs concrets permettant \u00e0 la fois de prot\u00e9ger les occupants et de rassurer les propri\u00e9taires des biens immobiliers occup\u00e9s.<\/p>\n<p>J&rsquo;ai surtout tenu \u00e0 aller plus loin et \u00e0 rendre les pouvoirs publics exemplaires dans ce domaines. En juillet 2009, notre attention avait \u00e9t\u00e9 attir\u00e9e sur le fait que certains logements sociaux en attente de r\u00e9novation pouvaient \u00eatre occup\u00e9s \u00e0 titre pr\u00e9caire pour faire face \u00e0 certaines situations d\u2019urgence et de d\u00e9tresse. Interpell\u00e9s par cette proposition et parall\u00e8lement \u00e0 notre travail de long terme visant \u00e0 r\u00e9pondre \u00e0 cette crise du logement, nous avons d\u00e9cid\u00e9 de mettre en place un groupe de travail afin d\u2019\u00e9tudier cette possibilit\u00e9. Et les travaux qu\u2019il a men\u00e9s ont permis de d\u00e9finir une premi\u00e8re convention-cadre visant \u00e0 servir de r\u00e9f\u00e9rence pour l\u2019analyse future des propositions de convention introduites par les soci\u00e9t\u00e9s de logements (SISP) aupr\u00e8s de la SLRB, voire le cas \u00e9ch\u00e9ant, pour leur servir de mod\u00e8le.<\/p>\n<p>Cette convention d\u00e9finit les droits et devoirs des partenaires \u00e0 savoir notamment la dur\u00e9e de l&rsquo;occupation, les modalit\u00e9s de prolongation, si besoin, l&rsquo;identification de l&rsquo;acteur de l&rsquo;accompagnement social, les frais \u00e0 charge de l&rsquo;occupant notamment assurance incendie, etc. Il nous faut pr\u00e9ciser ici que du fait de la pr\u00e9carit\u00e9 (en termes de b\u00e2ti et de dur\u00e9e) de ces occupations, il n&rsquo;y a donc \u00e9videmment aucune mise en concurrence avec des (candidats-) locataires du logement social<\/p>\n<p>Il s\u2019agissait d\u2019affirmer un certain nombre de crit\u00e8res et de balises. Une fois cette convention-type adopt\u00e9e (mars 2010), une premi\u00e8re exp\u00e9rience a pu \u00eatre lanc\u00e9e \u00e0 la demande de la F\u00e9bul (F\u00e9d\u00e9ration bruxelloise de l\u2019Union pour le Logement), \u00e0 Evere.<\/p>\n<p>4 conditions pour les occupations pr\u00e9caires<\/p>\n<ol>\n<li>Un cadre contractuel n\u00e9goci\u00e9 et volontaire: pour qu&rsquo;une occupation pr\u00e9caire se passe bien, les parties doivent se mettre d&rsquo;accord sur un certain nombre d&rsquo;\u00e9l\u00e9ments essentiels\u00a0; la conclusion d&rsquo;une convention d&rsquo;occupation pr\u00e9caire est \u00e0 mon sens indispensable.<\/li>\n<li>Conditions de s\u00e9curit\u00e9 et salubrit\u00e9.<br \/>\nSi les logements sociaux sont inoccup\u00e9s, c&rsquo;est qu&rsquo;ils doivent faire l&rsquo;objet de travaux de r\u00e9novation. Moyennant de petits travaux, certains de ces logements peuvent \u00eatre occup\u00e9s temporairement dans des conditions de s\u00e9curit\u00e9 et de salubrit\u00e9 satisfaisantes.<\/li>\n<li>Dur\u00e9e limit\u00e9e: ces occupations ne doivent en aucun cas retarder la mise en \u0153uvre des travaux de r\u00e9novation des logements sociaux et ne doivent en aucun cas aboutir \u00e0 \u00e9vincer ou retarder l&rsquo;acc\u00e8s au logement social des m\u00e9nages qui sont inscrits sur la liste d&rsquo;attente des logements sociaux.<\/li>\n<li>Travail social communautaire \/ Accompagnement.<br \/>\nUn accompagnement social des m\u00e9nages qui occupent des logements pr\u00e9caires est indispensable pour plusieurs raisons: d&rsquo;une part parce que les m\u00e9nages qui acceptent un h\u00e9bergement de courte dur\u00e9e sont r\u00e9ellement dans des situations sociales difficiles et qu&rsquo;ils ont besoin d&rsquo;\u00eatre aid\u00e9s, d&rsquo;autre part parce que cette solution d&rsquo;h\u00e9bergement est temporaire et qu&rsquo;il faut accompagner ces m\u00e9nages \u00e0 trouver un logement stable et durable.<\/li>\n<\/ol>\n<p>Plus sp\u00e9cifiquement, le travail d&rsquo;accompagnement des occupations r\u00e9alis\u00e9 par la Febul se base sur une approche de travail social communautaire\u00a0: assembl\u00e9e des habitants, dynamiques de participation et ouverture sur le quartier\u2026<\/p>\n<p>A c\u00f4t\u00e9 de ce travail communautaire, le secteur associatif apporte un accompagnement social individuel aux habitants, qui comprends un volet d&rsquo;accompagnement social d&rsquo;insertion par le logement\u00a0; on rejoint l\u00e0 l&rsquo;activit\u00e9 plus traditionnelle du secteur des Association d&rsquo;insertion par le logement, qui consiste \u00e0 accompagner les personnes dans la recherche d&rsquo;un logement\u00a0: inscription comme demandeur aupr\u00e8s des diff\u00e9rents organismes de logement\u00a0: les SISP, au Fond du logement, aupr\u00e8s des AIS, les services communaux, introductions de demandes d&rsquo;ADIL, aide \u00e0 la recherche sur le march\u00e9 priv\u00e9, etc&#8230;<\/p>\n<p>Le secteur associatif met en place, d\u00e8s le d\u00e9but de toute occupation, un syst\u00e8me \u00ab\u00a0d&rsquo;\u00e9pargne forc\u00e9e\u00a0\u00bb aupr\u00e8s des habitants qui ont donc l&rsquo;obligation de se constituer une r\u00e9serve financi\u00e8re mensuelle, destin\u00e9e \u00e0 couvrir les frais de d\u00e9m\u00e9nagement et\/ou les frais de garantie locative de leur logement une fois qu&rsquo;ils quittent l&rsquo;occupation.<\/p>\n<p>L&rsquo;associatif qui accompagne les occupations offre donc ce qu&rsquo;il peut, pour trouver des solutions de relogements.<\/p>\n<ul>\n<li>Aujourd&rsquo;hui, quatre occupations pr\u00e9caires sont en cours et concernent 27 logements encadr\u00e9e par la FEBUL.<br \/>\nDeux maisons unifamiliales de la SISP \u00ab\u00a0Ieder Zijn Huis\u00a0\u00bb \u00e0 Evere, qui ont fait l&rsquo;objet d&rsquo;une convention d&rsquo;occupation pr\u00e9caire en ao\u00fbt 2010, cette convention conclue pour une dur\u00e9e d&rsquo;un an a fait l&rsquo;objet de 2 renouvellements. Le partenaire de la SISP est la F\u00e9bul, l&rsquo;accompagnement social de ces deux grandes familles est faite par l&rsquo;Union des locataires de Schaerbeek.<\/li>\n<li>Le Foyer Forestois a mis 19 logements \u00e0 disposition de projets d&rsquo;occupations pr\u00e9caires, depuis septembre 2010, pour un an chaque fois. Le Foyer Forestois a \u00e9galement conclu une convention d&rsquo;occupation pr\u00e9caire avec le CPAS de Forest pour 5 logements qui sont utilis\u00e9s par le CPAS comme logements de transit.<\/li>\n<li>Le Foyer Etterbeekois a mis 2 logements \u00e0 disposition de projets d&rsquo;occupations pr\u00e9caires depuis septembre 2012.<\/li>\n<li>Et plus r\u00e9cemment, en juin 2013, la SLRB a marqu\u00e9 son accord sur la conclusion d&rsquo;une convention d&rsquo;occupation pr\u00e9caire entre le Foyer Ixellois et l&rsquo;Asbl \u00ab\u00a0Samenlevingsopbouw\u00a0\u00bb pour l&rsquo;occupation de 4 logements. Ces logements sont en cours de r\u00e9novation (projet Leeggoed).<\/li>\n<\/ul>\n<p>Les exp\u00e9riences sporadiques d&rsquo;occupations temporaires avaient cependant besoin d&rsquo;un soutien structurel, d&rsquo;une assurance juridique que seul le politique pouvait donner. C&rsquo;est d\u00e9sormais chose faite: la r\u00e9forme du code du logement que j&rsquo;ai port\u00e9 et qui a \u00e9t\u00e9 adopt\u00e9e en juillet 2013 par le Parlement r\u00e9gional accorde d\u00e9sormais une existence juridique aux occupations pr\u00e9caires et institutionnalise, en quelque sorte, leur existence.<\/p>\n<p>Enfin, derni\u00e8re intervention de la R\u00e9gion en date en faveur des occupations temporaires: l&rsquo;octroi d&rsquo;une subvention \u00e0 la F\u00e9bul pour la mise en oeuvre d&rsquo;une \u00ab\u00a0Agence occupations temporaires\u00a0\u00bb. L&rsquo;objectif est d&rsquo;en faire un acteur de r\u00e9f\u00e9rence pour tous les projets d&rsquo;occupations temporaires.<\/p>\n<p>Face \u00e0 la crise du logement, je suis convaincu qu\u2019il est indispensable de diversifier les r\u00e9ponses que peuvent donner les pouvoirs publics. En lien avec la soci\u00e9t\u00e9 civile et le monde associatif, les occupations pr\u00e9caires entrent pleinement dans le cadre des r\u00e9ponses concr\u00e8tes et originales que nous devons donner.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les occupations temporaires font d\u00e9sormais partie des dispositifs en R\u00e9gion Bruxelles-Capitale pour faire face aux d\u00e9fis sociaux que vivent de nombreux bruxellois. La F\u00e9BUL lui consacrait un colloque d&rsquo;une journ\u00e9e \u00e0 destination des acteurs de terrain du secteur de l&rsquo;insertion par le logement, du logement social et des d\u00e9cideurs politiques. Ce colloque m&rsquo;a donn\u00e9 l&rsquo;occasion de rappeler les importantes \u00e9volutions qui ont vu le jour sous cette l\u00e9gislature: lancement d&rsquo;occupations temporaires dans le logement social, inscription des occupations temporaires dans le code du logement, lancement d&rsquo;une agence occupation temporaire r\u00e9gionale. Sous cette l\u00e9gislature, la R\u00e9gion de Bruxelles-Capitale a pris en main de mani\u00e8re particuli\u00e8rement volontaire la question du logement. Les budgets ont \u00e9t\u00e9 renforc\u00e9 de mani\u00e8re significative et les dispositifs existants ont \u00e9t\u00e9 amplifi\u00e9s. Cependant, la R\u00e9gion reste confront\u00e9e \u00e0 une r\u00e9alit\u00e9 choquante: de grandes surfaces b\u00e2ties sont inoccup\u00e9es. Que ce soit des bureaux vides, des \u00e9tages au-dessus des commerces ou des logements \u00e0 l&rsquo;abandon, ces situations ne sont pas acceptables dans une R\u00e9gion comme la n\u00f4tre qui fait face \u00e0 un boom d\u00e9mographique et qui a besoin de nouvelles r\u00e9ponses. Pour cette raison, j&rsquo;ai tenu \u00e0 mettre en place de nouveaux dispositifs afin de mobiliser ses espaces b\u00e2ties en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12010,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[1011,984],"class_list":["post-12007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-logement","tag-logement","tag-occupations-temporaires"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les occupations temporaires: des exp\u00e9riences \u00e0 partager - Christos Doulkeridis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les occupations temporaires: des exp\u00e9riences \u00e0 partager - Christos Doulkeridis\" \/>\n<meta property=\"og:description\" content=\"Les occupations temporaires font d\u00e9sormais partie des dispositifs en R\u00e9gion Bruxelles-Capitale pour faire face aux d\u00e9fis sociaux que vivent de nombreux bruxellois. La F\u00e9BUL lui consacrait un colloque d&rsquo;une journ\u00e9e \u00e0 destination des acteurs de terrain du secteur de l&rsquo;insertion par le logement, du logement social et des d\u00e9cideurs politiques. Ce colloque m&rsquo;a donn\u00e9 l&rsquo;occasion de rappeler les importantes \u00e9volutions qui ont vu le jour sous cette l\u00e9gislature: lancement d&rsquo;occupations temporaires dans le logement social, inscription des occupations temporaires dans le code du logement, lancement d&rsquo;une agence occupation temporaire r\u00e9gionale. Sous cette l\u00e9gislature, la R\u00e9gion de Bruxelles-Capitale a pris en main de mani\u00e8re particuli\u00e8rement volontaire la question du logement. Les budgets ont \u00e9t\u00e9 renforc\u00e9 de mani\u00e8re significative et les dispositifs existants ont \u00e9t\u00e9 amplifi\u00e9s. Cependant, la R\u00e9gion reste confront\u00e9e \u00e0 une r\u00e9alit\u00e9 choquante: de grandes surfaces b\u00e2ties sont inoccup\u00e9es. Que ce soit des bureaux vides, des \u00e9tages au-dessus des commerces ou des logements \u00e0 l&rsquo;abandon, ces situations ne sont pas acceptables dans une R\u00e9gion comme la n\u00f4tre qui fait face \u00e0 un boom d\u00e9mographique et qui a besoin de nouvelles r\u00e9ponses. Pour cette raison, j&rsquo;ai tenu \u00e0 mettre en place de nouveaux dispositifs afin de mobiliser ses espaces b\u00e2ties en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/\" \/>\n<meta property=\"og:site_name\" content=\"Christos Doulkeridis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/doulkeridis\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-09T11:50:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T15:47:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2014\/05\/DSC00977-1024x680.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christos Doulkeridis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christos Doulkeridis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/05\\\/09\\\/les-occupations-temporaires-des-experiences-a-partager\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/05\\\/09\\\/les-occupations-temporaires-des-experiences-a-partager\\\/\"},\"author\":{\"name\":\"Christos Doulkeridis\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\"},\"headline\":\"Les occupations temporaires: des exp\u00e9riences \u00e0 partager\",\"datePublished\":\"2014-05-09T11:50:03+00:00\",\"dateModified\":\"2026-04-14T15:47:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/05\\\/09\\\/les-occupations-temporaires-des-experiences-a-partager\\\/\"},\"wordCount\":1484,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/05\\\/09\\\/les-occupations-temporaires-des-experiences-a-partager\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/DSC00977.jpg\",\"keywords\":[\"Logement\",\"occupations temporaires\"],\"articleSection\":[\"Logement\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/05\\\/09\\\/les-occupations-temporaires-des-experiences-a-partager\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/05\\\/09\\\/les-occupations-temporaires-des-experiences-a-partager\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/05\\\/09\\\/les-occupations-temporaires-des-experiences-a-partager\\\/\",\"name\":\"Les occupations temporaires: des exp\u00e9riences \u00e0 partager - Christos Doulkeridis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/05\\\/09\\\/les-occupations-temporaires-des-experiences-a-partager\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/05\\\/09\\\/les-occupations-temporaires-des-experiences-a-partager\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/DSC00977.jpg\",\"datePublished\":\"2014-05-09T11:50:03+00:00\",\"dateModified\":\"2026-04-14T15:47:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/05\\\/09\\\/les-occupations-temporaires-des-experiences-a-partager\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/05\\\/09\\\/les-occupations-temporaires-des-experiences-a-partager\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/05\\\/09\\\/les-occupations-temporaires-des-experiences-a-partager\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/DSC00977.jpg\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/05\\\/DSC00977.jpg\",\"width\":4912,\"height\":3264},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/05\\\/09\\\/les-occupations-temporaires-des-experiences-a-partager\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les occupations temporaires: des exp\u00e9riences \u00e0 partager\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"name\":\"Christos Doulkeridis\",\"description\":\"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\",\"name\":\"Ulyse\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"width\":1024,\"height\":728,\"caption\":\"Ulyse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/doulkeridis\",\"https:\\\/\\\/www.facebook.com\\\/christosdoulkeridis2\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\",\"name\":\"Christos Doulkeridis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"caption\":\"Christos Doulkeridis\"},\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/author\\\/christos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les occupations temporaires: des exp\u00e9riences \u00e0 partager - Christos Doulkeridis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/","og_locale":"fr_FR","og_type":"article","og_title":"Les occupations temporaires: des exp\u00e9riences \u00e0 partager - Christos Doulkeridis","og_description":"Les occupations temporaires font d\u00e9sormais partie des dispositifs en R\u00e9gion Bruxelles-Capitale pour faire face aux d\u00e9fis sociaux que vivent de nombreux bruxellois. La F\u00e9BUL lui consacrait un colloque d&rsquo;une journ\u00e9e \u00e0 destination des acteurs de terrain du secteur de l&rsquo;insertion par le logement, du logement social et des d\u00e9cideurs politiques. Ce colloque m&rsquo;a donn\u00e9 l&rsquo;occasion de rappeler les importantes \u00e9volutions qui ont vu le jour sous cette l\u00e9gislature: lancement d&rsquo;occupations temporaires dans le logement social, inscription des occupations temporaires dans le code du logement, lancement d&rsquo;une agence occupation temporaire r\u00e9gionale. Sous cette l\u00e9gislature, la R\u00e9gion de Bruxelles-Capitale a pris en main de mani\u00e8re particuli\u00e8rement volontaire la question du logement. Les budgets ont \u00e9t\u00e9 renforc\u00e9 de mani\u00e8re significative et les dispositifs existants ont \u00e9t\u00e9 amplifi\u00e9s. Cependant, la R\u00e9gion reste confront\u00e9e \u00e0 une r\u00e9alit\u00e9 choquante: de grandes surfaces b\u00e2ties sont inoccup\u00e9es. Que ce soit des bureaux vides, des \u00e9tages au-dessus des commerces ou des logements \u00e0 l&rsquo;abandon, ces situations ne sont pas acceptables dans une R\u00e9gion comme la n\u00f4tre qui fait face \u00e0 un boom d\u00e9mographique et qui a besoin de nouvelles r\u00e9ponses. Pour cette raison, j&rsquo;ai tenu \u00e0 mettre en place de nouveaux dispositifs afin de mobiliser ses espaces b\u00e2ties en [&hellip;]","og_url":"https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/","og_site_name":"Christos Doulkeridis","article_publisher":"https:\/\/www.facebook.com\/doulkeridis","article_published_time":"2014-05-09T11:50:03+00:00","article_modified_time":"2026-04-14T15:47:08+00:00","og_image":[{"width":1024,"height":680,"url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2014\/05\/DSC00977-1024x680.jpg","type":"image\/jpeg"}],"author":"Christos Doulkeridis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Christos Doulkeridis","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/#article","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/"},"author":{"name":"Christos Doulkeridis","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365"},"headline":"Les occupations temporaires: des exp\u00e9riences \u00e0 partager","datePublished":"2014-05-09T11:50:03+00:00","dateModified":"2026-04-14T15:47:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/"},"wordCount":1484,"commentCount":0,"publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/#primaryimage"},"thumbnailUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2014\/05\/DSC00977.jpg","keywords":["Logement","occupations temporaires"],"articleSection":["Logement"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/","url":"https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/","name":"Les occupations temporaires: des exp\u00e9riences \u00e0 partager - Christos Doulkeridis","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/#primaryimage"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/#primaryimage"},"thumbnailUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2014\/05\/DSC00977.jpg","datePublished":"2014-05-09T11:50:03+00:00","dateModified":"2026-04-14T15:47:08+00:00","breadcrumb":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/#primaryimage","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2014\/05\/DSC00977.jpg","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2014\/05\/DSC00977.jpg","width":4912,"height":3264},{"@type":"BreadcrumbList","@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/05\/09\/les-occupations-temporaires-des-experiences-a-partager\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.doulkeridis.be\/blog\/"},{"@type":"ListItem","position":2,"name":"Les occupations temporaires: des exp\u00e9riences \u00e0 partager"}]},{"@type":"WebSite","@id":"https:\/\/www.doulkeridis.be\/blog\/#website","url":"https:\/\/www.doulkeridis.be\/blog\/","name":"Christos Doulkeridis","description":"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations","publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doulkeridis.be\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.doulkeridis.be\/blog\/#organization","name":"Ulyse","url":"https:\/\/www.doulkeridis.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","width":1024,"height":728,"caption":"Ulyse"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/doulkeridis","https:\/\/www.facebook.com\/christosdoulkeridis2"]},{"@type":"Person","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365","name":"Christos Doulkeridis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","caption":"Christos Doulkeridis"},"url":"https:\/\/www.doulkeridis.be\/blog\/author\/christos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/12007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/comments?post=12007"}],"version-history":[{"count":4,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/12007\/revisions"}],"predecessor-version":[{"id":12012,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/12007\/revisions\/12012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media\/12010"}],"wp:attachment":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media?parent=12007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/categories?post=12007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/tags?post=12007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}