{"id":12192,"date":"2014-07-17T15:35:49","date_gmt":"2014-07-17T14:35:49","guid":{"rendered":"http:\/\/www.doulkeridis.be\/blog\/?p=12192"},"modified":"2014-07-18T08:55:47","modified_gmt":"2014-07-18T07:55:47","slug":"pret-booster","status":"publish","type":"post","link":"https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/","title":{"rendered":"Pr\u00eat Booster"},"content":{"rendered":"<p><a href=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/09\/BOOSTER_LOGO_RGB.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-4372\" alt=\"BOOSTER_LOGO_RGB\" src=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/09\/BOOSTER_LOGO_RGB-300x140.jpg\" width=\"300\" height=\"140\" srcset=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/09\/BOOSTER_LOGO_RGB-300x140.jpg 300w, https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/09\/BOOSTER_LOGO_RGB-1024x480.jpg 1024w, https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/09\/BOOSTER_LOGO_RGB.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Lors de la l\u00e9gislature 2009-2014, j&rsquo;ai mis en place un nouveau dispositif de pr\u00eat du Fonds du Logement destin\u00e9 aux jeunes m\u00e9nages bruxellois d\u00e9sireux de devenir propri\u00e9taire en R\u00e9gion de Bruxelles-Capitale. Le pr\u00eat BOOSTER \u00e9largit les conditions actuelles en mati\u00e8re de revenus maxima, de pr\u00eat maximum et de valeur v\u00e9nale maximale des biens, tenant compte de l\u2019\u00e9volution des prix de l\u2019immobilier \u00e0 Bruxelles. Il instaure des nouveaux taux d\u2019int\u00e9r\u00eat \u00e0 partir de 1,25 % selon le niveau de revenus, l\u2019\u00e2ge et la composition du m\u00e9nage avec une attention particuli\u00e8re pour les moins de 35 ans.<\/p>\n<p><strong>Pour en savoir plus:<\/strong><\/p>\n<p><a href=\"https:\/\/www.doulkeridis.be\/blog\/2013\/12\/05\/aider-les-jeunes-menages-a-acceder-a-la-propriete\/\">https:\/\/www.doulkeridis.be\/blog\/2013\/12\/05\/aider-les-jeunes-menages-a-acceder-a-la-propriete\/<\/a><\/p>\n<p><a href=\"https:\/\/www.doulkeridis.be\/blog\/2011\/09\/14\/le-pret-booster-l\u2019etape-cle-vers-votre-logement\/\">https:\/\/www.doulkeridis.be\/blog\/2011\/09\/14\/le-pret-booster-l%E2%80%99etape-cle-vers-votre-logement\/<\/a><\/p>\n<p><a href=\"https:\/\/www.doulkeridis.be\/blog\/2011\/02\/21\/un-contrat-vert-social-qui-va-notamment-booster-les-moins-de-35ans\/\">https:\/\/www.doulkeridis.be\/blog\/2011\/02\/21\/un-contrat-vert-social-qui-va-notamment-booster-les-moins-de-35ans\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lors de la l\u00e9gislature 2009-2014, j&rsquo;ai mis en place un nouveau dispositif de pr\u00eat du Fonds du Logement destin\u00e9 aux jeunes m\u00e9nages bruxellois d\u00e9sireux de devenir propri\u00e9taire en R\u00e9gion de Bruxelles-Capitale. Le pr\u00eat BOOSTER \u00e9largit les conditions actuelles en mati\u00e8re de revenus maxima, de pr\u00eat maximum et de valeur v\u00e9nale maximale des biens, tenant compte de l\u2019\u00e9volution des prix de l\u2019immobilier \u00e0 Bruxelles. Il instaure des nouveaux taux d\u2019int\u00e9r\u00eat \u00e0 partir de 1,25 % selon le niveau de revenus, l\u2019\u00e2ge et la composition du m\u00e9nage avec une attention particuli\u00e8re pour les moins de 35 ans. Pour en savoir plus: https:\/\/www.doulkeridis.be\/blog\/2013\/12\/05\/aider-les-jeunes-menages-a-acceder-a-la-propriete\/ https:\/\/www.doulkeridis.be\/blog\/2011\/09\/14\/le-pret-booster-l%E2%80%99etape-cle-vers-votre-logement\/ https:\/\/www.doulkeridis.be\/blog\/2011\/02\/21\/un-contrat-vert-social-qui-va-notamment-booster-les-moins-de-35ans\/<\/p>\n","protected":false},"author":2,"featured_media":4372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[1002,1000],"tags":[],"class_list":["post-12192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-en-logement","category-mes-realisations-2009-2014"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr\u00eat Booster - Christos Doulkeridis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00eat Booster - Christos Doulkeridis\" \/>\n<meta property=\"og:description\" content=\"Lors de la l\u00e9gislature 2009-2014, j&rsquo;ai mis en place un nouveau dispositif de pr\u00eat du Fonds du Logement destin\u00e9 aux jeunes m\u00e9nages bruxellois d\u00e9sireux de devenir propri\u00e9taire en R\u00e9gion de Bruxelles-Capitale. Le pr\u00eat BOOSTER \u00e9largit les conditions actuelles en mati\u00e8re de revenus maxima, de pr\u00eat maximum et de valeur v\u00e9nale maximale des biens, tenant compte de l\u2019\u00e9volution des prix de l\u2019immobilier \u00e0 Bruxelles. Il instaure des nouveaux taux d\u2019int\u00e9r\u00eat \u00e0 partir de 1,25 % selon le niveau de revenus, l\u2019\u00e2ge et la composition du m\u00e9nage avec une attention particuli\u00e8re pour les moins de 35 ans. Pour en savoir plus: https:\/\/www.doulkeridis.be\/blog\/2013\/12\/05\/aider-les-jeunes-menages-a-acceder-a-la-propriete\/ https:\/\/www.doulkeridis.be\/blog\/2011\/09\/14\/le-pret-booster-l%E2%80%99etape-cle-vers-votre-logement\/ https:\/\/www.doulkeridis.be\/blog\/2011\/02\/21\/un-contrat-vert-social-qui-va-notamment-booster-les-moins-de-35ans\/\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/\" \/>\n<meta property=\"og:site_name\" content=\"Christos Doulkeridis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/doulkeridis\" \/>\n<meta property=\"article:published_time\" content=\"2014-07-17T14:35:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-07-18T07:55:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/09\/BOOSTER_LOGO_RGB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"601\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christos Doulkeridis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christos Doulkeridis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/07\\\/17\\\/pret-booster\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/07\\\/17\\\/pret-booster\\\/\"},\"author\":{\"name\":\"Christos Doulkeridis\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\"},\"headline\":\"Pr\u00eat Booster\",\"datePublished\":\"2014-07-17T14:35:49+00:00\",\"dateModified\":\"2014-07-18T07:55:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/07\\\/17\\\/pret-booster\\\/\"},\"wordCount\":137,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/07\\\/17\\\/pret-booster\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/09\\\/BOOSTER_LOGO_RGB.jpg\",\"articleSection\":[\"En logement\",\"Mes r\u00e9alisations 2009-2014\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/07\\\/17\\\/pret-booster\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/07\\\/17\\\/pret-booster\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/07\\\/17\\\/pret-booster\\\/\",\"name\":\"Pr\u00eat Booster - Christos Doulkeridis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/07\\\/17\\\/pret-booster\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/07\\\/17\\\/pret-booster\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/09\\\/BOOSTER_LOGO_RGB.jpg\",\"datePublished\":\"2014-07-17T14:35:49+00:00\",\"dateModified\":\"2014-07-18T07:55:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/07\\\/17\\\/pret-booster\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/07\\\/17\\\/pret-booster\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/07\\\/17\\\/pret-booster\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/09\\\/BOOSTER_LOGO_RGB.jpg\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/09\\\/BOOSTER_LOGO_RGB.jpg\",\"width\":\"1280\",\"height\":\"601\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2014\\\/07\\\/17\\\/pret-booster\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr\u00eat Booster\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"name\":\"Christos Doulkeridis\",\"description\":\"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\",\"name\":\"Ulyse\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"width\":1024,\"height\":728,\"caption\":\"Ulyse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/doulkeridis\",\"https:\\\/\\\/www.facebook.com\\\/christosdoulkeridis2\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\",\"name\":\"Christos Doulkeridis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"caption\":\"Christos Doulkeridis\"},\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/author\\\/christos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00eat Booster - Christos Doulkeridis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/","og_locale":"fr_FR","og_type":"article","og_title":"Pr\u00eat Booster - Christos Doulkeridis","og_description":"Lors de la l\u00e9gislature 2009-2014, j&rsquo;ai mis en place un nouveau dispositif de pr\u00eat du Fonds du Logement destin\u00e9 aux jeunes m\u00e9nages bruxellois d\u00e9sireux de devenir propri\u00e9taire en R\u00e9gion de Bruxelles-Capitale. Le pr\u00eat BOOSTER \u00e9largit les conditions actuelles en mati\u00e8re de revenus maxima, de pr\u00eat maximum et de valeur v\u00e9nale maximale des biens, tenant compte de l\u2019\u00e9volution des prix de l\u2019immobilier \u00e0 Bruxelles. Il instaure des nouveaux taux d\u2019int\u00e9r\u00eat \u00e0 partir de 1,25 % selon le niveau de revenus, l\u2019\u00e2ge et la composition du m\u00e9nage avec une attention particuli\u00e8re pour les moins de 35 ans. Pour en savoir plus: https:\/\/www.doulkeridis.be\/blog\/2013\/12\/05\/aider-les-jeunes-menages-a-acceder-a-la-propriete\/ https:\/\/www.doulkeridis.be\/blog\/2011\/09\/14\/le-pret-booster-l%E2%80%99etape-cle-vers-votre-logement\/ https:\/\/www.doulkeridis.be\/blog\/2011\/02\/21\/un-contrat-vert-social-qui-va-notamment-booster-les-moins-de-35ans\/","og_url":"https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/","og_site_name":"Christos Doulkeridis","article_publisher":"https:\/\/www.facebook.com\/doulkeridis","article_published_time":"2014-07-17T14:35:49+00:00","article_modified_time":"2014-07-18T07:55:47+00:00","og_image":[{"width":1280,"height":601,"url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/09\/BOOSTER_LOGO_RGB.jpg","type":"image\/jpeg"}],"author":"Christos Doulkeridis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Christos Doulkeridis","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/#article","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/"},"author":{"name":"Christos Doulkeridis","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365"},"headline":"Pr\u00eat Booster","datePublished":"2014-07-17T14:35:49+00:00","dateModified":"2014-07-18T07:55:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/"},"wordCount":137,"commentCount":0,"publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/#primaryimage"},"thumbnailUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/09\/BOOSTER_LOGO_RGB.jpg","articleSection":["En logement","Mes r\u00e9alisations 2009-2014"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/","url":"https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/","name":"Pr\u00eat Booster - Christos Doulkeridis","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/#primaryimage"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/#primaryimage"},"thumbnailUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/09\/BOOSTER_LOGO_RGB.jpg","datePublished":"2014-07-17T14:35:49+00:00","dateModified":"2014-07-18T07:55:47+00:00","breadcrumb":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/#primaryimage","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/09\/BOOSTER_LOGO_RGB.jpg","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/09\/BOOSTER_LOGO_RGB.jpg","width":"1280","height":"601"},{"@type":"BreadcrumbList","@id":"https:\/\/www.doulkeridis.be\/blog\/2014\/07\/17\/pret-booster\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.doulkeridis.be\/blog\/"},{"@type":"ListItem","position":2,"name":"Pr\u00eat Booster"}]},{"@type":"WebSite","@id":"https:\/\/www.doulkeridis.be\/blog\/#website","url":"https:\/\/www.doulkeridis.be\/blog\/","name":"Christos Doulkeridis","description":"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations","publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doulkeridis.be\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.doulkeridis.be\/blog\/#organization","name":"Ulyse","url":"https:\/\/www.doulkeridis.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","width":1024,"height":728,"caption":"Ulyse"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/doulkeridis","https:\/\/www.facebook.com\/christosdoulkeridis2"]},{"@type":"Person","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365","name":"Christos Doulkeridis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","caption":"Christos Doulkeridis"},"url":"https:\/\/www.doulkeridis.be\/blog\/author\/christos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/12192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/comments?post=12192"}],"version-history":[{"count":4,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/12192\/revisions"}],"predecessor-version":[{"id":12237,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/12192\/revisions\/12237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media\/4372"}],"wp:attachment":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media?parent=12192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/categories?post=12192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/tags?post=12192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}