{"id":12378,"date":"2015-10-09T12:24:55","date_gmt":"2015-10-09T11:24:55","guid":{"rendered":"http:\/\/www.doulkeridis.be\/blog\/?p=12378"},"modified":"2015-10-09T12:24:55","modified_gmt":"2015-10-09T11:24:55","slug":"alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas","status":"publish","type":"post","link":"https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/","title":{"rendered":"Alerte : L\u2019Ambassadeur grec Melinos Merkouris n\u2019existe (malheureusement) pas !"},"content":{"rendered":"<p><a href=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2015\/10\/Melina_Mercouri.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-12379\" src=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2015\/10\/Melina_Mercouri-290x290.jpg\" alt=\"Melina_Mercouri\" width=\"290\" height=\"290\" srcset=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2015\/10\/Melina_Mercouri-290x290.jpg 290w, https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2015\/10\/Melina_Mercouri-50x50.jpg 50w\" sizes=\"auto, (max-width: 290px) 100vw, 290px\" \/><\/a>Il y a une semaine, je publiais sur mon blog un article intitul\u00e9 \u00ab\u00a0<em>L\u2019ambassadeur grec demande \u00e0 la\u00a0Belgique d&rsquo;augmenter ses budgets consacr\u00e9s\u00a0\u00e0 la culture<\/em>\u00a0\u00bb. Cet article paraissait le lendemain de la sortie\u00a0(malheureusement) bien r\u00e9elle\u00a0de l\u2019Ambassadrice des Etats-Unis qui demandait \u00e0 la Belgique d\u2019investir plus dans ses d\u00e9penses militaires.<\/p>\n<p>Faisant\u00a0r\u00e9f\u00e9rence \u00e0 une prise de position de l\u2019Ambassadeur grec \u00ab\u00a0Melinos Merkouris\u00a0\u00bb, il\u00a0disait en substance que la Gr\u00e8ce \u00e9tait le meilleur \u00e9l\u00e8ve de la classe europ\u00e9enne en PIB consacr\u00e9 \u00e0 l\u2019arm\u00e9e (plus de 2%), que cela n\u2019avait en aucun cas servi la s\u00e9curit\u00e9, l\u2019\u00e9conomie ou la diplomatie de son pays,\u00a0et\u00a0que le meilleur antidote \u00e0 la violence et \u00e0 la haine \u00e9tait l\u2019investissement dans la culture.<\/p>\n<p>En une semaine, l\u2019article en question\u00a0a \u00e9t\u00e9 partag\u00e9 pr\u00e8s de 1200 fois\u00a0\u00e0 partir de mon blog.\u00a0Si l\u2019on excepte mes recettes de cuisine,\u00a0la plupart de mes articles plafonnent \u00e0 200.\u00a0Celui-ci\u00a0a \u00e9t\u00e9 \u00ab\u00a0lik\u00e9\u00a0\u00bb tr\u00e8s largement sur Facebook et Twitter. Des associations m\u2019ont demand\u00e9 de pouvoir\u00a0le\u00a0publier dans leur lettre d\u2019information, des journalistes l\u2019ont repris dans\u00a0leurs\u00a0m\u00e9dias virtuels et finalement l\u2019Ambassade de Gr\u00e8ce m\u2019a appel\u00e9 pour me signaler qu\u2019il y avait \u00ab\u00a0quelques erreurs\u00a0\u00bb dans le texte. <strong>Et pour cause, l\u2019Ambassadeur Melinos Merkouris n\u2019existe (malheureusement) pas<\/strong>.<\/p>\n<p>J\u2019ai \u00e9crit ce texte de A \u00e0 Omega sous forme de d\u00e9rision\u00a0en r\u00e9f\u00e9rence\u00a0\u00e0 la sortie de l\u2019Ambassadrice des Etats-Unis. Il me paraissait bien \u00e9vident qu\u2019aucun autre ambassadeur que celui des Etats-Unis ne se permettrait de faire la le\u00e7on de la sorte \u00e0 un autre pays d\u00e9mocratique. La r\u00e9f\u00e9rence \u00e0 la tr\u00e8s appr\u00e9ci\u00e9e Melina Mercouri, Ministre\u00a0grecque\u00a0de la Culture\u00a0\u00e0 deux reprises\u00a0entre 1981 et 1994 \u00e9tait un clin d\u2019oeil \u00e0 une femme qui pla\u00e7a la culture \u00e0 l\u2019honneur dans son pays.<\/p>\n<p>J\u2019ai \u00e9crit ce texte parce que j\u2019aurais voulu le lire de la\u00a0plume\u00a0d\u2019une autorit\u00e9 plus officielle que moi. Il y a des silences de plus en plus insupportables. J\u2019aurais aussi aim\u00e9 lire par exemple d&rsquo;un-e chef-fe d\u2019une grande entreprise industrielle\u00a0des mots\u00a0appelant ses homologues \u00e0 moins d\u2019arrogance\u00a0:\u00a0\u00ab\u00a0<em>Quand on touche une r\u00e9mun\u00e9ration d\u2019au moins 645.000 euros, comme le PDG d\u2019Air-France-KLM en 2014, on a au minimum la d\u00e9cence de ne pas tenir des propos aussi m\u00e9prisants et ridicules envers ses employ\u00e9s<\/em>\u00a0!\u00a0\u00bb ou encore \u00ab\u00a0<em>Comment peut-on revendiquer avec autant de suffisance d\u2019augmenter sans cesse la productivit\u00e9 des travailleurs de nos entreprises en sous-entendant qu\u2019ils co\u00fbtent trop cher par rapport \u00e0 ce qu\u2019ils produisent quand on permet \u00e0 un PDG de partir avec un bonus de plus de 60 millions d\u2019euros apr\u00e8s avoir reconnu une faute gravissime\u00a0qui, outre le co\u00fbt sanitaire de ce scandale,\u00a0co\u00fbtera plusieurs milliards.\u00a0<\/em>\u00bb.<\/p>\n<p>Mis \u00e0 part la r\u00e9f\u00e9rence de l\u2019auteur de ces d\u00e9clarations,\u00a0ce texte\u00a0garde \u00e0 mon sens\u00a0toute\u00a0sa pertinence dans le d\u00e9bat. Je suis au moins heureux que ces arguments et ces plaidoyers aient \u00e9t\u00e9 autant lus et partag\u00e9s.<\/p>\n<p>Ci-dessous, le texte que j&rsquo;avais publi\u00e9 :<\/p>\n<blockquote><p>\u00ab\u00a0C\u2019est une intervention qui a \u00e9chapp\u00e9 \u00e0 la plupart des observateurs, mais au lendemain des d\u00e9clarations de l\u2019Ambassadrice des Etats-Unis qui encourageait la Belgique \u00e0 investir davantage dans son arm\u00e9e, Monsieur Melinos Merkouris, Ambassadeur de Gr\u00e8ce aupr\u00e8s de la Belgique et de l\u2019Union europ\u00e9enne \u00e9tait invit\u00e9 \u00e0 Bruxelles \u00e0 une conf\u00e9rence consacr\u00e9e \u00e0 l\u2019utilisation la plus rationnelle des moyens publics pour construire la paix, la prosp\u00e9rit\u00e9 et le bien-\u00eatre en Europe. Lors d\u2019une intervention attendue compte tenu du contexte \u00e9conomique dans lequel se trouve son pays et du fait que la Gr\u00e8ce est l\u2019un des pays europ\u00e9ens qui consacre la plus grande part de son PIB \u00e0 son arm\u00e9e, l\u2019Ambassadeur a surpris son auditoire. Alors que dans les couloirs chacun s\u2019attendait \u00e0 ce que le repr\u00e9sentant grec en profite pour re-l\u00e9gitimer les budgets affect\u00e9s par son gouvernement dans l\u2019arm\u00e9e apr\u00e8s les critiques acerbes re\u00e7ues ces derni\u00e8res ann\u00e9es par les autorit\u00e9s europ\u00e9ennes, Monsieur Merkouris a pris l\u2019assembl\u00e9e \u00e0 contre-pied.<\/p>\n<p>\u00ab\u00a0<i>Mon pays est sans doute le meilleur \u00e9l\u00e8ve de la classe europ\u00e9enne sur le plan des investissements publics d\u00e9di\u00e9s \u00e0 sa s\u00e9curit\u00e9 militaire. Nous avons consacr\u00e9 de mani\u00e8re annuelle plus de 2 % de notre PIB (2,4% en 2015) \u00e0 acheter des armes, des chars, des avions, des navires militaires. Tout \u00e7a pour quoi ? Regardez dans quel \u00e9tat se trouve aujourd\u2019hui notre pays. A-t-il pour autant \u00e9t\u00e9 r\u00e9compens\u00e9 par ces pays \u00e0 qui il a achet\u00e9 ces armes ? B\u00e9n\u00e9ficie-t-il d\u2019une s\u00e9curit\u00e9 plus importante ? Son \u00e9conomie se porte-t-elle mieux ? Comme je suis diplomate, je me contenterai de dire poliment que je pense que non. Regardez les discours de haine, les replis frileux, le racisme banalis\u00e9 soutenus non seulement par des citoyens europ\u00e9ens mais aussi par des responsables politiques au plus haut niveau.\u00a0<\/i><\/p>\n<p><i>Ce dont nous avons le plus besoin aujourd\u2019hui c\u2019est d\u2019investir davantage dans la Culture. Cet antidote \u00e0 la violence qui nous invite \u00e0 la compr\u00e9hension d\u2019autrui et f\u00e9conde la tol\u00e9rance, en nous incitant \u00e0 partir \u00e0 la rencontre d\u2019autres imaginaires et d\u2019autres cultures. Ce dont nous avons le plus besoin aujourd\u2019hui c\u2019est de stimuler notre cr\u00e9ativit\u00e9, notre humour, nos doutes, nos remises en question, nos enthousiasmes, nos recherches de sens. C\u2019est l\u00e0 qu\u2019excelle la culture. Jamais aucun char, aucun avion de chasse, aucune arme n\u2019est parvenue \u00e0 le faire.\u00a0<\/i><\/p>\n<p><i>A l\u2019heure o\u00f9 certains demandent \u00e0 la Belgique d\u2019investir davantage dans son arm\u00e9e, je constate que ce m\u00eame pays diminue \u00e0 tous les niveaux de pouvoir les budgets consacr\u00e9s \u00e0 la culture. Ses th\u00e9\u00e2tres, ses artistes, ses biblioth\u00e8ques, ses centres de cr\u00e9ativit\u00e9, ses centres culturels doivent travailler avec des moyens r\u00e9duits en cascade par chaque acteur public. Et pourtant, il n\u2019y a pas un seul jour qui \u00e9chappe \u00e0 une nouvelle alerte sur le plan des valeurs du vivre ensemble.\u00a0<\/i><\/p>\n<p><i>Je suis conscient que mon pays n\u2019a sans doute pas la l\u00e9gitimit\u00e9 pour se placer dans le r\u00f4le du donneur de le\u00e7on. Je ne sais d\u2019ailleurs pas si un seul pays au monde n\u2019a suffisamment de l\u00e9gitimit\u00e9 pour le faire. Mais si vous me demandiez sur base de notre exp\u00e9rience de ces derni\u00e8res ann\u00e9es de crise, des ann\u00e9es d\u2019opulence\u00a0obsc\u00e8ne\u00a0qui les ont pr\u00e9c\u00e9d\u00e9es, de celles o\u00f9 nous avons connu la dictature, la guerre, la pauvret\u00e9, l\u2019exil, l\u2019occupation, la conqu\u00eate, bref sur base de notre histoire bimill\u00e9naire, je vous dirais qu\u2019il y a un investissement qui est le plus s\u00fbr et le plus rentable, c\u2019est celui qui est consacr\u00e9 \u00e0 la culture.<\/i>\u00a0\u00bb<\/p><\/blockquote>\n<p><b>Bruxelles \/ 1-10-2015 \/ ChD<\/b><\/p>\n<p>&#8211; See more at: https:\/\/www.doulkeridis.be\/blog\/2015\/10\/02\/lambassadeur-de-grece-demande-a-la-belgique-daugmenter-ses-budgets-consacres-a-la-culture\/#sthash.7wdtqNqT.dpuf<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a une semaine, je publiais sur mon blog un article intitul\u00e9 \u00ab\u00a0L\u2019ambassadeur grec demande \u00e0 la\u00a0Belgique d&rsquo;augmenter ses budgets consacr\u00e9s\u00a0\u00e0 la culture\u00a0\u00bb. Cet article paraissait le lendemain de la sortie\u00a0(malheureusement) bien r\u00e9elle\u00a0de l\u2019Ambassadrice des Etats-Unis qui demandait \u00e0 la Belgique d\u2019investir plus dans ses d\u00e9penses militaires. Faisant\u00a0r\u00e9f\u00e9rence \u00e0 une prise de position de l\u2019Ambassadeur grec \u00ab\u00a0Melinos Merkouris\u00a0\u00bb, il\u00a0disait en substance que la Gr\u00e8ce \u00e9tait le meilleur \u00e9l\u00e8ve de la classe europ\u00e9enne en PIB consacr\u00e9 \u00e0 l\u2019arm\u00e9e (plus de 2%), que cela n\u2019avait en aucun cas servi la s\u00e9curit\u00e9, l\u2019\u00e9conomie ou la diplomatie de son pays,\u00a0et\u00a0que le meilleur antidote \u00e0 la violence et \u00e0 la haine \u00e9tait l\u2019investissement dans la culture. En une semaine, l\u2019article en question\u00a0a \u00e9t\u00e9 partag\u00e9 pr\u00e8s de 1200 fois\u00a0\u00e0 partir de mon blog.\u00a0Si l\u2019on excepte mes recettes de cuisine,\u00a0la plupart de mes articles plafonnent \u00e0 200.\u00a0Celui-ci\u00a0a \u00e9t\u00e9 \u00ab\u00a0lik\u00e9\u00a0\u00bb tr\u00e8s largement sur Facebook et Twitter. Des associations m\u2019ont demand\u00e9 de pouvoir\u00a0le\u00a0publier dans leur lettre d\u2019information, des journalistes l\u2019ont repris dans\u00a0leurs\u00a0m\u00e9dias virtuels et finalement l\u2019Ambassade de Gr\u00e8ce m\u2019a appel\u00e9 pour me signaler qu\u2019il y avait \u00ab\u00a0quelques erreurs\u00a0\u00bb dans le texte. Et pour cause, l\u2019Ambassadeur Melinos Merkouris n\u2019existe (malheureusement) pas. J\u2019ai \u00e9crit ce texte de A \u00e0 Omega [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12379,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[169,83],"tags":[],"class_list":["post-12378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-citoyennete","category-culture"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alerte : L\u2019Ambassadeur grec Melinos Merkouris n\u2019existe (malheureusement) pas ! - Christos Doulkeridis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alerte : L\u2019Ambassadeur grec Melinos Merkouris n\u2019existe (malheureusement) pas ! - Christos Doulkeridis\" \/>\n<meta property=\"og:description\" content=\"Il y a une semaine, je publiais sur mon blog un article intitul\u00e9 \u00ab\u00a0L\u2019ambassadeur grec demande \u00e0 la\u00a0Belgique d&rsquo;augmenter ses budgets consacr\u00e9s\u00a0\u00e0 la culture\u00a0\u00bb. Cet article paraissait le lendemain de la sortie\u00a0(malheureusement) bien r\u00e9elle\u00a0de l\u2019Ambassadrice des Etats-Unis qui demandait \u00e0 la Belgique d\u2019investir plus dans ses d\u00e9penses militaires. Faisant\u00a0r\u00e9f\u00e9rence \u00e0 une prise de position de l\u2019Ambassadeur grec \u00ab\u00a0Melinos Merkouris\u00a0\u00bb, il\u00a0disait en substance que la Gr\u00e8ce \u00e9tait le meilleur \u00e9l\u00e8ve de la classe europ\u00e9enne en PIB consacr\u00e9 \u00e0 l\u2019arm\u00e9e (plus de 2%), que cela n\u2019avait en aucun cas servi la s\u00e9curit\u00e9, l\u2019\u00e9conomie ou la diplomatie de son pays,\u00a0et\u00a0que le meilleur antidote \u00e0 la violence et \u00e0 la haine \u00e9tait l\u2019investissement dans la culture. En une semaine, l\u2019article en question\u00a0a \u00e9t\u00e9 partag\u00e9 pr\u00e8s de 1200 fois\u00a0\u00e0 partir de mon blog.\u00a0Si l\u2019on excepte mes recettes de cuisine,\u00a0la plupart de mes articles plafonnent \u00e0 200.\u00a0Celui-ci\u00a0a \u00e9t\u00e9 \u00ab\u00a0lik\u00e9\u00a0\u00bb tr\u00e8s largement sur Facebook et Twitter. Des associations m\u2019ont demand\u00e9 de pouvoir\u00a0le\u00a0publier dans leur lettre d\u2019information, des journalistes l\u2019ont repris dans\u00a0leurs\u00a0m\u00e9dias virtuels et finalement l\u2019Ambassade de Gr\u00e8ce m\u2019a appel\u00e9 pour me signaler qu\u2019il y avait \u00ab\u00a0quelques erreurs\u00a0\u00bb dans le texte. Et pour cause, l\u2019Ambassadeur Melinos Merkouris n\u2019existe (malheureusement) pas. J\u2019ai \u00e9crit ce texte de A \u00e0 Omega [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/\" \/>\n<meta property=\"og:site_name\" content=\"Christos Doulkeridis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/doulkeridis\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-09T11:24:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2015\/10\/Melina_Mercouri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"835\" \/>\n\t<meta property=\"og:image:height\" content=\"1091\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christos Doulkeridis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christos Doulkeridis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2015\\\/10\\\/09\\\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2015\\\/10\\\/09\\\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\\\/\"},\"author\":{\"name\":\"Christos Doulkeridis\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\"},\"headline\":\"Alerte : L\u2019Ambassadeur grec Melinos Merkouris n\u2019existe (malheureusement) pas !\",\"datePublished\":\"2015-10-09T11:24:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2015\\\/10\\\/09\\\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\\\/\"},\"wordCount\":1202,\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2015\\\/10\\\/09\\\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Melina_Mercouri.jpg\",\"articleSection\":[\"Citoyennet\u00e9\",\"Culture\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2015\\\/10\\\/09\\\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2015\\\/10\\\/09\\\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\\\/\",\"name\":\"Alerte : L\u2019Ambassadeur grec Melinos Merkouris n\u2019existe (malheureusement) pas ! - Christos Doulkeridis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2015\\\/10\\\/09\\\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2015\\\/10\\\/09\\\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Melina_Mercouri.jpg\",\"datePublished\":\"2015-10-09T11:24:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2015\\\/10\\\/09\\\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2015\\\/10\\\/09\\\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2015\\\/10\\\/09\\\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Melina_Mercouri.jpg\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/Melina_Mercouri.jpg\",\"width\":835,\"height\":1091},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2015\\\/10\\\/09\\\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alerte : L\u2019Ambassadeur grec Melinos Merkouris n\u2019existe (malheureusement) pas !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"name\":\"Christos Doulkeridis\",\"description\":\"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\",\"name\":\"Ulyse\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"width\":1024,\"height\":728,\"caption\":\"Ulyse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/doulkeridis\",\"https:\\\/\\\/www.facebook.com\\\/christosdoulkeridis2\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\",\"name\":\"Christos Doulkeridis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"caption\":\"Christos Doulkeridis\"},\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/author\\\/christos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alerte : L\u2019Ambassadeur grec Melinos Merkouris n\u2019existe (malheureusement) pas ! - Christos Doulkeridis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/","og_locale":"fr_FR","og_type":"article","og_title":"Alerte : L\u2019Ambassadeur grec Melinos Merkouris n\u2019existe (malheureusement) pas ! - Christos Doulkeridis","og_description":"Il y a une semaine, je publiais sur mon blog un article intitul\u00e9 \u00ab\u00a0L\u2019ambassadeur grec demande \u00e0 la\u00a0Belgique d&rsquo;augmenter ses budgets consacr\u00e9s\u00a0\u00e0 la culture\u00a0\u00bb. Cet article paraissait le lendemain de la sortie\u00a0(malheureusement) bien r\u00e9elle\u00a0de l\u2019Ambassadrice des Etats-Unis qui demandait \u00e0 la Belgique d\u2019investir plus dans ses d\u00e9penses militaires. Faisant\u00a0r\u00e9f\u00e9rence \u00e0 une prise de position de l\u2019Ambassadeur grec \u00ab\u00a0Melinos Merkouris\u00a0\u00bb, il\u00a0disait en substance que la Gr\u00e8ce \u00e9tait le meilleur \u00e9l\u00e8ve de la classe europ\u00e9enne en PIB consacr\u00e9 \u00e0 l\u2019arm\u00e9e (plus de 2%), que cela n\u2019avait en aucun cas servi la s\u00e9curit\u00e9, l\u2019\u00e9conomie ou la diplomatie de son pays,\u00a0et\u00a0que le meilleur antidote \u00e0 la violence et \u00e0 la haine \u00e9tait l\u2019investissement dans la culture. En une semaine, l\u2019article en question\u00a0a \u00e9t\u00e9 partag\u00e9 pr\u00e8s de 1200 fois\u00a0\u00e0 partir de mon blog.\u00a0Si l\u2019on excepte mes recettes de cuisine,\u00a0la plupart de mes articles plafonnent \u00e0 200.\u00a0Celui-ci\u00a0a \u00e9t\u00e9 \u00ab\u00a0lik\u00e9\u00a0\u00bb tr\u00e8s largement sur Facebook et Twitter. Des associations m\u2019ont demand\u00e9 de pouvoir\u00a0le\u00a0publier dans leur lettre d\u2019information, des journalistes l\u2019ont repris dans\u00a0leurs\u00a0m\u00e9dias virtuels et finalement l\u2019Ambassade de Gr\u00e8ce m\u2019a appel\u00e9 pour me signaler qu\u2019il y avait \u00ab\u00a0quelques erreurs\u00a0\u00bb dans le texte. Et pour cause, l\u2019Ambassadeur Melinos Merkouris n\u2019existe (malheureusement) pas. J\u2019ai \u00e9crit ce texte de A \u00e0 Omega [&hellip;]","og_url":"https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/","og_site_name":"Christos Doulkeridis","article_publisher":"https:\/\/www.facebook.com\/doulkeridis","article_published_time":"2015-10-09T11:24:55+00:00","og_image":[{"width":835,"height":1091,"url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2015\/10\/Melina_Mercouri.jpg","type":"image\/jpeg"}],"author":"Christos Doulkeridis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Christos Doulkeridis","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/#article","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/"},"author":{"name":"Christos Doulkeridis","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365"},"headline":"Alerte : L\u2019Ambassadeur grec Melinos Merkouris n\u2019existe (malheureusement) pas !","datePublished":"2015-10-09T11:24:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/"},"wordCount":1202,"publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2015\/10\/Melina_Mercouri.jpg","articleSection":["Citoyennet\u00e9","Culture"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/","url":"https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/","name":"Alerte : L\u2019Ambassadeur grec Melinos Merkouris n\u2019existe (malheureusement) pas ! - Christos Doulkeridis","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/#primaryimage"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2015\/10\/Melina_Mercouri.jpg","datePublished":"2015-10-09T11:24:55+00:00","breadcrumb":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/#primaryimage","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2015\/10\/Melina_Mercouri.jpg","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2015\/10\/Melina_Mercouri.jpg","width":835,"height":1091},{"@type":"BreadcrumbList","@id":"https:\/\/www.doulkeridis.be\/blog\/2015\/10\/09\/alerte-lambassadeur-grec-melinos-merkouris-nexiste-malheureusement-pas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.doulkeridis.be\/blog\/"},{"@type":"ListItem","position":2,"name":"Alerte : L\u2019Ambassadeur grec Melinos Merkouris n\u2019existe (malheureusement) pas !"}]},{"@type":"WebSite","@id":"https:\/\/www.doulkeridis.be\/blog\/#website","url":"https:\/\/www.doulkeridis.be\/blog\/","name":"Christos Doulkeridis","description":"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations","publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doulkeridis.be\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.doulkeridis.be\/blog\/#organization","name":"Ulyse","url":"https:\/\/www.doulkeridis.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","width":1024,"height":728,"caption":"Ulyse"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/doulkeridis","https:\/\/www.facebook.com\/christosdoulkeridis2"]},{"@type":"Person","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365","name":"Christos Doulkeridis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","caption":"Christos Doulkeridis"},"url":"https:\/\/www.doulkeridis.be\/blog\/author\/christos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/12378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/comments?post=12378"}],"version-history":[{"count":3,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/12378\/revisions"}],"predecessor-version":[{"id":12382,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/12378\/revisions\/12382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media\/12379"}],"wp:attachment":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media?parent=12378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/categories?post=12378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/tags?post=12378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}