{"id":12611,"date":"2017-02-15T16:06:18","date_gmt":"2017-02-15T15:06:18","guid":{"rendered":"http:\/\/www.doulkeridis.be\/blog\/?p=12611"},"modified":"2017-02-15T16:06:18","modified_gmt":"2017-02-15T15:06:18","slug":"statut-des-artistes-greoli-renvoie-la-balle-au-federal","status":"publish","type":"post","link":"https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/","title":{"rendered":"Statut des artistes : Greoli renvoie la balle au f\u00e9d\u00e9ral"},"content":{"rendered":"<p><strong><em><a href=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2017\/02\/statutartiste.jpg\" rel=\"attachment wp-att-12619\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-12619\" src=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2017\/02\/statutartiste-300x200.jpg\" alt=\"statut artiste\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2017\/02\/statutartiste-300x200.jpg 300w, https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2017\/02\/statutartiste.jpg 475w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Voici l&rsquo;\u00e9change que j\u2019ai eu avec Alda Greoli, Ministre de la Culture autour de ses initiatives sur le statut des artistes et de sa position commune avec Sven Gatz, Ministre flamand de la Culture : la Ministre nous renvoie au travail de fond r\u00e9alis\u00e9 par le groupe \u00ab\u00a0Statut et Emploi\u00a0\u00bb de l&rsquo;op\u00e9ration \u00ab\u00a0Bouger les lignes\u00a0\u00bb. Par ailleurs, les comit\u00e9s de suivi op\u00e9rationnel sont actuellement en train d&rsquo;examiner les propositions de ce groupe. Quant \u00e0 une position commune sur le statut des artistes des cabinets Greoli et Gatz, c&rsquo;est en cours de concertation. En bref, rien de neuf sous le soleil \u00e0 part qu&rsquo;on renvoie tout au f\u00e9d\u00e9ral. Affaires \u00e0 suivre donc&#8230;<br \/>\n<\/em><\/strong><\/p>\n<p><span style=\"font-family: Liberation Serif,serif;\"><span style=\"font-size: small;\"><u>Ma question<\/u>\u00a0:<\/span><\/span><\/p>\n<p><span style=\"font-family: Liberation Serif,serif;\"><span style=\"font-size: small;\">Madame la Ministre, vous avez particip\u00e9 derni\u00e8rement \u00e0 la traditionnelle r\u00e9ception organis\u00e9e le R\u00e9seau des Arts \u00e0 Bruxelles (RAB), son pendant flamand, le Brussels Kunstenoverleg (BKO), le Conseil bruxellois des mus\u00e9es, la Concertation des centres culturels bruxellois et Cultuurcentrum Brussel. Vous y \u00e9tiez invit\u00e9e,ainsi que vos homologues, \u00e0 pr\u00e9senter vos priorit\u00e9s pour l\u2019ann\u00e9e 2017. <\/span><\/span><\/p>\n<p><span style=\"font-family: Liberation Serif,serif;\"><span style=\"font-size: small;\">Lors de la partie de la conf\u00e9rence \u00e0 laquelle j\u2019ai pu assister, vous avez rappel\u00e9, avec le ministre Gatz, votre objectif de faire avancer le dossier du statut des artistes. Pouvez-vous faire le point sur ce dossier? Quelles sont les derni\u00e8res initiatives que vous avez prises? Avez-vous d\u00e9fini une position commune sur le fond avec votre M. Gatz? Si oui, quelle est cette position et quelles sont vos revendications? Mis \u00e0 part l\u2019intention de renvoyer ensemble la balle au niveau f\u00e9d\u00e9ral, avez-vous pris, \u00e0 votre niveau, d\u2019autres avanc\u00e9es relatives au statut des artistes? Il est important de r\u00e9fl\u00e9chir aux actions que nous pouvons prendre \u00e0 notre niveau avant de renvoyer ce dossier \u00e0 d\u2019autres.<\/span><\/span><\/p>\n<p><span style=\"font-family: Liberation Serif,serif;\"><span style=\"font-size: small;\"><u>R\u00e9ponse d&rsquo;Alda GREOLI, vice-pr\u00e9sidente et ministre de la Culture et de l&rsquo;Enfance<\/u>\u00a0:<\/span><\/span><\/p>\n<p><span style=\"font-family: Liberation Serif,serif;\"><span style=\"font-size: small;\">Monsieur, vous m\u2019interrogez sur les suites qui seront donn\u00e9es au travail men\u00e9 avec le secteur culturel et avec M. Gatz sur le statut des artistes. Vous d\u00e9sirez \u00e9galement savoir s\u2019il existe d\u00e9j\u00e0 des groupes de travail. Le travail de fond que vous \u00e9voquez a, justement, \u00e9t\u00e9 r\u00e9alis\u00e9 par un groupe de travail, le groupe \u00ab\u00a0statut et emploi\u00a0\u00bb de la coupole \u00ab\u00a0artistes au centre\u00a0\u00bb de l\u2019op\u00e9ration\u00a0\u00ab\u00a0bouger les lignes\u00a0\u00bb. Vous trouverez ses recommandations dans la synth\u00e8se, t\u00e9l\u00e9chargeable et dans l\u2019\u00e9tat des lieux dress\u00e9, en parall\u00e8le, par le guichet des arts. Le contenu de ces documents ayant d\u00e9j\u00e0 \u00e9t\u00e9 abord\u00e9 en commission, je n\u2019y reviendrai pas.<\/span><\/span><\/p>\n<p><span style=\"font-family: Liberation Serif,serif;\"><span style=\"font-size: small;\"> Les comit\u00e9s de suivi op\u00e9rationnel qui examinent les propositions des groupes de travail sont aujourd\u2019hui \u00e0 l\u2019\u0153uvre. Leurs propositions me parviendront vers la fin f\u00e9vrier. Nous aurons donc l\u2019occasion de revenir en temps opportun sur l\u2019ensemble des mesures envisag\u00e9es, en ce compris sur les mesures propos\u00e9es dans le cadre d\u2019une r\u00e9forme du statut de l\u2019artiste pour notre niveau de pouvoir. Pas moins de 804 recommandations sont relatives au statut !<\/span><\/span><\/p>\n<p><span style=\"font-family: Liberation Serif,serif;\"><span style=\"font-size: small;\">Du c\u00f4t\u00e9 n\u00e9erlandophone, une \u00e9tude men\u00e9e par le Kunstenloket vient d\u2019\u00eatre publi\u00e9e sur les positions socio-\u00e9conomiques des artistes. C\u2019est dans le cadre du lien entre cette \u00e9tude et \u00ab\u00a0Bouger les lignes\u00a0\u00bb que mon cabinet est en contact avec celui du ministre Gatz pour tenir compte de cette r\u00e9flexion \u00e0 laquelle sont associ\u00e9es nos administrations. Je leur laisse un peu de temps pour me donner le r\u00e9sultat de leur travail. <\/span><\/span><\/p>\n<p><span style=\"font-family: Liberation Serif,serif;\"><span style=\"font-size: small;\"><u>Ma r\u00e9plique<\/u>\u00a0:<\/span><\/span><\/p>\n<p><span style=\"font-family: Liberation Serif,serif;\"><span style=\"font-size: small;\">Je vais examiner les documents que vous avez mentionn\u00e9s ainsi que l\u2019\u00e9tude n\u00e9erlandophone. J\u2019ai not\u00e9 que les conclusions francophones seront d\u00e9pos\u00e9es fin f\u00e9vrier.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voici l&rsquo;\u00e9change que j\u2019ai eu avec Alda Greoli, Ministre de la Culture autour de ses initiatives sur le statut des artistes et de sa position commune avec Sven Gatz, Ministre flamand de la Culture : la Ministre nous renvoie au travail de fond r\u00e9alis\u00e9 par le groupe \u00ab\u00a0Statut et Emploi\u00a0\u00bb de l&rsquo;op\u00e9ration \u00ab\u00a0Bouger les lignes\u00a0\u00bb. Par ailleurs, les comit\u00e9s de suivi op\u00e9rationnel sont actuellement en train d&rsquo;examiner les propositions de ce groupe. Quant \u00e0 une position commune sur le statut des artistes des cabinets Greoli et Gatz, c&rsquo;est en cours de concertation. En bref, rien de neuf sous le soleil \u00e0 part qu&rsquo;on renvoie tout au f\u00e9d\u00e9ral. Affaires \u00e0 suivre donc&#8230; Ma question\u00a0: Madame la Ministre, vous avez particip\u00e9 derni\u00e8rement \u00e0 la traditionnelle r\u00e9ception organis\u00e9e le R\u00e9seau des Arts \u00e0 Bruxelles (RAB), son pendant flamand, le Brussels Kunstenoverleg (BKO), le Conseil bruxellois des mus\u00e9es, la Concertation des centres culturels bruxellois et Cultuurcentrum Brussel. Vous y \u00e9tiez invit\u00e9e,ainsi que vos homologues, \u00e0 pr\u00e9senter vos priorit\u00e9s pour l\u2019ann\u00e9e 2017. Lors de la partie de la conf\u00e9rence \u00e0 laquelle j\u2019ai pu assister, vous avez rappel\u00e9, avec le ministre Gatz, votre objectif de faire avancer le dossier du statut des artistes. Pouvez-vous faire le [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12619,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[1042,83,549],"tags":[],"class_list":["post-12611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artistes","category-culture","category-emploi-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Statut des artistes : Greoli renvoie la balle au f\u00e9d\u00e9ral - Christos Doulkeridis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Statut des artistes : Greoli renvoie la balle au f\u00e9d\u00e9ral - Christos Doulkeridis\" \/>\n<meta property=\"og:description\" content=\"Voici l&rsquo;\u00e9change que j\u2019ai eu avec Alda Greoli, Ministre de la Culture autour de ses initiatives sur le statut des artistes et de sa position commune avec Sven Gatz, Ministre flamand de la Culture : la Ministre nous renvoie au travail de fond r\u00e9alis\u00e9 par le groupe \u00ab\u00a0Statut et Emploi\u00a0\u00bb de l&rsquo;op\u00e9ration \u00ab\u00a0Bouger les lignes\u00a0\u00bb. Par ailleurs, les comit\u00e9s de suivi op\u00e9rationnel sont actuellement en train d&rsquo;examiner les propositions de ce groupe. Quant \u00e0 une position commune sur le statut des artistes des cabinets Greoli et Gatz, c&rsquo;est en cours de concertation. En bref, rien de neuf sous le soleil \u00e0 part qu&rsquo;on renvoie tout au f\u00e9d\u00e9ral. Affaires \u00e0 suivre donc&#8230; Ma question\u00a0: Madame la Ministre, vous avez particip\u00e9 derni\u00e8rement \u00e0 la traditionnelle r\u00e9ception organis\u00e9e le R\u00e9seau des Arts \u00e0 Bruxelles (RAB), son pendant flamand, le Brussels Kunstenoverleg (BKO), le Conseil bruxellois des mus\u00e9es, la Concertation des centres culturels bruxellois et Cultuurcentrum Brussel. Vous y \u00e9tiez invit\u00e9e,ainsi que vos homologues, \u00e0 pr\u00e9senter vos priorit\u00e9s pour l\u2019ann\u00e9e 2017. Lors de la partie de la conf\u00e9rence \u00e0 laquelle j\u2019ai pu assister, vous avez rappel\u00e9, avec le ministre Gatz, votre objectif de faire avancer le dossier du statut des artistes. Pouvez-vous faire le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/\" \/>\n<meta property=\"og:site_name\" content=\"Christos Doulkeridis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/doulkeridis\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-15T15:06:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2017\/02\/statutartiste.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"475\" \/>\n\t<meta property=\"og:image:height\" content=\"317\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christos Doulkeridis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christos Doulkeridis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2017\\\/02\\\/15\\\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2017\\\/02\\\/15\\\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\\\/\"},\"author\":{\"name\":\"Christos Doulkeridis\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\"},\"headline\":\"Statut des artistes : Greoli renvoie la balle au f\u00e9d\u00e9ral\",\"datePublished\":\"2017-02-15T15:06:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2017\\\/02\\\/15\\\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\\\/\"},\"wordCount\":639,\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2017\\\/02\\\/15\\\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/statutartiste.jpg\",\"articleSection\":[\"artistes\",\"Culture\",\"Emploi\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2017\\\/02\\\/15\\\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2017\\\/02\\\/15\\\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\\\/\",\"name\":\"Statut des artistes : Greoli renvoie la balle au f\u00e9d\u00e9ral - Christos Doulkeridis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2017\\\/02\\\/15\\\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2017\\\/02\\\/15\\\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/statutartiste.jpg\",\"datePublished\":\"2017-02-15T15:06:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2017\\\/02\\\/15\\\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2017\\\/02\\\/15\\\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2017\\\/02\\\/15\\\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/statutartiste.jpg\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/statutartiste.jpg\",\"width\":475,\"height\":317},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2017\\\/02\\\/15\\\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Statut des artistes : Greoli renvoie la balle au f\u00e9d\u00e9ral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"name\":\"Christos Doulkeridis\",\"description\":\"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\",\"name\":\"Ulyse\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"width\":1024,\"height\":728,\"caption\":\"Ulyse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/doulkeridis\",\"https:\\\/\\\/www.facebook.com\\\/christosdoulkeridis2\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\",\"name\":\"Christos Doulkeridis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"caption\":\"Christos Doulkeridis\"},\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/author\\\/christos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Statut des artistes : Greoli renvoie la balle au f\u00e9d\u00e9ral - Christos Doulkeridis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/","og_locale":"fr_FR","og_type":"article","og_title":"Statut des artistes : Greoli renvoie la balle au f\u00e9d\u00e9ral - Christos Doulkeridis","og_description":"Voici l&rsquo;\u00e9change que j\u2019ai eu avec Alda Greoli, Ministre de la Culture autour de ses initiatives sur le statut des artistes et de sa position commune avec Sven Gatz, Ministre flamand de la Culture : la Ministre nous renvoie au travail de fond r\u00e9alis\u00e9 par le groupe \u00ab\u00a0Statut et Emploi\u00a0\u00bb de l&rsquo;op\u00e9ration \u00ab\u00a0Bouger les lignes\u00a0\u00bb. Par ailleurs, les comit\u00e9s de suivi op\u00e9rationnel sont actuellement en train d&rsquo;examiner les propositions de ce groupe. Quant \u00e0 une position commune sur le statut des artistes des cabinets Greoli et Gatz, c&rsquo;est en cours de concertation. En bref, rien de neuf sous le soleil \u00e0 part qu&rsquo;on renvoie tout au f\u00e9d\u00e9ral. Affaires \u00e0 suivre donc&#8230; Ma question\u00a0: Madame la Ministre, vous avez particip\u00e9 derni\u00e8rement \u00e0 la traditionnelle r\u00e9ception organis\u00e9e le R\u00e9seau des Arts \u00e0 Bruxelles (RAB), son pendant flamand, le Brussels Kunstenoverleg (BKO), le Conseil bruxellois des mus\u00e9es, la Concertation des centres culturels bruxellois et Cultuurcentrum Brussel. Vous y \u00e9tiez invit\u00e9e,ainsi que vos homologues, \u00e0 pr\u00e9senter vos priorit\u00e9s pour l\u2019ann\u00e9e 2017. Lors de la partie de la conf\u00e9rence \u00e0 laquelle j\u2019ai pu assister, vous avez rappel\u00e9, avec le ministre Gatz, votre objectif de faire avancer le dossier du statut des artistes. Pouvez-vous faire le [&hellip;]","og_url":"https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/","og_site_name":"Christos Doulkeridis","article_publisher":"https:\/\/www.facebook.com\/doulkeridis","article_published_time":"2017-02-15T15:06:18+00:00","og_image":[{"width":475,"height":317,"url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2017\/02\/statutartiste.jpg","type":"image\/jpeg"}],"author":"Christos Doulkeridis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Christos Doulkeridis","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/#article","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/"},"author":{"name":"Christos Doulkeridis","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365"},"headline":"Statut des artistes : Greoli renvoie la balle au f\u00e9d\u00e9ral","datePublished":"2017-02-15T15:06:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/"},"wordCount":639,"publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2017\/02\/statutartiste.jpg","articleSection":["artistes","Culture","Emploi"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/","url":"https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/","name":"Statut des artistes : Greoli renvoie la balle au f\u00e9d\u00e9ral - Christos Doulkeridis","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/#primaryimage"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2017\/02\/statutartiste.jpg","datePublished":"2017-02-15T15:06:18+00:00","breadcrumb":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/#primaryimage","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2017\/02\/statutartiste.jpg","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2017\/02\/statutartiste.jpg","width":475,"height":317},{"@type":"BreadcrumbList","@id":"https:\/\/www.doulkeridis.be\/blog\/2017\/02\/15\/statut-des-artistes-greoli-renvoie-la-balle-au-federal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.doulkeridis.be\/blog\/"},{"@type":"ListItem","position":2,"name":"Statut des artistes : Greoli renvoie la balle au f\u00e9d\u00e9ral"}]},{"@type":"WebSite","@id":"https:\/\/www.doulkeridis.be\/blog\/#website","url":"https:\/\/www.doulkeridis.be\/blog\/","name":"Christos Doulkeridis","description":"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations","publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doulkeridis.be\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.doulkeridis.be\/blog\/#organization","name":"Ulyse","url":"https:\/\/www.doulkeridis.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","width":1024,"height":728,"caption":"Ulyse"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/doulkeridis","https:\/\/www.facebook.com\/christosdoulkeridis2"]},{"@type":"Person","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365","name":"Christos Doulkeridis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","caption":"Christos Doulkeridis"},"url":"https:\/\/www.doulkeridis.be\/blog\/author\/christos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/12611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/comments?post=12611"}],"version-history":[{"count":12,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/12611\/revisions"}],"predecessor-version":[{"id":12638,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/12611\/revisions\/12638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media\/12619"}],"wp:attachment":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media?parent=12611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/categories?post=12611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/tags?post=12611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}