{"id":2395,"date":"2011-04-29T13:29:33","date_gmt":"2011-04-29T11:29:33","guid":{"rendered":"http:\/\/www.doulkeridis.be\/blog\/?p=2395"},"modified":"2011-08-08T14:16:19","modified_gmt":"2011-08-08T12:16:19","slug":"violences-a-legard-des-holebi-une-campagne-et-une-expo","status":"publish","type":"post","link":"https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/","title":{"rendered":"Violences \u00e0 l&rsquo;\u00e9gard des Holebi: une campagne et une expo"},"content":{"rendered":"<p><a href=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/04\/expo-holebi-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-2396\" title=\"expo holebi 3\" src=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/04\/expo-holebi-3-294x300.jpg\" alt=\"\" width=\"294\" height=\"300\" srcset=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/04\/expo-holebi-3-294x300.jpg 294w, https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/04\/expo-holebi-3.jpg 336w\" sizes=\"auto, (max-width: 294px) 100vw, 294px\" \/><\/a>A l&rsquo;initiative de mon coll\u00e8gue Bruno De Lille, Secr\u00e9taire d\u2019Etat \u00e0 l\u2019Egalit\u00e9 des Chances,<strong> la campagne de sensibilisation sur la violence et les agressions \u00e0 l\u2019\u00e9gard des lesbiennes, gays, bisexuel-le-s et transgenres<\/strong> a \u00e9t\u00e9 lanc\u00e9e cette semaine. Sur le site <a href=\"www.hatecrime.be\" target=\"_blank\">www.hatecrime.be<\/a>, vous trouverez plus d\u2019informations sur la campagne qui souhaite encourager les victimes de violence \u00e0 porter plainte. Personne ne devrait \u00eatre victime de violence ou d\u2019agression ! Que ce soit de la violence verbale, physique, sexuelle ou psychologique. Pourtant, nous savons que la r\u00e9alit\u00e9 est toute autre. Voil\u00e0 pourquoi j&rsquo;avais envie de relayer l&rsquo;initiative de Bruno de Lille et f\u00e9liciter toutes les associations qui s&rsquo;y joignent.<a href=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/04\/expo-holebi-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-2397\" title=\"expo holebi 1\" src=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/04\/expo-holebi-1.jpg\" alt=\"\" width=\"282\" height=\"283\" srcset=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/04\/expo-holebi-1.jpg 282w, https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/04\/expo-holebi-1-150x150.jpg 150w\" sizes=\"auto, (max-width: 282px) 100vw, 282px\" \/><\/a><\/p>\n<p>E<strong>n marge de cette campagne, se tient aux Halles Saint G\u00e9ry, une expo rassemblant une vingtaine d\u2019artistes \u00ab street art \u00bb <\/strong>(dont Tarantino, Jef Aerosol et Vanessa Dutour) qui ont mobilis\u00e9 leur talent en cr\u00e9ant des \u0153uvres originales sur le th\u00e8me du refus de la violence contre les lesbiennes, gays, bisexuel-le-s et transgenres en R\u00e9gion bruxelloise<\/p>\n<p><strong>Les \u0153uvres sont expos\u00e9es du 28 avril au 31 mai aux Halles Saint G\u00e9ry<\/strong>. Ensuite, l\u2019exposition circulera dans plusieurs lieux culturels. A voir!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A l&rsquo;initiative de mon coll\u00e8gue Bruno De Lille, Secr\u00e9taire d\u2019Etat \u00e0 l\u2019Egalit\u00e9 des Chances, la campagne de sensibilisation sur la violence et les agressions \u00e0 l\u2019\u00e9gard des lesbiennes, gays, bisexuel-le-s et transgenres a \u00e9t\u00e9 lanc\u00e9e cette semaine. Sur le site www.hatecrime.be, vous trouverez plus d\u2019informations sur la campagne qui souhaite encourager les victimes de violence \u00e0 porter plainte. Personne ne devrait \u00eatre victime de violence ou d\u2019agression ! Que ce soit de la violence verbale, physique, sexuelle ou psychologique. Pourtant, nous savons que la r\u00e9alit\u00e9 est toute autre. Voil\u00e0 pourquoi j&rsquo;avais envie de relayer l&rsquo;initiative de Bruno de Lille et f\u00e9liciter toutes les associations qui s&rsquo;y joignent. En marge de cette campagne, se tient aux Halles Saint G\u00e9ry, une expo rassemblant une vingtaine d\u2019artistes \u00ab street art \u00bb (dont Tarantino, Jef Aerosol et Vanessa Dutour) qui ont mobilis\u00e9 leur talent en cr\u00e9ant des \u0153uvres originales sur le th\u00e8me du refus de la violence contre les lesbiennes, gays, bisexuel-le-s et transgenres en R\u00e9gion bruxelloise Les \u0153uvres sont expos\u00e9es du 28 avril au 31 mai aux Halles Saint G\u00e9ry. Ensuite, l\u2019exposition circulera dans plusieurs lieux culturels. A voir!<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[305,246,245],"tags":[349,347,346,348,350],"class_list":["post-2395","post","type-post","status-publish","format-standard","hentry","category-mes-coups-de-coeur","category-sensibilisation","category-solidarite","tag-bisexuel-le-s","tag-gays","tag-holebi","tag-lesbiennes","tag-transgenres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Violences \u00e0 l&#039;\u00e9gard des Holebi: une campagne et une expo - Christos Doulkeridis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Violences \u00e0 l&#039;\u00e9gard des Holebi: une campagne et une expo - Christos Doulkeridis\" \/>\n<meta property=\"og:description\" content=\"A l&rsquo;initiative de mon coll\u00e8gue Bruno De Lille, Secr\u00e9taire d\u2019Etat \u00e0 l\u2019Egalit\u00e9 des Chances, la campagne de sensibilisation sur la violence et les agressions \u00e0 l\u2019\u00e9gard des lesbiennes, gays, bisexuel-le-s et transgenres a \u00e9t\u00e9 lanc\u00e9e cette semaine. Sur le site www.hatecrime.be, vous trouverez plus d\u2019informations sur la campagne qui souhaite encourager les victimes de violence \u00e0 porter plainte. Personne ne devrait \u00eatre victime de violence ou d\u2019agression ! Que ce soit de la violence verbale, physique, sexuelle ou psychologique. Pourtant, nous savons que la r\u00e9alit\u00e9 est toute autre. Voil\u00e0 pourquoi j&rsquo;avais envie de relayer l&rsquo;initiative de Bruno de Lille et f\u00e9liciter toutes les associations qui s&rsquo;y joignent. En marge de cette campagne, se tient aux Halles Saint G\u00e9ry, une expo rassemblant une vingtaine d\u2019artistes \u00ab street art \u00bb (dont Tarantino, Jef Aerosol et Vanessa Dutour) qui ont mobilis\u00e9 leur talent en cr\u00e9ant des \u0153uvres originales sur le th\u00e8me du refus de la violence contre les lesbiennes, gays, bisexuel-le-s et transgenres en R\u00e9gion bruxelloise Les \u0153uvres sont expos\u00e9es du 28 avril au 31 mai aux Halles Saint G\u00e9ry. Ensuite, l\u2019exposition circulera dans plusieurs lieux culturels. A voir!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/\" \/>\n<meta property=\"og:site_name\" content=\"Christos Doulkeridis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/doulkeridis\" \/>\n<meta property=\"article:published_time\" content=\"2011-04-29T11:29:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-08-08T12:16:19+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/04\/expo-holebi-3-294x300.jpg\" \/>\n<meta name=\"author\" content=\"Christos Doulkeridis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christos Doulkeridis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/04\\\/29\\\/violences-a-legard-des-holebi-une-campagne-et-une-expo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/04\\\/29\\\/violences-a-legard-des-holebi-une-campagne-et-une-expo\\\/\"},\"author\":{\"name\":\"Christos Doulkeridis\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\"},\"headline\":\"Violences \u00e0 l&rsquo;\u00e9gard des Holebi: une campagne et une expo\",\"datePublished\":\"2011-04-29T11:29:33+00:00\",\"dateModified\":\"2011-08-08T12:16:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/04\\\/29\\\/violences-a-legard-des-holebi-une-campagne-et-une-expo\\\/\"},\"wordCount\":212,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/04\\\/29\\\/violences-a-legard-des-holebi-une-campagne-et-une-expo\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/04\\\/expo-holebi-3-294x300.jpg\",\"keywords\":[\"bisexuel-le-s\",\"gays\",\"Holebi\",\"lesbiennes\",\"transgenres\"],\"articleSection\":[\"Mes coups de coeur\",\"Sensibilisation\",\"Solidarit\u00e9\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/04\\\/29\\\/violences-a-legard-des-holebi-une-campagne-et-une-expo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/04\\\/29\\\/violences-a-legard-des-holebi-une-campagne-et-une-expo\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/04\\\/29\\\/violences-a-legard-des-holebi-une-campagne-et-une-expo\\\/\",\"name\":\"Violences \u00e0 l'\u00e9gard des Holebi: une campagne et une expo - Christos Doulkeridis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/04\\\/29\\\/violences-a-legard-des-holebi-une-campagne-et-une-expo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/04\\\/29\\\/violences-a-legard-des-holebi-une-campagne-et-une-expo\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/04\\\/expo-holebi-3-294x300.jpg\",\"datePublished\":\"2011-04-29T11:29:33+00:00\",\"dateModified\":\"2011-08-08T12:16:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/04\\\/29\\\/violences-a-legard-des-holebi-une-campagne-et-une-expo\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/04\\\/29\\\/violences-a-legard-des-holebi-une-campagne-et-une-expo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/04\\\/29\\\/violences-a-legard-des-holebi-une-campagne-et-une-expo\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/04\\\/expo-holebi-3-294x300.jpg\",\"contentUrl\":\"http:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/04\\\/expo-holebi-3-294x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/04\\\/29\\\/violences-a-legard-des-holebi-une-campagne-et-une-expo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Violences \u00e0 l&rsquo;\u00e9gard des Holebi: une campagne et une expo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"name\":\"Christos Doulkeridis\",\"description\":\"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\",\"name\":\"Ulyse\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"width\":1024,\"height\":728,\"caption\":\"Ulyse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/doulkeridis\",\"https:\\\/\\\/www.facebook.com\\\/christosdoulkeridis2\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\",\"name\":\"Christos Doulkeridis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"caption\":\"Christos Doulkeridis\"},\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/author\\\/christos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Violences \u00e0 l'\u00e9gard des Holebi: une campagne et une expo - Christos Doulkeridis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/","og_locale":"fr_FR","og_type":"article","og_title":"Violences \u00e0 l'\u00e9gard des Holebi: une campagne et une expo - Christos Doulkeridis","og_description":"A l&rsquo;initiative de mon coll\u00e8gue Bruno De Lille, Secr\u00e9taire d\u2019Etat \u00e0 l\u2019Egalit\u00e9 des Chances, la campagne de sensibilisation sur la violence et les agressions \u00e0 l\u2019\u00e9gard des lesbiennes, gays, bisexuel-le-s et transgenres a \u00e9t\u00e9 lanc\u00e9e cette semaine. Sur le site www.hatecrime.be, vous trouverez plus d\u2019informations sur la campagne qui souhaite encourager les victimes de violence \u00e0 porter plainte. Personne ne devrait \u00eatre victime de violence ou d\u2019agression ! Que ce soit de la violence verbale, physique, sexuelle ou psychologique. Pourtant, nous savons que la r\u00e9alit\u00e9 est toute autre. Voil\u00e0 pourquoi j&rsquo;avais envie de relayer l&rsquo;initiative de Bruno de Lille et f\u00e9liciter toutes les associations qui s&rsquo;y joignent. En marge de cette campagne, se tient aux Halles Saint G\u00e9ry, une expo rassemblant une vingtaine d\u2019artistes \u00ab street art \u00bb (dont Tarantino, Jef Aerosol et Vanessa Dutour) qui ont mobilis\u00e9 leur talent en cr\u00e9ant des \u0153uvres originales sur le th\u00e8me du refus de la violence contre les lesbiennes, gays, bisexuel-le-s et transgenres en R\u00e9gion bruxelloise Les \u0153uvres sont expos\u00e9es du 28 avril au 31 mai aux Halles Saint G\u00e9ry. Ensuite, l\u2019exposition circulera dans plusieurs lieux culturels. A voir!","og_url":"https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/","og_site_name":"Christos Doulkeridis","article_publisher":"https:\/\/www.facebook.com\/doulkeridis","article_published_time":"2011-04-29T11:29:33+00:00","article_modified_time":"2011-08-08T12:16:19+00:00","og_image":[{"url":"http:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/04\/expo-holebi-3-294x300.jpg","type":"","width":"","height":""}],"author":"Christos Doulkeridis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Christos Doulkeridis","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/#article","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/"},"author":{"name":"Christos Doulkeridis","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365"},"headline":"Violences \u00e0 l&rsquo;\u00e9gard des Holebi: une campagne et une expo","datePublished":"2011-04-29T11:29:33+00:00","dateModified":"2011-08-08T12:16:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/"},"wordCount":212,"commentCount":0,"publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/#primaryimage"},"thumbnailUrl":"http:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/04\/expo-holebi-3-294x300.jpg","keywords":["bisexuel-le-s","gays","Holebi","lesbiennes","transgenres"],"articleSection":["Mes coups de coeur","Sensibilisation","Solidarit\u00e9"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/","url":"https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/","name":"Violences \u00e0 l'\u00e9gard des Holebi: une campagne et une expo - Christos Doulkeridis","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/#primaryimage"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/#primaryimage"},"thumbnailUrl":"http:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/04\/expo-holebi-3-294x300.jpg","datePublished":"2011-04-29T11:29:33+00:00","dateModified":"2011-08-08T12:16:19+00:00","breadcrumb":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/#primaryimage","url":"http:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/04\/expo-holebi-3-294x300.jpg","contentUrl":"http:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/04\/expo-holebi-3-294x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.doulkeridis.be\/blog\/2011\/04\/29\/violences-a-legard-des-holebi-une-campagne-et-une-expo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.doulkeridis.be\/blog\/"},{"@type":"ListItem","position":2,"name":"Violences \u00e0 l&rsquo;\u00e9gard des Holebi: une campagne et une expo"}]},{"@type":"WebSite","@id":"https:\/\/www.doulkeridis.be\/blog\/#website","url":"https:\/\/www.doulkeridis.be\/blog\/","name":"Christos Doulkeridis","description":"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations","publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doulkeridis.be\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.doulkeridis.be\/blog\/#organization","name":"Ulyse","url":"https:\/\/www.doulkeridis.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","width":1024,"height":728,"caption":"Ulyse"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/doulkeridis","https:\/\/www.facebook.com\/christosdoulkeridis2"]},{"@type":"Person","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365","name":"Christos Doulkeridis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","caption":"Christos Doulkeridis"},"url":"https:\/\/www.doulkeridis.be\/blog\/author\/christos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/2395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/comments?post=2395"}],"version-history":[{"count":6,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/2395\/revisions"}],"predecessor-version":[{"id":2402,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/2395\/revisions\/2402"}],"wp:attachment":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media?parent=2395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/categories?post=2395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/tags?post=2395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}