{"id":3096,"date":"2011-07-05T11:16:21","date_gmt":"2011-07-05T09:16:21","guid":{"rendered":"http:\/\/www.doulkeridis.be\/blog\/?p=3096"},"modified":"2011-10-03T16:32:51","modified_gmt":"2011-10-03T14:32:51","slug":"du-logement-social-dans-les-projets-prives-une-idee-a-creuser","status":"publish","type":"post","link":"https:\/\/www.doulkeridis.be\/blog\/2011\/07\/05\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\/","title":{"rendered":"Du logement social dans les projets priv\u00e9s? Une id\u00e9e \u00e0 creuser"},"content":{"rendered":"<p><a href=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/07\/b\u00e2timent-exemplaire-006.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-3105\" title=\"b\u00e2timent exemplaire 006\" src=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/07\/b\u00e2timent-exemplaire-006-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/07\/b\u00e2timent-exemplaire-006-300x200.jpg 300w, https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2011\/07\/b\u00e2timent-exemplaire-006-1024x685.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><em><strong>Pour r\u00e9pondre au d\u00e9fi que repr\u00e9sente la crise du logement, j&rsquo;ai souvent r\u00e9p\u00e9t\u00e9 qu&rsquo;il fallait aussi proposer des id\u00e9es innovantes pour la R\u00e9gion bruxelloise. Lors de la r\u00e9union de la Commission Logement qui s&rsquo;est tenue ce matin, en r\u00e9ponse \u00e0 une question d&rsquo;Alain Maron (Ecolo), j&rsquo;ai donn\u00e9 plus de pr\u00e9cisions sur une id\u00e9e en pleine gestation: r\u00e9server un pourcentage de logements \u00e0 finalit\u00e9 sociale dans les projets immobiliers priv\u00e9s d&rsquo;une certaine taille.<\/strong><\/em><\/p>\n<p>Les efforts du Gouvernement pour porter \u00e0 15% la proportion de logements \u00e0 gestion publique et \u00e0 finalit\u00e9 sociale dans toutes les communes d&rsquo;ici \u00e0 2020, notamment via le Plan Logement (dont j\u2019esp\u00e8re qu\u2019il pourra d\u00e9boucher sur une production annuelle de 1.000 logements \u00e0 partir de 2012), pourraient se r\u00e9v\u00e9ler insuffisants, surtout si paral\u00adl\u00e8lement le rythme de la production de logements priv\u00e9s se maintient voire s&rsquo;accro\u00eet.<!--more--><\/p>\n<p>Ce probl\u00e8me n&rsquo;existe pas v\u00e9cu uniquement \u00e0 Bruxelles. En R\u00e9gion flamande, \u00e0 Lille, \u00e0 la Ville de Paris et au Grand-Duch\u00e9 du Luxembourg, les autorit\u00e9s se sont \u00e9galement fix\u00e9es comme objectif d&rsquo;augmenter la proportion de logements sociaux dans les zones qui en sont trop peu pourvues. A cette fin, elles se sont donn\u00e9es les moyens d&rsquo;imposer la production de logements \u00e0 caract\u00e8re social conjointement aux op\u00e9rations priv\u00e9es de production de logements. Examinons-les plus en d\u00e9tail.<\/p>\n<p><strong>En R\u00e9gion flamande<\/strong>, le \u00ab\u00a0Grond-en Pandendecreet\u00a0\u00bb du 27 mars 2009 contient au moins une disposition int\u00e9ressante. <strong>Il impose aux promoteurs de r\u00e9server, dans les zones comprenant moins de 9% de logements sociaux, 10 \u00e0 20 % des lots ou des surfaces planchers \u00e0 du logement social<\/strong>. Ces lots ou logements doivent \u00eatre revendus aux soci\u00e9t\u00e9s de logement social soit \u00e0 la valeur estim\u00e9e par le Receveur de l&rsquo;Enregistrement ou le Comit\u00e9 d&rsquo;Acquisition (pour les terrains), soit aux prix bar\u00eamis\u00e9s du secteur du logement social.<\/p>\n<p><strong>A Lille,<\/strong> le Conseil municipal a vot\u00e9 \u00e0 l&rsquo;unanimit\u00e9, le 1er f\u00e9vrier 2010, deux mesures fortes en faveur du logement social. Jusqu\u2019\u00e0 ce moment, <strong>les op\u00e9rations de construction sup\u00e9rieures \u00e0 50 logements devaient d\u00e9j\u00e0 int\u00e9grer au moins 25% de logements locatifs sociaux<\/strong>. Depuis f\u00e9vrier 2010,<strong> l\u2019imposition a \u00e9t\u00e9 \u00e9tendue \u00e0 toutes les op\u00e9rations \u00e0 partir de 17 logements, et le quota de logements sociaux a \u00e9t\u00e9 port\u00e9 \u00e0 30%<\/strong>.<\/p>\n<p><strong>A la Ville de Paris<\/strong>, les autorit\u00e9s administratives urbanistiques ont pr\u00e9vu d\u2019instaurer une r\u00e8gle d\u2019\u00e9quilibre et d\u2019harmonie pour favoriser la construction de logements sociaux dans les secteurs qui en sont le moins pourvus et la construction de logements libres dans ceux o\u00f9 il y en a moins\u00a0: <strong>c\u2019est la nouvelle r\u00e8gle des 25%, applicable dans un p\u00e9rim\u00e8tre dit \u00ab\u00a0en d\u00e9ficit\u00a0\u00bb de logements sociaux<\/strong>. Dans ce p\u00e9rim\u00e8tre, le futur r\u00e8glement demandera aux op\u00e9rateurs priv\u00e9s, lors d\u2019op\u00e9rations de construction de logements, mais aussi pour celles r\u00e9alis\u00e9es sous forme de r\u00e9habilitations, de r\u00e9server 25% de la surface hors \u0153uvre nette \u00e0 des logements sociaux. La disposition s\u2019applique ici seulement aux programmes de logement dont la surface est sup\u00e9rieure \u00e0 1.000m\u00b2. Concr\u00e8tement, pour la construction d\u2019un immeuble de 3.000m\u00b2, soit environ 33 logements sur la base de 90m\u00b2 par logement, 750m\u00b2, soit environ 8 logements, seront offerts au logement social.<\/p>\n<p><strong>Au Grand-Duch\u00e9 du Luxembourg<\/strong>, dans le cadre des Plans Particuliers d\u2019Am\u00e9nagement, <strong>tout projet priv\u00e9 de plus d&rsquo;1 hectare doit pr\u00e9voir 10 % de logements \u00ab\u00a0\u00e0 co\u00fbt mod\u00e9r\u00e9\u00a0\u00bb<\/strong>, destin\u00e9s \u00e0 des personnes r\u00e9pondant aux conditions d\u2019octroi des primes de construction ou d\u2019acquisition concernant l\u2019aide au logement, et mis sur le march\u00e9 dans de conditions de vente ou de location bar\u00e9mis\u00e9es.<\/p>\n<p>Ces mod\u00e8les m\u00e9ritent qu&rsquo;on les \u00e9tudie en profondeur. Il s\u2019agirait d<strong>\u2019un outil des plus efficaces pour assurer une mixit\u00e9 de types de logements dans tous les quartiers<\/strong> et ce, dans un contexte de raret\u00e9 des terrains et d\u2019opportunit\u00e9s immobili\u00e8res, d\u2019une fa\u00e7on de favoriser la mixit\u00e9 sociale en assurant entre les communes une r\u00e9partition \u00e9quilibr\u00e9e et diversifi\u00e9e de l\u2019offre de logements. Autre avantage important \u00e0 mes yeux\u00a0: les logements sociaux produits dans le cadre d\u2019un tel dispositif seraient dispers\u00e9s au sein m\u00eame d&rsquo;ensembles de logements libres et ins\u00e9r\u00e9s dans des copropri\u00e9t\u00e9s avec des tiers.<\/p>\n<p>Pour l\u2019heure, des experts juridiques et immobiliers planchent sur la question. J\u2019ai \u00e9galement pris des contacts avec le secteur. Il est important d&rsquo;anticiper tous les aspects et d\u2019\u00e9tudier l\u2019impact financier sur les op\u00e9rations immobili\u00e8res. <strong>On voit cependant que dans les R\u00e9gions o\u00f9 la r\u00e8gle est d\u2019application, le march\u00e9 ne s\u2019est pas \u00e9croul\u00e9.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour r\u00e9pondre au d\u00e9fi que repr\u00e9sente la crise du logement, j&rsquo;ai souvent r\u00e9p\u00e9t\u00e9 qu&rsquo;il fallait aussi proposer des id\u00e9es innovantes pour la R\u00e9gion bruxelloise. Lors de la r\u00e9union de la Commission Logement qui s&rsquo;est tenue ce matin, en r\u00e9ponse \u00e0 une question d&rsquo;Alain Maron (Ecolo), j&rsquo;ai donn\u00e9 plus de pr\u00e9cisions sur une id\u00e9e en pleine gestation: r\u00e9server un pourcentage de logements \u00e0 finalit\u00e9 sociale dans les projets immobiliers priv\u00e9s d&rsquo;une certaine taille. Les efforts du Gouvernement pour porter \u00e0 15% la proportion de logements \u00e0 gestion publique et \u00e0 finalit\u00e9 sociale dans toutes les communes d&rsquo;ici \u00e0 2020, notamment via le Plan Logement (dont j\u2019esp\u00e8re qu\u2019il pourra d\u00e9boucher sur une production annuelle de 1.000 logements \u00e0 partir de 2012), pourraient se r\u00e9v\u00e9ler insuffisants, surtout si paral\u00adl\u00e8lement le rythme de la production de logements priv\u00e9s se maintient voire s&rsquo;accro\u00eet.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,303],"tags":[4,224],"class_list":["post-3096","post","type-post","status-publish","format-standard","hentry","category-logement","category-mes_projets","tag-logement-social","tag-plan-logement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Du logement social dans les projets priv\u00e9s? Une id\u00e9e \u00e0 creuser - Christos Doulkeridis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doulkeridis.be\/blog\/2011\/07\/05\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Du logement social dans les projets priv\u00e9s? Une id\u00e9e \u00e0 creuser - Christos Doulkeridis\" \/>\n<meta property=\"og:description\" content=\"Pour r\u00e9pondre au d\u00e9fi que repr\u00e9sente la crise du logement, j&rsquo;ai souvent r\u00e9p\u00e9t\u00e9 qu&rsquo;il fallait aussi proposer des id\u00e9es innovantes pour la R\u00e9gion bruxelloise. Lors de la r\u00e9union de la Commission Logement qui s&rsquo;est tenue ce matin, en r\u00e9ponse \u00e0 une question d&rsquo;Alain Maron (Ecolo), j&rsquo;ai donn\u00e9 plus de pr\u00e9cisions sur une id\u00e9e en pleine gestation: r\u00e9server un pourcentage de logements \u00e0 finalit\u00e9 sociale dans les projets immobiliers priv\u00e9s d&rsquo;une certaine taille. Les efforts du Gouvernement pour porter \u00e0 15% la proportion de logements \u00e0 gestion publique et \u00e0 finalit\u00e9 sociale dans toutes les communes d&rsquo;ici \u00e0 2020, notamment via le Plan Logement (dont j\u2019esp\u00e8re qu\u2019il pourra d\u00e9boucher sur une production annuelle de 1.000 logements \u00e0 partir de 2012), pourraient se r\u00e9v\u00e9ler insuffisants, surtout si paral\u00adl\u00e8lement le rythme de la production de logements priv\u00e9s se maintient voire s&rsquo;accro\u00eet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.doulkeridis.be\/blog\/2011\/07\/05\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\/\" \/>\n<meta property=\"og:site_name\" content=\"Christos Doulkeridis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/doulkeridis\" \/>\n<meta property=\"article:published_time\" content=\"2011-07-05T09:16:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-10-03T14:32:51+00:00\" \/>\n<meta name=\"author\" content=\"Christos Doulkeridis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christos Doulkeridis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/07\\\/05\\\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/07\\\/05\\\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\\\/\"},\"author\":{\"name\":\"Christos Doulkeridis\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\"},\"headline\":\"Du logement social dans les projets priv\u00e9s? Une id\u00e9e \u00e0 creuser\",\"datePublished\":\"2011-07-05T09:16:21+00:00\",\"dateModified\":\"2011-10-03T14:32:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/07\\\/05\\\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\\\/\"},\"wordCount\":816,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"keywords\":[\"logement social\",\"Plan Logement\"],\"articleSection\":[\"Logement\",\"Mes projets\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/07\\\/05\\\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/07\\\/05\\\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/07\\\/05\\\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\\\/\",\"name\":\"Du logement social dans les projets priv\u00e9s? Une id\u00e9e \u00e0 creuser - Christos Doulkeridis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\"},\"datePublished\":\"2011-07-05T09:16:21+00:00\",\"dateModified\":\"2011-10-03T14:32:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/07\\\/05\\\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/07\\\/05\\\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2011\\\/07\\\/05\\\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Du logement social dans les projets priv\u00e9s? Une id\u00e9e \u00e0 creuser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"name\":\"Christos Doulkeridis\",\"description\":\"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\",\"name\":\"Ulyse\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"width\":1024,\"height\":728,\"caption\":\"Ulyse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/doulkeridis\",\"https:\\\/\\\/www.facebook.com\\\/christosdoulkeridis2\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\",\"name\":\"Christos Doulkeridis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"caption\":\"Christos Doulkeridis\"},\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/author\\\/christos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Du logement social dans les projets priv\u00e9s? Une id\u00e9e \u00e0 creuser - Christos Doulkeridis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doulkeridis.be\/blog\/2011\/07\/05\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\/","og_locale":"fr_FR","og_type":"article","og_title":"Du logement social dans les projets priv\u00e9s? Une id\u00e9e \u00e0 creuser - Christos Doulkeridis","og_description":"Pour r\u00e9pondre au d\u00e9fi que repr\u00e9sente la crise du logement, j&rsquo;ai souvent r\u00e9p\u00e9t\u00e9 qu&rsquo;il fallait aussi proposer des id\u00e9es innovantes pour la R\u00e9gion bruxelloise. Lors de la r\u00e9union de la Commission Logement qui s&rsquo;est tenue ce matin, en r\u00e9ponse \u00e0 une question d&rsquo;Alain Maron (Ecolo), j&rsquo;ai donn\u00e9 plus de pr\u00e9cisions sur une id\u00e9e en pleine gestation: r\u00e9server un pourcentage de logements \u00e0 finalit\u00e9 sociale dans les projets immobiliers priv\u00e9s d&rsquo;une certaine taille. Les efforts du Gouvernement pour porter \u00e0 15% la proportion de logements \u00e0 gestion publique et \u00e0 finalit\u00e9 sociale dans toutes les communes d&rsquo;ici \u00e0 2020, notamment via le Plan Logement (dont j\u2019esp\u00e8re qu\u2019il pourra d\u00e9boucher sur une production annuelle de 1.000 logements \u00e0 partir de 2012), pourraient se r\u00e9v\u00e9ler insuffisants, surtout si paral\u00adl\u00e8lement le rythme de la production de logements priv\u00e9s se maintient voire s&rsquo;accro\u00eet.","og_url":"https:\/\/www.doulkeridis.be\/blog\/2011\/07\/05\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\/","og_site_name":"Christos Doulkeridis","article_publisher":"https:\/\/www.facebook.com\/doulkeridis","article_published_time":"2011-07-05T09:16:21+00:00","article_modified_time":"2011-10-03T14:32:51+00:00","author":"Christos Doulkeridis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Christos Doulkeridis","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.doulkeridis.be\/blog\/2011\/07\/05\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\/#article","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2011\/07\/05\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\/"},"author":{"name":"Christos Doulkeridis","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365"},"headline":"Du logement social dans les projets priv\u00e9s? Une id\u00e9e \u00e0 creuser","datePublished":"2011-07-05T09:16:21+00:00","dateModified":"2011-10-03T14:32:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2011\/07\/05\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\/"},"wordCount":816,"commentCount":0,"publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"keywords":["logement social","Plan Logement"],"articleSection":["Logement","Mes projets"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.doulkeridis.be\/blog\/2011\/07\/05\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.doulkeridis.be\/blog\/2011\/07\/05\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\/","url":"https:\/\/www.doulkeridis.be\/blog\/2011\/07\/05\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\/","name":"Du logement social dans les projets priv\u00e9s? Une id\u00e9e \u00e0 creuser - Christos Doulkeridis","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#website"},"datePublished":"2011-07-05T09:16:21+00:00","dateModified":"2011-10-03T14:32:51+00:00","breadcrumb":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2011\/07\/05\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doulkeridis.be\/blog\/2011\/07\/05\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.doulkeridis.be\/blog\/2011\/07\/05\/du-logement-social-dans-les-projets-prives-une-idee-a-creuser\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.doulkeridis.be\/blog\/"},{"@type":"ListItem","position":2,"name":"Du logement social dans les projets priv\u00e9s? Une id\u00e9e \u00e0 creuser"}]},{"@type":"WebSite","@id":"https:\/\/www.doulkeridis.be\/blog\/#website","url":"https:\/\/www.doulkeridis.be\/blog\/","name":"Christos Doulkeridis","description":"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations","publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doulkeridis.be\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.doulkeridis.be\/blog\/#organization","name":"Ulyse","url":"https:\/\/www.doulkeridis.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","width":1024,"height":728,"caption":"Ulyse"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/doulkeridis","https:\/\/www.facebook.com\/christosdoulkeridis2"]},{"@type":"Person","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365","name":"Christos Doulkeridis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","caption":"Christos Doulkeridis"},"url":"https:\/\/www.doulkeridis.be\/blog\/author\/christos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/3096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/comments?post=3096"}],"version-history":[{"count":19,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/3096\/revisions"}],"predecessor-version":[{"id":4542,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/3096\/revisions\/4542"}],"wp:attachment":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media?parent=3096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/categories?post=3096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/tags?post=3096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}