{"id":3984,"date":"2008-02-20T10:46:24","date_gmt":"2008-02-20T08:46:24","guid":{"rendered":"http:\/\/www.doulkeridis.be\/blog\/?p=3984"},"modified":"2011-08-17T11:52:01","modified_gmt":"2011-08-17T09:52:01","slug":"pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques","status":"publish","type":"post","link":"https:\/\/www.doulkeridis.be\/blog\/2008\/02\/20\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\/","title":{"rendered":"Pics de pollution : Les Belges sont pr\u00eats \u00e0 modifier leurs comportements et r\u00e9clament des gestes forts de la part des autorit\u00e9s publiques"},"content":{"rendered":"<p><em>Depuis le d\u00e9but de cet hiver, la Belgique a connu  plusieurs pics de pollution. Un ph\u00e9nom\u00e8ne pr\u00e9occupant pour notre sant\u00e9  et qui nous concerne toutes et tous au premier plan.<br \/>\n<\/em><\/p>\n<p><em> <\/em><\/p>\n<p><em>Comme le d\u00e9montre une \u00e9tude r\u00e9alis\u00e9e  par Dedicated research, les Belges semblent en avoir pris conscience et  se disent pr\u00eats \u00e0 modifier leurs comportements. Vous trouverez <a href=\"http:\/\/www.lesoir.be\/mediastore\/_2008\/fevrier\/du_11_au_20\/_19_sondage_pics_lesoir.pdf\">en cliquant ici<\/a> la totalit\u00e9 de cette \u00e9tude pour laquelle 700 Wallons et Bruxellois ont \u00e9t\u00e9 interrog\u00e9s. En voici les grandes lignes\u00a0:<\/em><\/p>\n<p><em><!--more--><\/em><img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> Sur  le plan de la sant\u00e9 et sur les causes, 77% des sond\u00e9s consid\u00e8rent que  les pics de pollution repr\u00e9sentent un danger pour leur sant\u00e9. Cette  proportion passe \u00e0 91% lorsqu\u2019il s\u2019agit de la sant\u00e9 des personnes plus  fragiles, telles que les enfants ou les personnes \u00e2g\u00e9es. 75% des sond\u00e9s  identifient clairement la voiture comme cause principale des pics de  pollution.<\/p>\n<p><img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> Cot\u00e9  comportement, 68% des personnes s\u2019engagent \u00e0 diminuer leur chauffage\u00a0;  65% \u00e0 adopter une conduite plus souple\u00a0; 47% \u00e0 rouler moins ou \u00e0 ne pas  utiliser leur voiture\u00a0; 27% \u00e0 opter pour le covoiturage.<\/p>\n<p><img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> Au  niveau des mesures, 69% des personnes sond\u00e9es jugent l\u2019action des  pouvoirs publics insuffisante\u00a0; 78% se disent favorables \u00e0 la limitation  de vitesse sur les autoroutes\u00a0; 62% \u00e0 l\u2019interdiction de circuler dans  les centres-villes en cas de pics de pollution.<\/p>\n<p><img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> Pour  lutter de mani\u00e8re structurelle contre la pollution de l\u2019air, 86% des  personnes sond\u00e9es r\u00e9clament un investissement massif dans les transports  publics et 67% attendent que l\u2019on taxe plus fortement es v\u00e9hicules les  plus polluants. Et 55% se disent favorables \u00e0 un p\u00e9age urbain.<\/p>\n<p>En tant qu\u2019\u00e9lu \u00e9cologiste, il m\u2019appara\u00eet \u00e9galement tr\u00e8s  important d\u2019apporter des solutions structurelles \u00e0 cot\u00e9 des mesures  ponctuelles d\u00e9velopp\u00e9es par l\u2019actuel Gouvernement bruxellois dans le  cadre du Plan Bruxell\u2019air. C\u2019est dans cet esprit que j\u2019ai propos\u00e9 la  cr\u00e9ation de la carte Hypermobil, une carte qui permet \u00e0 son utilisateur  de se d\u00e9placer avec un seul outil sur l\u2019ensemble des r\u00e9seaux de  transport en commun, de taxis mais \u00e9galement de faire usage du Thalys,  du syst\u00e8me de voiture partag\u00e9e et d\u2019acheter un v\u00e9lo. Alternative \u00e0 la  voiture de soci\u00e9t\u00e9 (qui constitue la moiti\u00e9 des nouvelles  immatriculations en Belgique et les trois quarts \u00e0 Bruxelles), cette  carte serait aliment\u00e9e par l\u2019employeur ou par les particuliers, qui  b\u00e9n\u00e9ficieraient dans ce dernier cas de tarifs pr\u00e9f\u00e9rentiels (<a href=\"..\/..\/article.php3?id_secteur=4&amp;id_rubrique=36&amp;id_article=240&amp;debut_article=5\">toutes les infos sur ce projet en cliquant ici<\/a>).  Ce projet a s\u00e9duit les diff\u00e9rentes soci\u00e9t\u00e9s de transport ainsi que le  monde des entreprises. Il ne reste qu\u2019\u00e0 octroyer la d\u00e9ductibilit\u00e9  fiscale pour les entreprises. Mesure qui d\u00e9pend exclusivement du  Gouvernement f\u00e9d\u00e9ral et sur laquelle ECOLO a d\u00e9j\u00e0 interpell\u00e9 le Ministre  comp\u00e9tent.<br \/>\nA c\u00f4t\u00e9 des autres mesures propos\u00e9es par ECOLO comme la cr\u00e9ation d\u2019une  vignette \u00ab\u00a0Ecoscore\u00a0\u00bb qui informerait les consommateurs du bilan  environnemental de chaque v\u00e9hicule, l\u2019adoption d\u2019une loi permettant aux  centres urbains de cr\u00e9er des zones dont l\u2019accessibilit\u00e9 est li\u00e9e au  degr\u00e9 de pollution d\u2019un v\u00e9hicule et l\u2019octroi de primes valables dans  tout le pays pour encourager le recours au LPG et l\u2019installation d\u2019un  filtre \u00e0 particules, la carte Hypermobil participerait \u00e0 la r\u00e9duction  des particules fines pr\u00e9sentes dans l\u2019air que nous respirons et qui  proviennent en partie des v\u00e9hicules diesel.<\/p>\n<p>Car s\u2019il est vrai que le diesel g\u00e9n\u00e8re moins d\u2019\u00e9missions  CO2 selon le type de v\u00e9hicule, la plupart des mod\u00e8les actuellement  commercialis\u00e9s ou pr\u00e9sents sur nos routes et dans nos rues \u00e9mettent  \u00e9norm\u00e9ment de particules fines, ces fameuses poussi\u00e8res noires qu\u2019on  retrouve au final sur nos fa\u00e7ades, nos fen\u00eatres &#8230; et dans nos poumons.  Il s\u2019agit donc d\u2019un probl\u00e8me de sant\u00e9 publique qui nous touche toutes  et tous dans notre qualit\u00e9 de vie au quotidien.<\/p>\n<p>Produits par la combustion du diesel, ces particules  forment sans doute une des composantes les plus nocives des \u00e9missions  des moteurs \u00e0 combustion. Selon diverses \u00e9tudes, la part du trafic  routier dans les \u00e9missions de particules varie de 20 \u00e0 40% selon les  endroits o\u00f9 les mesures sont effectu\u00e9es. En R\u00e9gion bruxelloise, jusqu\u2019\u00e0  70% des particules pr\u00e9sentes dans l\u2019air proviennent de la circulation  motoris\u00e9e.<\/p>\n<p>Or un rapport command\u00e9 par l\u2019Union europ\u00e9enne \u00e9tablit  que les particules fines raccourcissent l\u2019esp\u00e9rance de vie moyenne de la  population d\u2019une dur\u00e9e de 1 \u00e0 3 ans. Par ailleurs, les \u00e9tudes indiquent  que les particules fines contribuent \u00e0 g\u00e9n\u00e9rer des maladies des voies  respiratoires, des d\u00e9faillances cardiovasculaires et des cancers des  poumons. De nombreux sp\u00e9cialistes sont \u00e9galement convaincus que la  spectaculaire augmentation du nombre d\u2019allergies et des personnes  souffrant d\u2019asthme est \u00e9troitement &#8211; mais pas exclusivement &#8211; li\u00e9 \u00e0 la  pollution atmosph\u00e9rique. A noter que la Belgique compte 800.000  asthmatiques et que cette maladie est en progression rapide.<\/p>\n<p>L\u2019exposition aux particules fines a donc des effets  extr\u00eamement nocifs sur la sant\u00e9 et diminue l\u2019esp\u00e9rance de vie. Une  priorit\u00e9 doit donc \u00eatre accord\u00e9e \u00e0 la r\u00e9duction durable de cette  exposition et \u00e0 la diminution des concentrations. Il s\u2019agit non  seulement d\u2019un enjeu de sant\u00e9 publique mais \u00e9galement d\u2019un enjeu  \u00e9conomique. Selon l\u2019OMS, l\u2019Europe pourrait \u00e9conomiser jusqu\u2019\u00e0 161  milliards par an en r\u00e9duisant la mortalit\u00e9 g\u00e9n\u00e9r\u00e9e par les particules  fines. Quant au co\u00fbt du traitement des maladies qu\u2019elles entra\u00eenent, il  pourrait diminuer de 29 milliards d\u2019euros par an. Autant de montants qui  pourraient \u00eatre consacr\u00e9s \u00e0 d\u2019autres politiques et \u00e0 l\u2019am\u00e9lioration des  moyens de transport plus respectueux de l\u2019environnement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis le d\u00e9but de cet hiver, la Belgique a connu plusieurs pics de pollution. Un ph\u00e9nom\u00e8ne pr\u00e9occupant pour notre sant\u00e9 et qui nous concerne toutes et tous au premier plan. Comme le d\u00e9montre une \u00e9tude r\u00e9alis\u00e9e par Dedicated research, les Belges semblent en avoir pris conscience et se disent pr\u00eats \u00e0 modifier leurs comportements. Vous trouverez en cliquant ici la totalit\u00e9 de cette \u00e9tude pour laquelle 700 Wallons et Bruxellois ont \u00e9t\u00e9 interrog\u00e9s. En voici les grandes lignes\u00a0:<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[243,303,304],"tags":[197,13],"class_list":["post-3984","post","type-post","status-publish","format-standard","hentry","category-environnement-2","category-mes_projets","category-mes_realisations","tag-durable","tag-environnement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pics de pollution : Les Belges sont pr\u00eats \u00e0 modifier leurs comportements et r\u00e9clament des gestes forts de la part des autorit\u00e9s publiques - Christos Doulkeridis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doulkeridis.be\/blog\/2008\/02\/20\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pics de pollution : Les Belges sont pr\u00eats \u00e0 modifier leurs comportements et r\u00e9clament des gestes forts de la part des autorit\u00e9s publiques - Christos Doulkeridis\" \/>\n<meta property=\"og:description\" content=\"Depuis le d\u00e9but de cet hiver, la Belgique a connu plusieurs pics de pollution. Un ph\u00e9nom\u00e8ne pr\u00e9occupant pour notre sant\u00e9 et qui nous concerne toutes et tous au premier plan. Comme le d\u00e9montre une \u00e9tude r\u00e9alis\u00e9e par Dedicated research, les Belges semblent en avoir pris conscience et se disent pr\u00eats \u00e0 modifier leurs comportements. Vous trouverez en cliquant ici la totalit\u00e9 de cette \u00e9tude pour laquelle 700 Wallons et Bruxellois ont \u00e9t\u00e9 interrog\u00e9s. En voici les grandes lignes\u00a0:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.doulkeridis.be\/blog\/2008\/02\/20\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Christos Doulkeridis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/doulkeridis\" \/>\n<meta property=\"article:published_time\" content=\"2008-02-20T08:46:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-08-17T09:52:01+00:00\" \/>\n<meta name=\"author\" content=\"Christos Doulkeridis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christos Doulkeridis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2008\\\/02\\\/20\\\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2008\\\/02\\\/20\\\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\\\/\"},\"author\":{\"name\":\"Christos Doulkeridis\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\"},\"headline\":\"Pics de pollution : Les Belges sont pr\u00eats \u00e0 modifier leurs comportements et r\u00e9clament des gestes forts de la part des autorit\u00e9s publiques\",\"datePublished\":\"2008-02-20T08:46:24+00:00\",\"dateModified\":\"2011-08-17T09:52:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2008\\\/02\\\/20\\\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\\\/\"},\"wordCount\":983,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"keywords\":[\"durable\",\"environnement\"],\"articleSection\":[\"Environnement\",\"Mes projets\",\"Mes r\u00e9alisations\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2008\\\/02\\\/20\\\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2008\\\/02\\\/20\\\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2008\\\/02\\\/20\\\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\\\/\",\"name\":\"Pics de pollution : Les Belges sont pr\u00eats \u00e0 modifier leurs comportements et r\u00e9clament des gestes forts de la part des autorit\u00e9s publiques - Christos Doulkeridis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\"},\"datePublished\":\"2008-02-20T08:46:24+00:00\",\"dateModified\":\"2011-08-17T09:52:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2008\\\/02\\\/20\\\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2008\\\/02\\\/20\\\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2008\\\/02\\\/20\\\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pics de pollution : Les Belges sont pr\u00eats \u00e0 modifier leurs comportements et r\u00e9clament des gestes forts de la part des autorit\u00e9s publiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"name\":\"Christos Doulkeridis\",\"description\":\"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\",\"name\":\"Ulyse\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"width\":1024,\"height\":728,\"caption\":\"Ulyse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/doulkeridis\",\"https:\\\/\\\/www.facebook.com\\\/christosdoulkeridis2\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\",\"name\":\"Christos Doulkeridis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"caption\":\"Christos Doulkeridis\"},\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/author\\\/christos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pics de pollution : Les Belges sont pr\u00eats \u00e0 modifier leurs comportements et r\u00e9clament des gestes forts de la part des autorit\u00e9s publiques - Christos Doulkeridis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doulkeridis.be\/blog\/2008\/02\/20\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\/","og_locale":"fr_FR","og_type":"article","og_title":"Pics de pollution : Les Belges sont pr\u00eats \u00e0 modifier leurs comportements et r\u00e9clament des gestes forts de la part des autorit\u00e9s publiques - Christos Doulkeridis","og_description":"Depuis le d\u00e9but de cet hiver, la Belgique a connu plusieurs pics de pollution. Un ph\u00e9nom\u00e8ne pr\u00e9occupant pour notre sant\u00e9 et qui nous concerne toutes et tous au premier plan. Comme le d\u00e9montre une \u00e9tude r\u00e9alis\u00e9e par Dedicated research, les Belges semblent en avoir pris conscience et se disent pr\u00eats \u00e0 modifier leurs comportements. Vous trouverez en cliquant ici la totalit\u00e9 de cette \u00e9tude pour laquelle 700 Wallons et Bruxellois ont \u00e9t\u00e9 interrog\u00e9s. En voici les grandes lignes\u00a0:","og_url":"https:\/\/www.doulkeridis.be\/blog\/2008\/02\/20\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\/","og_site_name":"Christos Doulkeridis","article_publisher":"https:\/\/www.facebook.com\/doulkeridis","article_published_time":"2008-02-20T08:46:24+00:00","article_modified_time":"2011-08-17T09:52:01+00:00","author":"Christos Doulkeridis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Christos Doulkeridis","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.doulkeridis.be\/blog\/2008\/02\/20\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\/#article","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2008\/02\/20\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\/"},"author":{"name":"Christos Doulkeridis","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365"},"headline":"Pics de pollution : Les Belges sont pr\u00eats \u00e0 modifier leurs comportements et r\u00e9clament des gestes forts de la part des autorit\u00e9s publiques","datePublished":"2008-02-20T08:46:24+00:00","dateModified":"2011-08-17T09:52:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2008\/02\/20\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\/"},"wordCount":983,"commentCount":0,"publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"keywords":["durable","environnement"],"articleSection":["Environnement","Mes projets","Mes r\u00e9alisations"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.doulkeridis.be\/blog\/2008\/02\/20\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.doulkeridis.be\/blog\/2008\/02\/20\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\/","url":"https:\/\/www.doulkeridis.be\/blog\/2008\/02\/20\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\/","name":"Pics de pollution : Les Belges sont pr\u00eats \u00e0 modifier leurs comportements et r\u00e9clament des gestes forts de la part des autorit\u00e9s publiques - Christos Doulkeridis","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#website"},"datePublished":"2008-02-20T08:46:24+00:00","dateModified":"2011-08-17T09:52:01+00:00","breadcrumb":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2008\/02\/20\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doulkeridis.be\/blog\/2008\/02\/20\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.doulkeridis.be\/blog\/2008\/02\/20\/pics-de-pollution-les-belges-sont-prets-a-modifier-leurs-comportements-et-reclament-des-gestes-forts-de-la-part-des-autorites-publiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.doulkeridis.be\/blog\/"},{"@type":"ListItem","position":2,"name":"Pics de pollution : Les Belges sont pr\u00eats \u00e0 modifier leurs comportements et r\u00e9clament des gestes forts de la part des autorit\u00e9s publiques"}]},{"@type":"WebSite","@id":"https:\/\/www.doulkeridis.be\/blog\/#website","url":"https:\/\/www.doulkeridis.be\/blog\/","name":"Christos Doulkeridis","description":"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations","publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doulkeridis.be\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.doulkeridis.be\/blog\/#organization","name":"Ulyse","url":"https:\/\/www.doulkeridis.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","width":1024,"height":728,"caption":"Ulyse"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/doulkeridis","https:\/\/www.facebook.com\/christosdoulkeridis2"]},{"@type":"Person","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365","name":"Christos Doulkeridis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","caption":"Christos Doulkeridis"},"url":"https:\/\/www.doulkeridis.be\/blog\/author\/christos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/3984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/comments?post=3984"}],"version-history":[{"count":3,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/3984\/revisions"}],"predecessor-version":[{"id":4147,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/3984\/revisions\/4147"}],"wp:attachment":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media?parent=3984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/categories?post=3984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/tags?post=3984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}