{"id":4100,"date":"2005-07-15T11:11:59","date_gmt":"2005-07-15T09:11:59","guid":{"rendered":"http:\/\/www.doulkeridis.be\/blog\/?p=4100"},"modified":"2011-08-17T11:13:20","modified_gmt":"2011-08-17T09:13:20","slug":"mon-cv","status":"publish","type":"post","link":"https:\/\/www.doulkeridis.be\/blog\/2005\/07\/15\/mon-cv\/","title":{"rendered":"Mon CV"},"content":{"rendered":"<div dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"..\/..\/IMG\/arton101.jpg\" alt=\"http:\/\/www.doulkeridis.be\/IMG\/arton101.jpg\" width=\"265\" height=\"176\" \/><strong>N\u00e9 en mars 1968, j\u2019ai fait  mes \u00e9tudes \u00e0 Bruxelles. En 1988, je suis devenu membre du parti Ecolo et  j\u2019ai occup\u00e9 une s\u00e9rie de fonctions au sein du parti avant de devenir  d\u00e9put\u00e9 en 1999. En 2004, j\u2019ai pr\u00e9sid\u00e9 le Parlement francophone  bruxellois. Cinq ans plus tard, je suis r\u00e9\u00e9lu. En juillet 2009, apr\u00e8s  avoir \u00e9t\u00e9 n\u00e9gociateur de mon parti en vue de la formation du  gouvernement de la R\u00e9gion de Bruxelles-Capitale, je deviens le nouveau  Secr\u00e9taire d\u2019Etat au Logement et au Siamu. Je me vois \u00e9galement confier  la Pr\u00e9sidence du Coll\u00e8ge de la COCOF, la politique du Tourisme,  l\u2019Enseignement et le Budget.<br \/>\n<\/strong><\/div>\n<p><strong>Mes fonctions actuelles<\/strong><br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> Secr\u00e9taire d\u2019Etat au Logement \u00e0 Bruxelles et au Siamu<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> Ministre-Pr\u00e9sident du Coll\u00e8ge de la COCOF, en charge de l\u2019Enseignement, du Tourisme et du Budget.<\/p>\n<p><strong>Mes fonctions pr\u00e9c\u00e9dentes<\/strong><br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> <strong>de juillet 2004 \u00e0 juin 2009<\/strong> :  Pr\u00e9sident du Parlement francophone bruxellois, D\u00e9put\u00e9 au Parlement de  la R\u00e9gion de Bruxelles-Capitale, Pr\u00e9sident de la Commission du Budget\u00a0;  de l\u2019Administration\u00a0; des Relations internationales et des Comp\u00e9tences  r\u00e9siduaires, Pr\u00e9sident de la Commission de Coop\u00e9ration avec d\u2019autres  parlements\u00a0; Secr\u00e9taire politique d\u2019ECOLOBXL<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> <strong>de juin 1999 \u00e0 juin 2004<\/strong> : D\u00e9put\u00e9 bruxellois<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> <strong>de septembre 2002 \u00e0 juin 2004<\/strong> : Chef de groupe au Parlement bruxellois<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> <strong>d\u2019octobre 2000 \u00e0 septembre 2002<\/strong> : Chef de groupe Cocof<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> <strong>de juin 1999 \u00e0 septembre 2001<\/strong> : D\u00e9put\u00e9 et Vice-Pr\u00e9sident du  Parlement de la Communaut\u00e9 fran\u00e7aise<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> <strong>1996- 1999<\/strong> : Assistant politique du secr\u00e9tariat f\u00e9d\u00e9ral et coordinateur du programme ECOLO<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> <strong>1991- 1994<\/strong> : Secr\u00e9taire parlementaire d\u2019Andr\u00e9 Drouart et de Jacques Liesenborghs<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> <strong>1992-1996<\/strong> : Secr\u00e9taire politique de la r\u00e9gionale Ecolo-Bruxelles<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> <strong>1991<\/strong> : Secr\u00e9taire de la locale d\u2019Ecolo-Anderlecht<\/p>\n<p><!--more--><strong>Ma formation<\/strong><br \/>\nAutodidacte<br \/>\nDipl\u00f4m\u00e9 de l\u2019enseignement secondaire sup\u00e9rieur<\/p>\n<p><strong>Les dossiers que j\u2019affectionne particuli\u00e8rement<\/strong><br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> le d\u00e9veloppement durable et les opportunit\u00e9s \u00e9conomiques qu\u2019offre l\u2019\u00e9cologie<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> l\u2019\u00e9nergie du futur<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> l\u2019enjeu du \u00ab\u00a0logement pour tous\u00a0\u00bb dans une capitale internationale<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> l\u2019emploi et la formation professionnelle<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> le  d\u00e9veloppement \u00e9conomique de la R\u00e9gion de Bruxelles-Capitale dans le  double contexte de concurrence interr\u00e9gionale et internationale<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> la revalorisation de l\u2019enseignement technique et professionnel<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> la culture accessible \u00e0 tous, l\u2019audiovisuel<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> la gouvernance politique<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> l\u2019associatif<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> le financement et l\u2019avenir institutionnel de Bruxelles<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> le bilinguisme, l\u2019apprentissage des langues<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> la promotion du fran\u00e7ais \u00e0 l\u2019\u00e9chelle internationale<\/p>\n<p><strong>Les dossiers r\u00e9alis\u00e9s et \u00e0 r\u00e9aliser&#8230;<\/strong><br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> Auteur du livre <em>\u00ab\u00a0Des Belges ont commenc\u00e9 \u00e0 sauver la plan\u00e8te\u00a0\u00bb<\/em><br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> Cr\u00e9ateur du projet \u00ab\u00a0Hypermobil\u00a0\u00bb\u00a0: une alternative \u00e0 l\u2019usage exclusif de la voiture individuelle<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> D\u00e9veloppement (plus visible) de la cuisine \u00ab\u00a0Slow Food\u00a0\u00bb<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> Pr\u00e9paration d\u2019un colloque \u00ab\u00a0Kyoto\u00a0: des contraintes aux opportunit\u00e9s \u00e9conomiques\u00a0\u00bb<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> Etude de faisabilit\u00e9 d\u2019un TGV fret<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> D\u00e9veloppement d\u2019activit\u00e9s citoyennes<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> D\u00e9veloppement de la langue fran\u00e7aise et de sa richesse dans les nouveaux pays adh\u00e9rents \u00e0 l\u2019Union europ\u00e9enne<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> R\u00e9alisation d\u2019outils politiques p\u00e9dagogiques \u00e0 destination de la population<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> Pr\u00e9paration \u00e0 l\u2019\u00e9chelle f\u00e9d\u00e9rale de la prochaine campagne \u00e9lectorale<\/p>\n<p><strong>Mes loisirs<\/strong><br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> La cuisine<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> Musique<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> B.D<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> Le graphisme<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> Le v\u00e9lo<br \/>\n<img decoding=\"async\" src=\"..\/..\/ecrire\/puce.gif\" alt=\"-\" \/> La lecture<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e9 en mars 1968, j\u2019ai fait mes \u00e9tudes \u00e0 Bruxelles. En 1988, je suis devenu membre du parti Ecolo et j\u2019ai occup\u00e9 une s\u00e9rie de fonctions au sein du parti avant de devenir d\u00e9put\u00e9 en 1999. En 2004, j\u2019ai pr\u00e9sid\u00e9 le Parlement francophone bruxellois. Cinq ans plus tard, je suis r\u00e9\u00e9lu. En juillet 2009, apr\u00e8s avoir \u00e9t\u00e9 n\u00e9gociateur de mon parti en vue de la formation du gouvernement de la R\u00e9gion de Bruxelles-Capitale, je deviens le nouveau Secr\u00e9taire d\u2019Etat au Logement et au Siamu. Je me vois \u00e9galement confier la Pr\u00e9sidence du Coll\u00e8ge de la COCOF, la politique du Tourisme, l\u2019Enseignement et le Budget. Mes fonctions actuelles Secr\u00e9taire d\u2019Etat au Logement \u00e0 Bruxelles et au Siamu Ministre-Pr\u00e9sident du Coll\u00e8ge de la COCOF, en charge de l\u2019Enseignement, du Tourisme et du Budget. Mes fonctions pr\u00e9c\u00e9dentes de juillet 2004 \u00e0 juin 2009 : Pr\u00e9sident du Parlement francophone bruxellois, D\u00e9put\u00e9 au Parlement de la R\u00e9gion de Bruxelles-Capitale, Pr\u00e9sident de la Commission du Budget\u00a0; de l\u2019Administration\u00a0; des Relations internationales et des Comp\u00e9tences r\u00e9siduaires, Pr\u00e9sident de la Commission de Coop\u00e9ration avec d\u2019autres parlements\u00a0; Secr\u00e9taire politique d\u2019ECOLOBXL de juin 1999 \u00e0 juin 2004 : D\u00e9put\u00e9 bruxellois de septembre 2002 \u00e0 juin 2004 : Chef de groupe [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[304,110],"tags":[],"class_list":["post-4100","post","type-post","status-publish","format-standard","hentry","category-mes_realisations","category-perso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mon CV - Christos Doulkeridis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doulkeridis.be\/blog\/2005\/07\/15\/mon-cv\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mon CV - Christos Doulkeridis\" \/>\n<meta property=\"og:description\" content=\"N\u00e9 en mars 1968, j\u2019ai fait mes \u00e9tudes \u00e0 Bruxelles. En 1988, je suis devenu membre du parti Ecolo et j\u2019ai occup\u00e9 une s\u00e9rie de fonctions au sein du parti avant de devenir d\u00e9put\u00e9 en 1999. En 2004, j\u2019ai pr\u00e9sid\u00e9 le Parlement francophone bruxellois. Cinq ans plus tard, je suis r\u00e9\u00e9lu. En juillet 2009, apr\u00e8s avoir \u00e9t\u00e9 n\u00e9gociateur de mon parti en vue de la formation du gouvernement de la R\u00e9gion de Bruxelles-Capitale, je deviens le nouveau Secr\u00e9taire d\u2019Etat au Logement et au Siamu. Je me vois \u00e9galement confier la Pr\u00e9sidence du Coll\u00e8ge de la COCOF, la politique du Tourisme, l\u2019Enseignement et le Budget. Mes fonctions actuelles Secr\u00e9taire d\u2019Etat au Logement \u00e0 Bruxelles et au Siamu Ministre-Pr\u00e9sident du Coll\u00e8ge de la COCOF, en charge de l\u2019Enseignement, du Tourisme et du Budget. Mes fonctions pr\u00e9c\u00e9dentes de juillet 2004 \u00e0 juin 2009 : Pr\u00e9sident du Parlement francophone bruxellois, D\u00e9put\u00e9 au Parlement de la R\u00e9gion de Bruxelles-Capitale, Pr\u00e9sident de la Commission du Budget\u00a0; de l\u2019Administration\u00a0; des Relations internationales et des Comp\u00e9tences r\u00e9siduaires, Pr\u00e9sident de la Commission de Coop\u00e9ration avec d\u2019autres parlements\u00a0; Secr\u00e9taire politique d\u2019ECOLOBXL de juin 1999 \u00e0 juin 2004 : D\u00e9put\u00e9 bruxellois de septembre 2002 \u00e0 juin 2004 : Chef de groupe [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.doulkeridis.be\/blog\/2005\/07\/15\/mon-cv\/\" \/>\n<meta property=\"og:site_name\" content=\"Christos Doulkeridis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/doulkeridis\" \/>\n<meta property=\"article:published_time\" content=\"2005-07-15T09:11:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-08-17T09:13:20+00:00\" \/>\n<meta name=\"author\" content=\"Christos Doulkeridis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christos Doulkeridis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2005\\\/07\\\/15\\\/mon-cv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2005\\\/07\\\/15\\\/mon-cv\\\/\"},\"author\":{\"name\":\"Christos Doulkeridis\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\"},\"headline\":\"Mon CV\",\"datePublished\":\"2005-07-15T09:11:59+00:00\",\"dateModified\":\"2011-08-17T09:13:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2005\\\/07\\\/15\\\/mon-cv\\\/\"},\"wordCount\":521,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"articleSection\":[\"Mes r\u00e9alisations\",\"Mon espace Perso\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2005\\\/07\\\/15\\\/mon-cv\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2005\\\/07\\\/15\\\/mon-cv\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2005\\\/07\\\/15\\\/mon-cv\\\/\",\"name\":\"Mon CV - Christos Doulkeridis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\"},\"datePublished\":\"2005-07-15T09:11:59+00:00\",\"dateModified\":\"2011-08-17T09:13:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2005\\\/07\\\/15\\\/mon-cv\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2005\\\/07\\\/15\\\/mon-cv\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2005\\\/07\\\/15\\\/mon-cv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mon CV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"name\":\"Christos Doulkeridis\",\"description\":\"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\",\"name\":\"Ulyse\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"width\":1024,\"height\":728,\"caption\":\"Ulyse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/doulkeridis\",\"https:\\\/\\\/www.facebook.com\\\/christosdoulkeridis2\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\",\"name\":\"Christos Doulkeridis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"caption\":\"Christos Doulkeridis\"},\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/author\\\/christos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mon CV - Christos Doulkeridis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doulkeridis.be\/blog\/2005\/07\/15\/mon-cv\/","og_locale":"fr_FR","og_type":"article","og_title":"Mon CV - Christos Doulkeridis","og_description":"N\u00e9 en mars 1968, j\u2019ai fait mes \u00e9tudes \u00e0 Bruxelles. En 1988, je suis devenu membre du parti Ecolo et j\u2019ai occup\u00e9 une s\u00e9rie de fonctions au sein du parti avant de devenir d\u00e9put\u00e9 en 1999. En 2004, j\u2019ai pr\u00e9sid\u00e9 le Parlement francophone bruxellois. Cinq ans plus tard, je suis r\u00e9\u00e9lu. En juillet 2009, apr\u00e8s avoir \u00e9t\u00e9 n\u00e9gociateur de mon parti en vue de la formation du gouvernement de la R\u00e9gion de Bruxelles-Capitale, je deviens le nouveau Secr\u00e9taire d\u2019Etat au Logement et au Siamu. Je me vois \u00e9galement confier la Pr\u00e9sidence du Coll\u00e8ge de la COCOF, la politique du Tourisme, l\u2019Enseignement et le Budget. Mes fonctions actuelles Secr\u00e9taire d\u2019Etat au Logement \u00e0 Bruxelles et au Siamu Ministre-Pr\u00e9sident du Coll\u00e8ge de la COCOF, en charge de l\u2019Enseignement, du Tourisme et du Budget. Mes fonctions pr\u00e9c\u00e9dentes de juillet 2004 \u00e0 juin 2009 : Pr\u00e9sident du Parlement francophone bruxellois, D\u00e9put\u00e9 au Parlement de la R\u00e9gion de Bruxelles-Capitale, Pr\u00e9sident de la Commission du Budget\u00a0; de l\u2019Administration\u00a0; des Relations internationales et des Comp\u00e9tences r\u00e9siduaires, Pr\u00e9sident de la Commission de Coop\u00e9ration avec d\u2019autres parlements\u00a0; Secr\u00e9taire politique d\u2019ECOLOBXL de juin 1999 \u00e0 juin 2004 : D\u00e9put\u00e9 bruxellois de septembre 2002 \u00e0 juin 2004 : Chef de groupe [&hellip;]","og_url":"https:\/\/www.doulkeridis.be\/blog\/2005\/07\/15\/mon-cv\/","og_site_name":"Christos Doulkeridis","article_publisher":"https:\/\/www.facebook.com\/doulkeridis","article_published_time":"2005-07-15T09:11:59+00:00","article_modified_time":"2011-08-17T09:13:20+00:00","author":"Christos Doulkeridis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Christos Doulkeridis","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.doulkeridis.be\/blog\/2005\/07\/15\/mon-cv\/#article","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2005\/07\/15\/mon-cv\/"},"author":{"name":"Christos Doulkeridis","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365"},"headline":"Mon CV","datePublished":"2005-07-15T09:11:59+00:00","dateModified":"2011-08-17T09:13:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2005\/07\/15\/mon-cv\/"},"wordCount":521,"commentCount":0,"publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"articleSection":["Mes r\u00e9alisations","Mon espace Perso"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.doulkeridis.be\/blog\/2005\/07\/15\/mon-cv\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.doulkeridis.be\/blog\/2005\/07\/15\/mon-cv\/","url":"https:\/\/www.doulkeridis.be\/blog\/2005\/07\/15\/mon-cv\/","name":"Mon CV - Christos Doulkeridis","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#website"},"datePublished":"2005-07-15T09:11:59+00:00","dateModified":"2011-08-17T09:13:20+00:00","breadcrumb":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2005\/07\/15\/mon-cv\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doulkeridis.be\/blog\/2005\/07\/15\/mon-cv\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.doulkeridis.be\/blog\/2005\/07\/15\/mon-cv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.doulkeridis.be\/blog\/"},{"@type":"ListItem","position":2,"name":"Mon CV"}]},{"@type":"WebSite","@id":"https:\/\/www.doulkeridis.be\/blog\/#website","url":"https:\/\/www.doulkeridis.be\/blog\/","name":"Christos Doulkeridis","description":"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations","publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doulkeridis.be\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.doulkeridis.be\/blog\/#organization","name":"Ulyse","url":"https:\/\/www.doulkeridis.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","width":1024,"height":728,"caption":"Ulyse"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/doulkeridis","https:\/\/www.facebook.com\/christosdoulkeridis2"]},{"@type":"Person","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365","name":"Christos Doulkeridis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","caption":"Christos Doulkeridis"},"url":"https:\/\/www.doulkeridis.be\/blog\/author\/christos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/4100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/comments?post=4100"}],"version-history":[{"count":1,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/4100\/revisions"}],"predecessor-version":[{"id":4101,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/4100\/revisions\/4101"}],"wp:attachment":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media?parent=4100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/categories?post=4100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/tags?post=4100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}