{"id":755,"date":"2010-07-19T16:27:06","date_gmt":"2010-07-19T14:27:06","guid":{"rendered":"http:\/\/www.doulkeridis.be\/blog\/?p=755"},"modified":"2011-08-09T15:04:37","modified_gmt":"2011-08-09T13:04:37","slug":"plan-regional-du-logement-11-nouveaux-projets","status":"publish","type":"post","link":"https:\/\/www.doulkeridis.be\/blog\/2010\/07\/19\/plan-regional-du-logement-11-nouveaux-projets\/","title":{"rendered":"Plan r\u00e9gional du logement : 11 nouveaux projets"},"content":{"rendered":"<p>Vendredi dernier, j&rsquo;ai fait avaliser par le Gouvernement de la R\u00e9gion bruxelloise 11 nouveaux projets de nouvelles constructions dans le cadre du Plan r\u00e9gional du logement. J&rsquo;en suis tr\u00e8s heureux car ces projets sont un nouveau pas en avant vers l&rsquo;objectif r\u00e9gional de 15% de logements de qualit\u00e9 de gestion publique \u00e0 finalit\u00e9 sociale dans toutes les communes.<strong> Les 11 projets en question &#8211; on compte 260 logements sociaux et 78 logements moyens &#8211; repr\u00e9sentent un investissement de 43 millions d&rsquo;euros et seront r\u00e9partis de mani\u00e8re \u00e9quilibr\u00e9e sur le territoire r\u00e9gional.<\/strong> Ils viendront s&rsquo;implanter notamment dans les communes d&rsquo;Anderlecht, de Molenbeek-Saint-Jean, d&rsquo;Uccle, d&rsquo;Evere, de Forest, de Schaerbeek et de Saint-Gilles. J&rsquo;en profite d&rsquo;ailleurs pour rappeler que j&rsquo;ai d\u00e9j\u00e0 rencontr\u00e9 une premi\u00e8re fois les bourgmestres et \u00e9chevins responsables des 19 communes bruxelloise et que mon intention est de continuer \u00e0 entretenir des contacts r\u00e9guliers pour faire avancer collectivement l&rsquo;ensemble des projets de construction et de r\u00e9novation du parc de logements publics.<\/p>\n<p>Autre motif de satisfaction pour moi:<strong> tous ces nouveaux projets seront \u00e0 la pointe en termes d&rsquo;\u00e9co-construction et d&rsquo;int\u00e9gration environnementale<\/strong> (standard passif, mat\u00e9riaux de construction sains et durables, r\u00e9cup\u00e9ration de l&rsquo;eau de pluie, \u00e9nergies renouvelables, jardins et potagers collectifs, &#8230;). Il s&rsquo;agit d&rsquo;inscrire l&rsquo;ensemble des mesures planifi\u00e9es dans une perspective de durabilit\u00e9 afin que notre lutte contre la crise du logement &#8211; un d\u00e9fi social\u00a0ET \u00e9conomique &#8211; contribue aussi \u00e0 une r\u00e9ponse bruxelloise aux enjeux environnementaux et \u00e9nerg\u00e9tiques, pour faire de Bruxelles la capitale europ\u00e9enne du d\u00e9veloppement durable. <strong>Le standard passif des nouveaux logements permettra aux locataires de r\u00e9aliser de fortes \u00e9conomies (jusque 90%) sur leur facture de chauffage.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vendredi dernier, j&rsquo;ai fait avaliser par le Gouvernement de la R\u00e9gion bruxelloise 11 nouveaux projets de nouvelles constructions dans le cadre du Plan r\u00e9gional du logement. J&rsquo;en suis tr\u00e8s heureux car ces projets sont un nouveau pas en avant vers l&rsquo;objectif r\u00e9gional de 15% de logements de qualit\u00e9 de gestion publique \u00e0 finalit\u00e9 sociale dans toutes les communes. Les 11 projets en question &#8211; on compte 260 logements sociaux et 78 logements moyens &#8211; repr\u00e9sentent un investissement de 43 millions d&rsquo;euros et seront r\u00e9partis de mani\u00e8re \u00e9quilibr\u00e9e sur le territoire r\u00e9gional. Ils viendront s&rsquo;implanter notamment dans les communes d&rsquo;Anderlecht, de Molenbeek-Saint-Jean, d&rsquo;Uccle, d&rsquo;Evere, de Forest, de Schaerbeek et de Saint-Gilles. J&rsquo;en profite d&rsquo;ailleurs pour rappeler que j&rsquo;ai d\u00e9j\u00e0 rencontr\u00e9 une premi\u00e8re fois les bourgmestres et \u00e9chevins responsables des 19 communes bruxelloise et que mon intention est de continuer \u00e0 entretenir des contacts r\u00e9guliers pour faire avancer collectivement l&rsquo;ensemble des projets de construction et de r\u00e9novation du parc de logements publics. Autre motif de satisfaction pour moi: tous ces nouveaux projets seront \u00e0 la pointe en termes d&rsquo;\u00e9co-construction et d&rsquo;int\u00e9gration environnementale (standard passif, mat\u00e9riaux de construction sains et durables, r\u00e9cup\u00e9ration de l&rsquo;eau de pluie, \u00e9nergies renouvelables, jardins et potagers collectifs, &#8230;). [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,304],"tags":[47,197,1011,4,37],"class_list":["post-755","post","type-post","status-publish","format-standard","hentry","category-logement","category-mes_realisations","tag-durabilite","tag-durable","tag-logement","tag-logement-social","tag-passif"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plan r\u00e9gional du logement : 11 nouveaux projets - Christos Doulkeridis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doulkeridis.be\/blog\/2010\/07\/19\/plan-regional-du-logement-11-nouveaux-projets\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan r\u00e9gional du logement : 11 nouveaux projets - Christos Doulkeridis\" \/>\n<meta property=\"og:description\" content=\"Vendredi dernier, j&rsquo;ai fait avaliser par le Gouvernement de la R\u00e9gion bruxelloise 11 nouveaux projets de nouvelles constructions dans le cadre du Plan r\u00e9gional du logement. J&rsquo;en suis tr\u00e8s heureux car ces projets sont un nouveau pas en avant vers l&rsquo;objectif r\u00e9gional de 15% de logements de qualit\u00e9 de gestion publique \u00e0 finalit\u00e9 sociale dans toutes les communes. Les 11 projets en question &#8211; on compte 260 logements sociaux et 78 logements moyens &#8211; repr\u00e9sentent un investissement de 43 millions d&rsquo;euros et seront r\u00e9partis de mani\u00e8re \u00e9quilibr\u00e9e sur le territoire r\u00e9gional. Ils viendront s&rsquo;implanter notamment dans les communes d&rsquo;Anderlecht, de Molenbeek-Saint-Jean, d&rsquo;Uccle, d&rsquo;Evere, de Forest, de Schaerbeek et de Saint-Gilles. J&rsquo;en profite d&rsquo;ailleurs pour rappeler que j&rsquo;ai d\u00e9j\u00e0 rencontr\u00e9 une premi\u00e8re fois les bourgmestres et \u00e9chevins responsables des 19 communes bruxelloise et que mon intention est de continuer \u00e0 entretenir des contacts r\u00e9guliers pour faire avancer collectivement l&rsquo;ensemble des projets de construction et de r\u00e9novation du parc de logements publics. Autre motif de satisfaction pour moi: tous ces nouveaux projets seront \u00e0 la pointe en termes d&rsquo;\u00e9co-construction et d&rsquo;int\u00e9gration environnementale (standard passif, mat\u00e9riaux de construction sains et durables, r\u00e9cup\u00e9ration de l&rsquo;eau de pluie, \u00e9nergies renouvelables, jardins et potagers collectifs, &#8230;). [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.doulkeridis.be\/blog\/2010\/07\/19\/plan-regional-du-logement-11-nouveaux-projets\/\" \/>\n<meta property=\"og:site_name\" content=\"Christos Doulkeridis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/doulkeridis\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-19T14:27:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-08-09T13:04:37+00:00\" \/>\n<meta name=\"author\" content=\"Christos Doulkeridis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christos Doulkeridis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/07\\\/19\\\/plan-regional-du-logement-11-nouveaux-projets\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/07\\\/19\\\/plan-regional-du-logement-11-nouveaux-projets\\\/\"},\"author\":{\"name\":\"Christos Doulkeridis\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\"},\"headline\":\"Plan r\u00e9gional du logement : 11 nouveaux projets\",\"datePublished\":\"2010-07-19T14:27:06+00:00\",\"dateModified\":\"2011-08-09T13:04:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/07\\\/19\\\/plan-regional-du-logement-11-nouveaux-projets\\\/\"},\"wordCount\":306,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"keywords\":[\"durabilit\u00e9\",\"durable\",\"Logement\",\"logement social\",\"passif\"],\"articleSection\":[\"Logement\",\"Mes r\u00e9alisations\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/07\\\/19\\\/plan-regional-du-logement-11-nouveaux-projets\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/07\\\/19\\\/plan-regional-du-logement-11-nouveaux-projets\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/07\\\/19\\\/plan-regional-du-logement-11-nouveaux-projets\\\/\",\"name\":\"Plan r\u00e9gional du logement : 11 nouveaux projets - Christos Doulkeridis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\"},\"datePublished\":\"2010-07-19T14:27:06+00:00\",\"dateModified\":\"2011-08-09T13:04:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/07\\\/19\\\/plan-regional-du-logement-11-nouveaux-projets\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/07\\\/19\\\/plan-regional-du-logement-11-nouveaux-projets\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/07\\\/19\\\/plan-regional-du-logement-11-nouveaux-projets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plan r\u00e9gional du logement : 11 nouveaux projets\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"name\":\"Christos Doulkeridis\",\"description\":\"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\",\"name\":\"Ulyse\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"width\":1024,\"height\":728,\"caption\":\"Ulyse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/doulkeridis\",\"https:\\\/\\\/www.facebook.com\\\/christosdoulkeridis2\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\",\"name\":\"Christos Doulkeridis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"caption\":\"Christos Doulkeridis\"},\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/author\\\/christos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plan r\u00e9gional du logement : 11 nouveaux projets - Christos Doulkeridis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doulkeridis.be\/blog\/2010\/07\/19\/plan-regional-du-logement-11-nouveaux-projets\/","og_locale":"fr_FR","og_type":"article","og_title":"Plan r\u00e9gional du logement : 11 nouveaux projets - Christos Doulkeridis","og_description":"Vendredi dernier, j&rsquo;ai fait avaliser par le Gouvernement de la R\u00e9gion bruxelloise 11 nouveaux projets de nouvelles constructions dans le cadre du Plan r\u00e9gional du logement. J&rsquo;en suis tr\u00e8s heureux car ces projets sont un nouveau pas en avant vers l&rsquo;objectif r\u00e9gional de 15% de logements de qualit\u00e9 de gestion publique \u00e0 finalit\u00e9 sociale dans toutes les communes. Les 11 projets en question &#8211; on compte 260 logements sociaux et 78 logements moyens &#8211; repr\u00e9sentent un investissement de 43 millions d&rsquo;euros et seront r\u00e9partis de mani\u00e8re \u00e9quilibr\u00e9e sur le territoire r\u00e9gional. Ils viendront s&rsquo;implanter notamment dans les communes d&rsquo;Anderlecht, de Molenbeek-Saint-Jean, d&rsquo;Uccle, d&rsquo;Evere, de Forest, de Schaerbeek et de Saint-Gilles. J&rsquo;en profite d&rsquo;ailleurs pour rappeler que j&rsquo;ai d\u00e9j\u00e0 rencontr\u00e9 une premi\u00e8re fois les bourgmestres et \u00e9chevins responsables des 19 communes bruxelloise et que mon intention est de continuer \u00e0 entretenir des contacts r\u00e9guliers pour faire avancer collectivement l&rsquo;ensemble des projets de construction et de r\u00e9novation du parc de logements publics. Autre motif de satisfaction pour moi: tous ces nouveaux projets seront \u00e0 la pointe en termes d&rsquo;\u00e9co-construction et d&rsquo;int\u00e9gration environnementale (standard passif, mat\u00e9riaux de construction sains et durables, r\u00e9cup\u00e9ration de l&rsquo;eau de pluie, \u00e9nergies renouvelables, jardins et potagers collectifs, &#8230;). [&hellip;]","og_url":"https:\/\/www.doulkeridis.be\/blog\/2010\/07\/19\/plan-regional-du-logement-11-nouveaux-projets\/","og_site_name":"Christos Doulkeridis","article_publisher":"https:\/\/www.facebook.com\/doulkeridis","article_published_time":"2010-07-19T14:27:06+00:00","article_modified_time":"2011-08-09T13:04:37+00:00","author":"Christos Doulkeridis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Christos Doulkeridis","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.doulkeridis.be\/blog\/2010\/07\/19\/plan-regional-du-logement-11-nouveaux-projets\/#article","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2010\/07\/19\/plan-regional-du-logement-11-nouveaux-projets\/"},"author":{"name":"Christos Doulkeridis","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365"},"headline":"Plan r\u00e9gional du logement : 11 nouveaux projets","datePublished":"2010-07-19T14:27:06+00:00","dateModified":"2011-08-09T13:04:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2010\/07\/19\/plan-regional-du-logement-11-nouveaux-projets\/"},"wordCount":306,"commentCount":0,"publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"keywords":["durabilit\u00e9","durable","Logement","logement social","passif"],"articleSection":["Logement","Mes r\u00e9alisations"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.doulkeridis.be\/blog\/2010\/07\/19\/plan-regional-du-logement-11-nouveaux-projets\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.doulkeridis.be\/blog\/2010\/07\/19\/plan-regional-du-logement-11-nouveaux-projets\/","url":"https:\/\/www.doulkeridis.be\/blog\/2010\/07\/19\/plan-regional-du-logement-11-nouveaux-projets\/","name":"Plan r\u00e9gional du logement : 11 nouveaux projets - Christos Doulkeridis","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#website"},"datePublished":"2010-07-19T14:27:06+00:00","dateModified":"2011-08-09T13:04:37+00:00","breadcrumb":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2010\/07\/19\/plan-regional-du-logement-11-nouveaux-projets\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doulkeridis.be\/blog\/2010\/07\/19\/plan-regional-du-logement-11-nouveaux-projets\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.doulkeridis.be\/blog\/2010\/07\/19\/plan-regional-du-logement-11-nouveaux-projets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.doulkeridis.be\/blog\/"},{"@type":"ListItem","position":2,"name":"Plan r\u00e9gional du logement : 11 nouveaux projets"}]},{"@type":"WebSite","@id":"https:\/\/www.doulkeridis.be\/blog\/#website","url":"https:\/\/www.doulkeridis.be\/blog\/","name":"Christos Doulkeridis","description":"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations","publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doulkeridis.be\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.doulkeridis.be\/blog\/#organization","name":"Ulyse","url":"https:\/\/www.doulkeridis.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","width":1024,"height":728,"caption":"Ulyse"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/doulkeridis","https:\/\/www.facebook.com\/christosdoulkeridis2"]},{"@type":"Person","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365","name":"Christos Doulkeridis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","caption":"Christos Doulkeridis"},"url":"https:\/\/www.doulkeridis.be\/blog\/author\/christos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/comments?post=755"}],"version-history":[{"count":5,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/755\/revisions"}],"predecessor-version":[{"id":791,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/755\/revisions\/791"}],"wp:attachment":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media?parent=755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/categories?post=755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/tags?post=755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}