{"id":822,"date":"2010-08-17T13:56:41","date_gmt":"2010-08-17T11:56:41","guid":{"rendered":"http:\/\/www.doulkeridis.be\/blog\/?p=822"},"modified":"2011-08-09T14:38:57","modified_gmt":"2011-08-09T12:38:57","slug":"cartes-de-la-belgique-episode-3-une-strategie-deliberee","status":"publish","type":"post","link":"https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/","title":{"rendered":"Cartes flamandes de la Belgique, \u00e9pisode 3: qu&rsquo;on ne parle plus de m\u00e9prise !"},"content":{"rendered":"<p><a href=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2010\/08\/carte-Flandre1.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-825\" title=\"carte Flandre\" src=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2010\/08\/carte-Flandre1-300x129.gif\" alt=\"\" width=\"300\" height=\"129\" srcset=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2010\/08\/carte-Flandre1-300x129.gif 300w, https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2010\/08\/carte-Flandre1.gif 585w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Alors l\u00e0, je suis effar\u00e9! Pourquoi? Et bien il suffit de jeter un \u0153il sur la publication en ligne d&rsquo;une carte destin\u00e9e au tourisme et qui montre une nouvelle fois une Flandre ind\u00e9pendante annexant la R\u00e9gion bruxelloise, \u00e0 c\u00f4t\u00e9 d&rsquo;un Etat belge aux fronti\u00e8res bien distinctes. Une carte que l&rsquo;on peut retrouver sur <a href=\"http:\/\/www.visitflanders.co.uk\" target=\"_blank\">le site de l\u2019office de promotion de la Flandre.<\/a><\/p>\n<p>La premi\u00e8re fois, la Flandre a parl\u00e9 de m\u00e9prise, je veux bien admettre. Ensuite, l&rsquo;erreur d&rsquo;un Tour-Op\u00e9rateur a \u00e9t\u00e9 justifi\u00e9e par un probl\u00e8me avec un fournisseur. Cette-fois, la coupe est pleine! Rien ne peut plus emp\u00eacher de penser \u00e0 une strat\u00e9gie d\u00e9lib\u00e9r\u00e9e, une volont\u00e9 profonde de pr\u00e9senter la Flandre comme \u00e9tant un pays \u00e0 part enti\u00e8re, annexant Bruxelles sans scrupules. C&rsquo;est particuli\u00e8rement interpellant en cette p\u00e9riode de n\u00e9gociations institutionnelles!<a href=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2010\/08\/carte-Flandre.gif\"><\/a><\/p>\n<p><strong><em>Dans la presse :<\/em><\/strong><\/p>\n<p><a href=\"http:\/\/archives.lesoir.be\/la-flandre-deboussole-la-belgique-vrienden-nog-een_t-20100818-010ZGH.html?action=nav&amp;nav=1&amp;pos=1&amp;all=473&amp;query=doulkeridis&amp;queryor=doulkeridis&amp;firstHit=0&amp;by=10&amp;when=-1&amp;sort=datedesc&amp;all=473\" target=\"_blank\">La Flandre d\u00e9boussole la Belgique (Le Soir)<\/a><\/p>\n<p><a href=\"http:\/\/www.lalibre.be\/actu\/elections-2010\/article\/603083\/doulkeridis-denonce-la-nouvelle-carte-flamande.html\" target=\"_blank\">Doulkeridis d\u00e9nonce la nouvelle carte flamande (La Libre Belgique)<\/a><\/p>\n<p><a href=\"http:\/\/www.dhnet.be\/infos\/belgique\/article\/321906\/doulkeridis-denonce-une-strategie-deliberee.html\" target=\"_blank\">Doulkeridis d\u00e9nonce une strat\u00e9gie d\u00e9lib\u00e9r\u00e9e (DH)<\/a><\/p>\n<p><a href=\"http:\/\/www.lavenir.net\/article\/detail.aspx?articleid=DMF20100817_057\" target=\"_blank\">Carte flamande : Toerisme Vlaanderen n&rsquo;en d\u00e9mord pas (L&rsquo;Avenir)<\/a><\/p>\n<p><a href=\"http:\/\/www.standaard.be\/artikel\/detail.aspx?artikelid=DMF20100817_081\" target=\"_blank\">Vlaamse landkaart zorgt weer voor beroering (Standaard)<\/a><\/p>\n<p><a href=\"http:\/\/www.hln.be\/hln\/nl\/1274\/De-formatie\/article\/detail\/1146078\/2010\/08\/17\/Landkaart-met-Brussel-als-Vlaamse-stad-zorgt-voor-ophef.dhtml\" target=\"_blank\">Landkaart met Brussel als Vlaamse stad zorgt voor ophef (Het Laatste Nieuws)<\/a><\/p>\n<p><a href=\"http:\/\/www.demorgen.be\/dm\/nl\/1341\/Belgie-in-politieke-crisis\/article\/detail\/1146078\/2010\/08\/17\/Landkaart-met-Brussel-als-Vlaamse-stad-zorgt-voor-ophef.dhtml\" target=\"_blank\">Landkaart met Brussel als Vlaamse stad zorgt voor ophef (De Morgen)<\/a><\/p>\n<p><em><strong>JT<\/strong><\/em> :<\/p>\n<p><a href=\"http:\/\/www.rtlinfo.be\/videos\/19h\/200345\" target=\"_blank\">www.rtlinfo.be<\/a><\/p>\n<p><a href=\"http:\/\/www.rtbf.be\/video\/v_jt-19h30?id=405832&amp;category=info\" target=\"_blank\">www.rtbf.be\/video\/<\/a> (premier reportage du JT)<\/p>\n<p><a href=\"http:\/\/www.tvbrussel.be\/programmas\/brussel-vandaag\/herbekijk\" target=\"_blank\">www.tvbrussel.be<\/a> (reportage apr\u00e8s 3 minutes 20)<\/p>\n<p><a href=\"http:\/\/jt.france2.fr\/13h\/\">jt.france2.fr\/13h\/<\/a> (mardi 18 ao\u00fbt 2010, d\u00e9but reportage apr\u00e8s 15 minutes 35)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors l\u00e0, je suis effar\u00e9! Pourquoi? Et bien il suffit de jeter un \u0153il sur la publication en ligne d&rsquo;une carte destin\u00e9e au tourisme et qui montre une nouvelle fois une Flandre ind\u00e9pendante annexant la R\u00e9gion bruxelloise, \u00e0 c\u00f4t\u00e9 d&rsquo;un Etat belge aux fronti\u00e8res bien distinctes. Une carte que l&rsquo;on peut retrouver sur le site de l\u2019office de promotion de la Flandre. La premi\u00e8re fois, la Flandre a parl\u00e9 de m\u00e9prise, je veux bien admettre. Ensuite, l&rsquo;erreur d&rsquo;un Tour-Op\u00e9rateur a \u00e9t\u00e9 justifi\u00e9e par un probl\u00e8me avec un fournisseur. Cette-fois, la coupe est pleine! Rien ne peut plus emp\u00eacher de penser \u00e0 une strat\u00e9gie d\u00e9lib\u00e9r\u00e9e, une volont\u00e9 profonde de pr\u00e9senter la Flandre comme \u00e9tant un pays \u00e0 part enti\u00e8re, annexant Bruxelles sans scrupules. C&rsquo;est particuli\u00e8rement interpellant en cette p\u00e9riode de n\u00e9gociations institutionnelles! Dans la presse : La Flandre d\u00e9boussole la Belgique (Le Soir) Doulkeridis d\u00e9nonce la nouvelle carte flamande (La Libre Belgique) Doulkeridis d\u00e9nonce une strat\u00e9gie d\u00e9lib\u00e9r\u00e9e (DH) Carte flamande : Toerisme Vlaanderen n&rsquo;en d\u00e9mord pas (L&rsquo;Avenir) Vlaamse landkaart zorgt weer voor beroering (Standaard) Landkaart met Brussel als Vlaamse stad zorgt voor ophef (Het Laatste Nieuws) Landkaart met Brussel als Vlaamse stad zorgt voor ophef (De Morgen) JT : www.rtlinfo.be www.rtbf.be\/video\/ [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[29,38,304,8],"tags":[119,414],"class_list":["post-822","post","type-post","status-publish","format-standard","hentry","category-bruxelles","category-institutionnel","category-mes_realisations","category-tourisme","tag-carte","tag-cartes-flamandes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cartes flamandes de la Belgique, \u00e9pisode 3: qu&#039;on ne parle plus de m\u00e9prise ! - Christos Doulkeridis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cartes flamandes de la Belgique, \u00e9pisode 3: qu&#039;on ne parle plus de m\u00e9prise ! - Christos Doulkeridis\" \/>\n<meta property=\"og:description\" content=\"Alors l\u00e0, je suis effar\u00e9! Pourquoi? Et bien il suffit de jeter un \u0153il sur la publication en ligne d&rsquo;une carte destin\u00e9e au tourisme et qui montre une nouvelle fois une Flandre ind\u00e9pendante annexant la R\u00e9gion bruxelloise, \u00e0 c\u00f4t\u00e9 d&rsquo;un Etat belge aux fronti\u00e8res bien distinctes. Une carte que l&rsquo;on peut retrouver sur le site de l\u2019office de promotion de la Flandre. La premi\u00e8re fois, la Flandre a parl\u00e9 de m\u00e9prise, je veux bien admettre. Ensuite, l&rsquo;erreur d&rsquo;un Tour-Op\u00e9rateur a \u00e9t\u00e9 justifi\u00e9e par un probl\u00e8me avec un fournisseur. Cette-fois, la coupe est pleine! Rien ne peut plus emp\u00eacher de penser \u00e0 une strat\u00e9gie d\u00e9lib\u00e9r\u00e9e, une volont\u00e9 profonde de pr\u00e9senter la Flandre comme \u00e9tant un pays \u00e0 part enti\u00e8re, annexant Bruxelles sans scrupules. C&rsquo;est particuli\u00e8rement interpellant en cette p\u00e9riode de n\u00e9gociations institutionnelles! Dans la presse : La Flandre d\u00e9boussole la Belgique (Le Soir) Doulkeridis d\u00e9nonce la nouvelle carte flamande (La Libre Belgique) Doulkeridis d\u00e9nonce une strat\u00e9gie d\u00e9lib\u00e9r\u00e9e (DH) Carte flamande : Toerisme Vlaanderen n&rsquo;en d\u00e9mord pas (L&rsquo;Avenir) Vlaamse landkaart zorgt weer voor beroering (Standaard) Landkaart met Brussel als Vlaamse stad zorgt voor ophef (Het Laatste Nieuws) Landkaart met Brussel als Vlaamse stad zorgt voor ophef (De Morgen) JT : www.rtlinfo.be www.rtbf.be\/video\/ [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/\" \/>\n<meta property=\"og:site_name\" content=\"Christos Doulkeridis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/doulkeridis\" \/>\n<meta property=\"article:published_time\" content=\"2010-08-17T11:56:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-08-09T12:38:57+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2010\/08\/carte-Flandre1-300x129.gif\" \/>\n<meta name=\"author\" content=\"Christos Doulkeridis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christos Doulkeridis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/08\\\/17\\\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/08\\\/17\\\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\\\/\"},\"author\":{\"name\":\"Christos Doulkeridis\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\"},\"headline\":\"Cartes flamandes de la Belgique, \u00e9pisode 3: qu&rsquo;on ne parle plus de m\u00e9prise !\",\"datePublished\":\"2010-08-17T11:56:41+00:00\",\"dateModified\":\"2011-08-09T12:38:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/08\\\/17\\\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\\\/\"},\"wordCount\":274,\"commentCount\":16,\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/08\\\/17\\\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/08\\\/carte-Flandre1-300x129.gif\",\"keywords\":[\"Carte\",\"Cartes flamandes\"],\"articleSection\":[\"Bruxelles\",\"Institutionnel\",\"Mes r\u00e9alisations\",\"Tourisme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/08\\\/17\\\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/08\\\/17\\\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/08\\\/17\\\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\\\/\",\"name\":\"Cartes flamandes de la Belgique, \u00e9pisode 3: qu'on ne parle plus de m\u00e9prise ! - Christos Doulkeridis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/08\\\/17\\\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/08\\\/17\\\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/08\\\/carte-Flandre1-300x129.gif\",\"datePublished\":\"2010-08-17T11:56:41+00:00\",\"dateModified\":\"2011-08-09T12:38:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/08\\\/17\\\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/08\\\/17\\\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/08\\\/17\\\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/08\\\/carte-Flandre1-300x129.gif\",\"contentUrl\":\"http:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/08\\\/carte-Flandre1-300x129.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2010\\\/08\\\/17\\\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartes flamandes de la Belgique, \u00e9pisode 3: qu&rsquo;on ne parle plus de m\u00e9prise !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"name\":\"Christos Doulkeridis\",\"description\":\"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\",\"name\":\"Ulyse\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"width\":1024,\"height\":728,\"caption\":\"Ulyse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/doulkeridis\",\"https:\\\/\\\/www.facebook.com\\\/christosdoulkeridis2\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\",\"name\":\"Christos Doulkeridis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"caption\":\"Christos Doulkeridis\"},\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/author\\\/christos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cartes flamandes de la Belgique, \u00e9pisode 3: qu'on ne parle plus de m\u00e9prise ! - Christos Doulkeridis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/","og_locale":"fr_FR","og_type":"article","og_title":"Cartes flamandes de la Belgique, \u00e9pisode 3: qu'on ne parle plus de m\u00e9prise ! - Christos Doulkeridis","og_description":"Alors l\u00e0, je suis effar\u00e9! Pourquoi? Et bien il suffit de jeter un \u0153il sur la publication en ligne d&rsquo;une carte destin\u00e9e au tourisme et qui montre une nouvelle fois une Flandre ind\u00e9pendante annexant la R\u00e9gion bruxelloise, \u00e0 c\u00f4t\u00e9 d&rsquo;un Etat belge aux fronti\u00e8res bien distinctes. Une carte que l&rsquo;on peut retrouver sur le site de l\u2019office de promotion de la Flandre. La premi\u00e8re fois, la Flandre a parl\u00e9 de m\u00e9prise, je veux bien admettre. Ensuite, l&rsquo;erreur d&rsquo;un Tour-Op\u00e9rateur a \u00e9t\u00e9 justifi\u00e9e par un probl\u00e8me avec un fournisseur. Cette-fois, la coupe est pleine! Rien ne peut plus emp\u00eacher de penser \u00e0 une strat\u00e9gie d\u00e9lib\u00e9r\u00e9e, une volont\u00e9 profonde de pr\u00e9senter la Flandre comme \u00e9tant un pays \u00e0 part enti\u00e8re, annexant Bruxelles sans scrupules. C&rsquo;est particuli\u00e8rement interpellant en cette p\u00e9riode de n\u00e9gociations institutionnelles! Dans la presse : La Flandre d\u00e9boussole la Belgique (Le Soir) Doulkeridis d\u00e9nonce la nouvelle carte flamande (La Libre Belgique) Doulkeridis d\u00e9nonce une strat\u00e9gie d\u00e9lib\u00e9r\u00e9e (DH) Carte flamande : Toerisme Vlaanderen n&rsquo;en d\u00e9mord pas (L&rsquo;Avenir) Vlaamse landkaart zorgt weer voor beroering (Standaard) Landkaart met Brussel als Vlaamse stad zorgt voor ophef (Het Laatste Nieuws) Landkaart met Brussel als Vlaamse stad zorgt voor ophef (De Morgen) JT : www.rtlinfo.be www.rtbf.be\/video\/ [&hellip;]","og_url":"https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/","og_site_name":"Christos Doulkeridis","article_publisher":"https:\/\/www.facebook.com\/doulkeridis","article_published_time":"2010-08-17T11:56:41+00:00","article_modified_time":"2011-08-09T12:38:57+00:00","og_image":[{"url":"http:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2010\/08\/carte-Flandre1-300x129.gif","type":"","width":"","height":""}],"author":"Christos Doulkeridis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Christos Doulkeridis","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/#article","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/"},"author":{"name":"Christos Doulkeridis","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365"},"headline":"Cartes flamandes de la Belgique, \u00e9pisode 3: qu&rsquo;on ne parle plus de m\u00e9prise !","datePublished":"2010-08-17T11:56:41+00:00","dateModified":"2011-08-09T12:38:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/"},"wordCount":274,"commentCount":16,"publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/#primaryimage"},"thumbnailUrl":"http:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2010\/08\/carte-Flandre1-300x129.gif","keywords":["Carte","Cartes flamandes"],"articleSection":["Bruxelles","Institutionnel","Mes r\u00e9alisations","Tourisme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/","url":"https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/","name":"Cartes flamandes de la Belgique, \u00e9pisode 3: qu'on ne parle plus de m\u00e9prise ! - Christos Doulkeridis","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/#primaryimage"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/#primaryimage"},"thumbnailUrl":"http:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2010\/08\/carte-Flandre1-300x129.gif","datePublished":"2010-08-17T11:56:41+00:00","dateModified":"2011-08-09T12:38:57+00:00","breadcrumb":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/#primaryimage","url":"http:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2010\/08\/carte-Flandre1-300x129.gif","contentUrl":"http:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2010\/08\/carte-Flandre1-300x129.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/www.doulkeridis.be\/blog\/2010\/08\/17\/cartes-de-la-belgique-episode-3-une-strategie-deliberee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.doulkeridis.be\/blog\/"},{"@type":"ListItem","position":2,"name":"Cartes flamandes de la Belgique, \u00e9pisode 3: qu&rsquo;on ne parle plus de m\u00e9prise !"}]},{"@type":"WebSite","@id":"https:\/\/www.doulkeridis.be\/blog\/#website","url":"https:\/\/www.doulkeridis.be\/blog\/","name":"Christos Doulkeridis","description":"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations","publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doulkeridis.be\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.doulkeridis.be\/blog\/#organization","name":"Ulyse","url":"https:\/\/www.doulkeridis.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","width":1024,"height":728,"caption":"Ulyse"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/doulkeridis","https:\/\/www.facebook.com\/christosdoulkeridis2"]},{"@type":"Person","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365","name":"Christos Doulkeridis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","caption":"Christos Doulkeridis"},"url":"https:\/\/www.doulkeridis.be\/blog\/author\/christos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/comments?post=822"}],"version-history":[{"count":13,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/822\/revisions"}],"predecessor-version":[{"id":831,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/822\/revisions\/831"}],"wp:attachment":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media?parent=822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/categories?post=822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/tags?post=822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}