{"id":9340,"date":"2013-05-21T14:40:21","date_gmt":"2013-05-21T13:40:21","guid":{"rendered":"http:\/\/www.doulkeridis.be\/blog\/?p=9340"},"modified":"2013-06-03T14:10:24","modified_gmt":"2013-06-03T13:10:24","slug":"la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois","status":"publish","type":"post","link":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/","title":{"rendered":"La transition \u00e9nerg\u00e9tique du logement social bruxellois obtient un soutien important de la BEI"},"content":{"rendered":"<p><a href=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/ELENA.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-9341\" alt=\"ELENA\" src=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/ELENA-300x109.jpg\" width=\"300\" height=\"109\" srcset=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/ELENA-300x109.jpg 300w, https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/ELENA.jpg 739w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>La Commission europ\u00e9enne et la Banque europ\u00e9enne d\u2019investissement (BEI) viennent de donner leur approbation \u00e0 la demande de financement de la R\u00e9gion Bruxelles-Capitale, via la SLRB, dans le cadre du Programme ELENA, le m\u00e9canisme europ\u00e9en d\u2019assistance technique pour les projets \u00e9nerg\u00e9tiques locaux. Elena financera ainsi au cours des prochaines ann\u00e9es jusqu\u2019\u00e0 90 % des co\u00fbts d\u2019une assistance technique (personnel, expertise, \u00e9tudes, audits \u00e9nerg\u00e9tiques\u2026) li\u00e9e \u00e0 l&rsquo;am\u00e9lioration de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique et d\u2019utilisation des \u00e9nergies renouvelables des b\u00e2timents dans le contexte de la transition \u00e9nerg\u00e9tique engag\u00e9e sous cette l\u00e9gislature dans le logement social bruxellois.<\/p>\n<p>C\u2019est \u00e0 la fois un soutien financier d\u2019importance et une reconnaissance de la qualit\u00e9 du programme d\u2019investissement engag\u00e9 par la SLRB et les soci\u00e9t\u00e9s de logement social dans la r\u00e9duction de la consommation \u00e9nerg\u00e9tique et de l\u2019empreinte \u00e9cologique du logement social bruxellois, au b\u00e9n\u00e9fice premier des locataires. C\u2019est aussi une contribution de la capitale europ\u00e9enne aux objectifs de l\u2019Union.<\/p>\n<p>ELENA s\u2019inscrit, en effet, dans le cadre de l\u2019action engag\u00e9e pour soutenir la r\u00e9alisation des objectifs de la politique du climat et de l\u2019\u00e9nergie de l\u2019Union europ\u00e9enne. Cette initiative conjointe de la BEI et de la Commission europ\u00e9enne vise \u00e0 aider les collectivit\u00e9s locales et r\u00e9gionales \u00e0 porter des projets favorisant l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique ou les \u00e9nergies renouvelables.<\/p>\n<p>Le plan pr\u00e9sent\u00e9 par la SLRB \u00e0 la BEI, baptis\u00e9 \u00ab VAMOS \u00bb (\u00ab Vert. une Aide \u00e0 la Ma\u00eetrise de l\u2019Ouvrage Social \u00bb) est bas\u00e9 sur un plan d\u2019investissement en 3 axes :<br \/>\n&#8211; la construction de logements passifs, dans le cadre du Plan logement : ELENA couvrira l\u2019expertise n\u00e9cessaire \u00e0 la construction de 500 logements sociaux passifs par an, g\u00e9n\u00e9rant une \u00e9conomie d\u2019\u00e9nergie de 3,5 GWh et 754 tonnes de CO2\/an par rapport \u00e0 des constructions traditionnelles;<br \/>\n&#8211; la r\u00e9novation des logements sociaux visant et au standard \u00ab basse \u00e9nergie \u00bb : 4000 logements sociaux s\u2019inscrivent dans des projets de r\u00e9novation \u00ab basse \u00e9nergie \u00bb et pourront b\u00e9n\u00e9ficier de l\u2019expertise financ\u00e9e par ELENA, g\u00e9n\u00e9rant des \u00e9conomies d\u2019\u00e9nergie de 33,9 GWh et une baisse des \u00e9missions de CO2 de 7.355 tonnes\/an par rapport aux logements avant r\u00e9novation ;<br \/>\n&#8211; le d\u00e9veloppement de la cog\u00e9n\u00e9ration pour les grands ensembles de logement sociaux : 5 projets de cog\u00e9n\u00e9ration seront install\u00e9es, g\u00e9n\u00e9rant 6,6 GWh et 1.425 tonnes de CO2 par an en moins que les syst\u00e8mes de chauffage traditionnels dans les 1400 logements vis\u00e9s. Le Conseil d&rsquo;administration a d\u00e9cid\u00e9 d&rsquo;attribuer 3 million d&rsquo;\u20ac pour financer les premiers projets.<\/p>\n<p>Les \u00e9conomies g\u00e9n\u00e9r\u00e9es de 8.000 t\/an de CO2 peuvent etre compar\u00e9es \u00e0 :<br \/>\n\u2022 La production de chaleur annuelle de +\/-96.000m\u00b2 de Panneau Solaire Thermique (rendement de conversion 39%) ;<br \/>\n\u2022 La production annuelle de +\/- 375.000m\u00b2 de Panneau Photovolta\u00efque (rendement 10%) ;<br \/>\n\u2022 La production annuelle de 2 Eoliennes (terre) de 2MW ;<br \/>\n\u2022 Les besoins nets en chauffage de +\/- 250.000 m\u00b2 de logements existants (+\/-3.100 logements (80m\u00b2\/log)) ;<br \/>\n\u2022 Les besoins nets en chauffage de +\/- 2.500.000 m\u00b2 de logements passifs (+\/-31.000 logements (80m\u00b2\/log)) ;<br \/>\n\u2022 (A 5 cts le kWh gaz) une \u00e9conomie de +\/- 1.900.000 \u20ac\/an.<\/p>\n<p>La s\u00e9lection du programme VAMOS par la BEI et la Commission europ\u00e9enne souligne l&rsquo;engagement fort et certain de la R\u00e9gion Bruxelloise dans une r\u00e9duction drastique de ses \u00e9missions de CO2, notamment dans le secteur du logement social, je f\u00e9licite au passage la SLRB pour la qualit\u00e9 du travail fourni afin d&rsquo;obtenir cette aide et cette reconnaissance europ\u00e9enne.<\/p>\n<p>Outre le soulagement que de nombreux locataires sociaux pourront percevoir sur leur note de chauffage, ces investissements conforteront d&rsquo;avantage Bruxelles dans son objectif dynamique d&rsquo;un d\u00e9veloppement durable de la ville et d&rsquo;une am\u00e9lioration de ses performances \u00e9nerg\u00e9tiques. Autant d&rsquo;arguments qui ont leur importance dans le cadre de la candidature de la R\u00e9gion en tant que Capitale Verte Europ\u00e9enne 2015.<\/p>\n<p>La SLRB se r\u00e9jouit que son action aupr\u00e8s de la Commission Europ\u00e9enne, visant directement la qualit\u00e9 de vie des plus d\u00e9munis, ait port\u00e9 ses fruits. Selon le Directeur g\u00e9n\u00e9ral de la SLRB, cette reconnaissance constitue une r\u00e9ponse concr\u00e8te \u00e0 la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique de nos habitants, et les associe \u00e9troitement au d\u00e9fi de demain pour la sauvegarde de notre plan\u00e8te.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Commission europ\u00e9enne et la Banque europ\u00e9enne d\u2019investissement (BEI) viennent de donner leur approbation \u00e0 la demande de financement de la R\u00e9gion Bruxelles-Capitale, via la SLRB, dans le cadre du Programme ELENA, le m\u00e9canisme europ\u00e9en d\u2019assistance technique pour les projets \u00e9nerg\u00e9tiques locaux. Elena financera ainsi au cours des prochaines ann\u00e9es jusqu\u2019\u00e0 90 % des co\u00fbts d\u2019une assistance technique (personnel, expertise, \u00e9tudes, audits \u00e9nerg\u00e9tiques\u2026) li\u00e9e \u00e0 l&rsquo;am\u00e9lioration de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique et d\u2019utilisation des \u00e9nergies renouvelables des b\u00e2timents dans le contexte de la transition \u00e9nerg\u00e9tique engag\u00e9e sous cette l\u00e9gislature dans le logement social bruxellois. C\u2019est \u00e0 la fois un soutien financier d\u2019importance et une reconnaissance de la qualit\u00e9 du programme d\u2019investissement engag\u00e9 par la SLRB et les soci\u00e9t\u00e9s de logement social dans la r\u00e9duction de la consommation \u00e9nerg\u00e9tique et de l\u2019empreinte \u00e9cologique du logement social bruxellois, au b\u00e9n\u00e9fice premier des locataires. C\u2019est aussi une contribution de la capitale europ\u00e9enne aux objectifs de l\u2019Union. ELENA s\u2019inscrit, en effet, dans le cadre de l\u2019action engag\u00e9e pour soutenir la r\u00e9alisation des objectifs de la politique du climat et de l\u2019\u00e9nergie de l\u2019Union europ\u00e9enne. Cette initiative conjointe de la BEI et de la Commission europ\u00e9enne vise \u00e0 aider les collectivit\u00e9s locales et r\u00e9gionales \u00e0 porter des [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9341,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[580,579,4,581],"class_list":["post-9340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-logement","tag-efficacite-energetique","tag-energie","tag-logement-social","tag-transition-energetique"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La transition \u00e9nerg\u00e9tique du logement social bruxellois obtient un soutien important de la BEI - Christos Doulkeridis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La transition \u00e9nerg\u00e9tique du logement social bruxellois obtient un soutien important de la BEI - Christos Doulkeridis\" \/>\n<meta property=\"og:description\" content=\"La Commission europ\u00e9enne et la Banque europ\u00e9enne d\u2019investissement (BEI) viennent de donner leur approbation \u00e0 la demande de financement de la R\u00e9gion Bruxelles-Capitale, via la SLRB, dans le cadre du Programme ELENA, le m\u00e9canisme europ\u00e9en d\u2019assistance technique pour les projets \u00e9nerg\u00e9tiques locaux. Elena financera ainsi au cours des prochaines ann\u00e9es jusqu\u2019\u00e0 90 % des co\u00fbts d\u2019une assistance technique (personnel, expertise, \u00e9tudes, audits \u00e9nerg\u00e9tiques\u2026) li\u00e9e \u00e0 l&rsquo;am\u00e9lioration de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique et d\u2019utilisation des \u00e9nergies renouvelables des b\u00e2timents dans le contexte de la transition \u00e9nerg\u00e9tique engag\u00e9e sous cette l\u00e9gislature dans le logement social bruxellois. C\u2019est \u00e0 la fois un soutien financier d\u2019importance et une reconnaissance de la qualit\u00e9 du programme d\u2019investissement engag\u00e9 par la SLRB et les soci\u00e9t\u00e9s de logement social dans la r\u00e9duction de la consommation \u00e9nerg\u00e9tique et de l\u2019empreinte \u00e9cologique du logement social bruxellois, au b\u00e9n\u00e9fice premier des locataires. C\u2019est aussi une contribution de la capitale europ\u00e9enne aux objectifs de l\u2019Union. ELENA s\u2019inscrit, en effet, dans le cadre de l\u2019action engag\u00e9e pour soutenir la r\u00e9alisation des objectifs de la politique du climat et de l\u2019\u00e9nergie de l\u2019Union europ\u00e9enne. Cette initiative conjointe de la BEI et de la Commission europ\u00e9enne vise \u00e0 aider les collectivit\u00e9s locales et r\u00e9gionales \u00e0 porter des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/\" \/>\n<meta property=\"og:site_name\" content=\"Christos Doulkeridis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/doulkeridis\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-21T13:40:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-06-03T13:10:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/ELENA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"739\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christos Doulkeridis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christos Doulkeridis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/21\\\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/21\\\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\\\/\"},\"author\":{\"name\":\"Christos Doulkeridis\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\"},\"headline\":\"La transition \u00e9nerg\u00e9tique du logement social bruxellois obtient un soutien important de la BEI\",\"datePublished\":\"2013-05-21T13:40:21+00:00\",\"dateModified\":\"2013-06-03T13:10:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/21\\\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\\\/\"},\"wordCount\":756,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/21\\\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/ELENA.jpg\",\"keywords\":[\"efficacit\u00e9 \u00e9nerg\u00e9tique\",\"\u00e9nergie\",\"logement social\",\"transition \u00e9nerg\u00e9tique\"],\"articleSection\":[\"Logement\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/21\\\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/21\\\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/21\\\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\\\/\",\"name\":\"La transition \u00e9nerg\u00e9tique du logement social bruxellois obtient un soutien important de la BEI - Christos Doulkeridis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/21\\\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/21\\\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/ELENA.jpg\",\"datePublished\":\"2013-05-21T13:40:21+00:00\",\"dateModified\":\"2013-06-03T13:10:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/21\\\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/21\\\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/21\\\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/ELENA.jpg\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/ELENA.jpg\",\"width\":739,\"height\":270},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/21\\\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La transition \u00e9nerg\u00e9tique du logement social bruxellois obtient un soutien important de la BEI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"name\":\"Christos Doulkeridis\",\"description\":\"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\",\"name\":\"Ulyse\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"width\":1024,\"height\":728,\"caption\":\"Ulyse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/doulkeridis\",\"https:\\\/\\\/www.facebook.com\\\/christosdoulkeridis2\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\",\"name\":\"Christos Doulkeridis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"caption\":\"Christos Doulkeridis\"},\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/author\\\/christos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La transition \u00e9nerg\u00e9tique du logement social bruxellois obtient un soutien important de la BEI - Christos Doulkeridis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/","og_locale":"fr_FR","og_type":"article","og_title":"La transition \u00e9nerg\u00e9tique du logement social bruxellois obtient un soutien important de la BEI - Christos Doulkeridis","og_description":"La Commission europ\u00e9enne et la Banque europ\u00e9enne d\u2019investissement (BEI) viennent de donner leur approbation \u00e0 la demande de financement de la R\u00e9gion Bruxelles-Capitale, via la SLRB, dans le cadre du Programme ELENA, le m\u00e9canisme europ\u00e9en d\u2019assistance technique pour les projets \u00e9nerg\u00e9tiques locaux. Elena financera ainsi au cours des prochaines ann\u00e9es jusqu\u2019\u00e0 90 % des co\u00fbts d\u2019une assistance technique (personnel, expertise, \u00e9tudes, audits \u00e9nerg\u00e9tiques\u2026) li\u00e9e \u00e0 l&rsquo;am\u00e9lioration de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique et d\u2019utilisation des \u00e9nergies renouvelables des b\u00e2timents dans le contexte de la transition \u00e9nerg\u00e9tique engag\u00e9e sous cette l\u00e9gislature dans le logement social bruxellois. C\u2019est \u00e0 la fois un soutien financier d\u2019importance et une reconnaissance de la qualit\u00e9 du programme d\u2019investissement engag\u00e9 par la SLRB et les soci\u00e9t\u00e9s de logement social dans la r\u00e9duction de la consommation \u00e9nerg\u00e9tique et de l\u2019empreinte \u00e9cologique du logement social bruxellois, au b\u00e9n\u00e9fice premier des locataires. C\u2019est aussi une contribution de la capitale europ\u00e9enne aux objectifs de l\u2019Union. ELENA s\u2019inscrit, en effet, dans le cadre de l\u2019action engag\u00e9e pour soutenir la r\u00e9alisation des objectifs de la politique du climat et de l\u2019\u00e9nergie de l\u2019Union europ\u00e9enne. Cette initiative conjointe de la BEI et de la Commission europ\u00e9enne vise \u00e0 aider les collectivit\u00e9s locales et r\u00e9gionales \u00e0 porter des [&hellip;]","og_url":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/","og_site_name":"Christos Doulkeridis","article_publisher":"https:\/\/www.facebook.com\/doulkeridis","article_published_time":"2013-05-21T13:40:21+00:00","article_modified_time":"2013-06-03T13:10:24+00:00","og_image":[{"width":739,"height":270,"url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/ELENA.jpg","type":"image\/jpeg"}],"author":"Christos Doulkeridis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Christos Doulkeridis","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/#article","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/"},"author":{"name":"Christos Doulkeridis","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365"},"headline":"La transition \u00e9nerg\u00e9tique du logement social bruxellois obtient un soutien important de la BEI","datePublished":"2013-05-21T13:40:21+00:00","dateModified":"2013-06-03T13:10:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/"},"wordCount":756,"commentCount":0,"publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/#primaryimage"},"thumbnailUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/ELENA.jpg","keywords":["efficacit\u00e9 \u00e9nerg\u00e9tique","\u00e9nergie","logement social","transition \u00e9nerg\u00e9tique"],"articleSection":["Logement"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/","url":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/","name":"La transition \u00e9nerg\u00e9tique du logement social bruxellois obtient un soutien important de la BEI - Christos Doulkeridis","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/#primaryimage"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/#primaryimage"},"thumbnailUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/ELENA.jpg","datePublished":"2013-05-21T13:40:21+00:00","dateModified":"2013-06-03T13:10:24+00:00","breadcrumb":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/#primaryimage","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/ELENA.jpg","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/ELENA.jpg","width":739,"height":270},{"@type":"BreadcrumbList","@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/21\/la-banque-europeenne-dinvestissement-bei-soutiendra-la-transition-energetique-du-logement-social-bruxellois\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.doulkeridis.be\/blog\/"},{"@type":"ListItem","position":2,"name":"La transition \u00e9nerg\u00e9tique du logement social bruxellois obtient un soutien important de la BEI"}]},{"@type":"WebSite","@id":"https:\/\/www.doulkeridis.be\/blog\/#website","url":"https:\/\/www.doulkeridis.be\/blog\/","name":"Christos Doulkeridis","description":"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations","publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doulkeridis.be\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.doulkeridis.be\/blog\/#organization","name":"Ulyse","url":"https:\/\/www.doulkeridis.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","width":1024,"height":728,"caption":"Ulyse"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/doulkeridis","https:\/\/www.facebook.com\/christosdoulkeridis2"]},{"@type":"Person","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365","name":"Christos Doulkeridis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","caption":"Christos Doulkeridis"},"url":"https:\/\/www.doulkeridis.be\/blog\/author\/christos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/9340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/comments?post=9340"}],"version-history":[{"count":6,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/9340\/revisions"}],"predecessor-version":[{"id":9476,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/9340\/revisions\/9476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media\/9341"}],"wp:attachment":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media?parent=9340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/categories?post=9340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/tags?post=9340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}