{"id":9419,"date":"2013-05-30T15:35:22","date_gmt":"2013-05-30T14:35:22","guid":{"rendered":"http:\/\/www.doulkeridis.be\/blog\/?p=9419"},"modified":"2013-05-30T15:35:22","modified_gmt":"2013-05-30T14:35:22","slug":"six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles","status":"publish","type":"post","link":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/","title":{"rendered":"Six nouveaux h\u00e9bergements touristiques labellis\u00e9s \u201dCl\u00e9 Verte\u201d \u00e0 Bruxelles"},"content":{"rendered":"<p><a href=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/cl\u00e9-verte1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9421\" alt=\"cl\u00e9 verte\" src=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/cl\u00e9-verte1.jpg\" width=\"482\" height=\"315\" srcset=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/cl\u00e9-verte1.jpg 482w, https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/cl\u00e9-verte1-300x196.jpg 300w\" sizes=\"auto, (max-width: 482px) 100vw, 482px\" \/><\/a>L\u2019\u00e9colabel international \u00ab Cl\u00e9 Verte \u00bb distinguant les \u00e9tablissements touristiques pour leurs performances environnementales vient d\u2019\u00eatre octroy\u00e9 \u00e0 6 nouveaux candidats bruxellois, ce qui porte \u00e0 28 le nombre de labellis\u00e9s dans la R\u00e9gion de Bruxelles-Capitale. 80% des auberges de jeunesse et centres d\u2019h\u00e9bergements pour jeunes bruxellois reconnus par la Commission communautaire fran\u00e7aise (COCOF) sont d\u00e9sormais \u00ab Cl\u00e9 Verte \u00bb.<br \/>\nOn le sait, la durabilit\u00e9 compte d\u00e9sormais \u00e9galement en mati\u00e8re de tourisme o\u00f9 des acheteurs institutionnels (pour les s\u00e9minaires) et certains visiteurs (voyages d\u2019agr\u00e9ment) cherchent des produits plus \u00ab verts \u00bb. Face \u00e0 ce ph\u00e9nom\u00e8ne, les \u00e9colabels et autres certifications se sont multipli\u00e9s, au risque de semer la confusion dans les esprits. Pour r\u00e9pondre \u00e0 l\u2019int\u00e9r\u00eat du secteur h\u00f4telier et d\u2019autres types d\u2019\u00e9tablissements touristiques implant\u00e9s en R\u00e9gion de Bruxelles-Capitale, en tant que Ministre bruxellois du Tourisme, j&rsquo;ai souhait\u00e9 instaurer un label clair et reconnu permettant de positionner Bruxelles en tant que destination durable d\u2019ici 2014. Au terme d\u2019une proc\u00e9dure de r\u00e9flexion et d\u2019analyse ind\u00e9pendante, son choix s\u2019est port\u00e9 fin 2010 sur le label international \u00ab Cl\u00e9 Verte \u00bb (ou \u00ab Green Key \u00bb, en anglais) repr\u00e9sent\u00e9 en Wallonie et \u00e0 Bruxelles par la F\u00e9d\u00e9ration Inter-Environnement Wallonie (IEW).<br \/>\nLe label Cl\u00e9 Verte fonctionne selon un syst\u00e8me de crit\u00e8res imp\u00e9ratifs, auxquels les candidats doivent satisfaire enti\u00e8rement, et de crit\u00e8res optionnels pour lesquels les candidats doivent obtenir au minimum un tiers du total des points en jeu. Ainsi les labellis\u00e9s r\u00e9pondent \u00e0 une s\u00e9rie d\u2019exigences dans des domaines vari\u00e9s et se distinguent par les d\u00e9marches qu\u2019ils entreprennent pour satisfaire aux crit\u00e8res optionnels. La labellisation est organis\u00e9e 2 fois par an. La Cl\u00e9 Verte est octroy\u00e9e pour un an et les labellis\u00e9s doivent faire preuve d\u2019une am\u00e9lioration continue, d\u2019ann\u00e9e en ann\u00e9e, en mati\u00e8re de gestion environnementale.<br \/>\nAujourd\u2019hui, le secteur h\u00f4telier bruxellois compte d\u00e9j\u00e0 pr\u00e8s de 2.500 chambres \u00ab Cl\u00e9 Verte \u00bb, ce qui repr\u00e9sente pr\u00e8s de 16% des chambres h\u00f4teli\u00e8res reconnues par la COCOF). Au niveau de l\u2019h\u00e9bergement pour jeunes, pr\u00e8s de 80 % de la capacit\u00e9 d\u2019accueil est concern\u00e9e, le label distinguant d\u00e9sormais 4 des 5 auberges et centres bruxellois reconnus par la COCOF soit 4\/5\u00e8mes des lits disponibles.<\/p>\n<p>Voici la liste des labellis\u00e9s du \u00ab premier cru \u00bb 2013 avec, pour chacun et \u00e0 titre d\u2019exemple, l\u2019une ou l\u2019autre bonne pratique environnementale justifiant \u2013 parmi beaucoup d\u2019autres ! \u2013 leur cons\u00e9cration :<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Le Diamant Brussels Conference &amp; Business Centre<\/strong> (Bd. A. Reyerslaan 80, 1030 Bruxelles &#8211; www.diamant.be) : centre de conf\u00e9rences de 20 salles, situ\u00e9 entre le quartier europ\u00e9en et l\u2019a\u00e9roport de Zaventem, qui s\u2019est distingu\u00e9 entre autres par ses initiatives en mati\u00e8re d\u2019alimentation durable et notamment le nombre de plats v\u00e9g\u00e9tariens propos\u00e9s aux visiteurs.<\/li>\n<li>\n<strong>Le B&amp;B Chambre Chocolat<\/strong> (145 rue de la Cambre, 1150 Bruxelles &#8211; http:\/\/www.bruxelleschambredhote.net\/) : chambre d\u2019h\u00f4tes situ\u00e9e \u00e0 deux pas du square Montgomery, qui a notamment mis en place des solutions plus durables en mati\u00e8re d\u2019\u00e9nergie (chaudi\u00e8re \u00e0 haut rendement et panneaux solaires) et de mobilit\u00e9 (mise \u00e0 disposition de v\u00e9los pour les visiteurs).<\/li>\n<\/ul>\n<ul>\n<li><strong>Le M\u00e9ridien Bruxelles<\/strong> (Carrefour de l&rsquo;Europe 3, 1000 Bruxelles &#8211; http:\/\/www.starwoodhotels.com\/lemeridien\/property\/overview\/index.html?propertyID=1914) : h\u00f4tel situ\u00e9 au c\u0153ur de la capitale, ayant d\u00e9velopp\u00e9 des initiatives int\u00e9ressantes notamment au niveau des d\u00e9chets (poubelles de tri, pr\u00e9vention au niveau des articles de toilette et des conditionnements alimentaires) et de la mobilit\u00e9 (r\u00e9duction pour les clients qui utilisent les transports en commun).<\/li>\n<li>\n<strong>L\u2019Auberge de Jeunesse de Bruxelles-G\u00e9n\u00e9ration Europe<\/strong> (4 rue de l\u2019El\u00e9phant, 1080 Bruxelles &#8211; http:\/\/www.lesaubergesdejeunesse.be\/Bruxelles-Generation-Europe,302?lang=fr) : h\u00e9bergement pour jeune localis\u00e9 \u00e0 Molenbeek, non loin du quartier Saint-G\u00e9ry, qui se distingue entre autres par sa politique en mati\u00e8re de responsabilit\u00e9 soci\u00e9tale et ses actions permettant de r\u00e9duire de fa\u00e7on significative sa consommation d\u2019eau.<\/li>\n<li>\n<strong>Le Foyer Europ\u00e9en<\/strong> (17 rue Traversi\u00e8re, 1210 Bruxelles &#8211; http:\/\/www.etr-brussels.be) : centre situ\u00e9 \u00e0 proximit\u00e9 du jardin botanique, qui accueille des \u00e9tudiants europ\u00e9ens et qui se distingue notamment pas sa gestion raisonn\u00e9e de l\u2019eau (utilisation d\u2019eau de pluie, limitation des d\u00e9bits) et sa toiture verte.<\/li>\n<li>\n<strong>Le Sleep Well Youth Hostel<\/strong> (23 rue du Damier, 1000 Bruxelles &#8211; www.sleepwell.be) : localis\u00e9 \u00e0 5 minutes de la Grand Place, cette auberge et h\u00f4tel de jeunes se distingue notamment par les produits locaux, bio et \u00e9quitables qu\u2019il propose aux visiteurs et son utilisation d\u2019\u00e9nergie renouvelable (\u00e9lectricit\u00e9 100 % verte).<\/li>\n<\/ul>\n<p>Sept h\u00e9bergements ont par ailleurs vu leur labellisation renouvel\u00e9e : le Radisson Blu Royal (Rue du Foss\u00e9-aux-Loups 47, 1000 Bruxelles) et le Radisson Blu EU (35 rue d\u2019Idalie, 1050 Bruxelles), l\u2019Auberge des 3 Fontaines (2057 chauss\u00e9e de Wavre, 1160 Bruxelles), le B&amp;B BiHome (15 avenue Mar\u00e9chal Foch, 1030 Bruxelles) , l\u2019h\u00f4tel Stanhope (9 rue du Commerce, 1000 Bruxelles), l\u2019h\u00f4tel Dolce La Hulpe Brussels (135 chauss\u00e9e de Bruxelles, 1310 La Hulpe), l\u2019h\u00f4tel Le Plaza (118-126 boulevard Adolphe Max, 1000 Bruxelles).<br \/>\nSoutenue notamment par la Brussels Hotels Association (BHA), cette initiative est port\u00e9e par la F\u00e9d\u00e9ration Inter-Environnement Wallonie, partenaire officiel de la FEE pour Bruxelles et la Wallonie, en collaboration \u00e9troite avec Wallonie-Bruxelles Tourisme (WBT), VisitBrussels, Brussels Booking Desk (BBD) et les associations professionnelles Hostels in Brussels, Bed &amp; Brussels et Brussels Special Venue, ainsi que l&rsquo;administration bruxelloise en charge du tourisme au sein de la COCOF.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9colabel international \u00ab Cl\u00e9 Verte \u00bb distinguant les \u00e9tablissements touristiques pour leurs performances environnementales vient d\u2019\u00eatre octroy\u00e9 \u00e0 6 nouveaux candidats bruxellois, ce qui porte \u00e0 28 le nombre de labellis\u00e9s dans la R\u00e9gion de Bruxelles-Capitale. 80% des auberges de jeunesse et centres d\u2019h\u00e9bergements pour jeunes bruxellois reconnus par la Commission communautaire fran\u00e7aise (COCOF) sont d\u00e9sormais \u00ab Cl\u00e9 Verte \u00bb. On le sait, la durabilit\u00e9 compte d\u00e9sormais \u00e9galement en mati\u00e8re de tourisme o\u00f9 des acheteurs institutionnels (pour les s\u00e9minaires) et certains visiteurs (voyages d\u2019agr\u00e9ment) cherchent des produits plus \u00ab verts \u00bb. Face \u00e0 ce ph\u00e9nom\u00e8ne, les \u00e9colabels et autres certifications se sont multipli\u00e9s, au risque de semer la confusion dans les esprits. Pour r\u00e9pondre \u00e0 l\u2019int\u00e9r\u00eat du secteur h\u00f4telier et d\u2019autres types d\u2019\u00e9tablissements touristiques implant\u00e9s en R\u00e9gion de Bruxelles-Capitale, en tant que Ministre bruxellois du Tourisme, j&rsquo;ai souhait\u00e9 instaurer un label clair et reconnu permettant de positionner Bruxelles en tant que destination durable d\u2019ici 2014. Au terme d\u2019une proc\u00e9dure de r\u00e9flexion et d\u2019analyse ind\u00e9pendante, son choix s\u2019est port\u00e9 fin 2010 sur le label international \u00ab Cl\u00e9 Verte \u00bb (ou \u00ab Green Key \u00bb, en anglais) repr\u00e9sent\u00e9 en Wallonie et \u00e0 Bruxelles par la F\u00e9d\u00e9ration Inter-Environnement Wallonie (IEW). Le label Cl\u00e9 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[8],"tags":[265,595,547,597,596],"class_list":["post-9419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tourisme","tag-cle-verte","tag-ecolabel","tag-ecolabellise","tag-federation-inter-environnement-wallonie","tag-iew"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Six nouveaux h\u00e9bergements touristiques labellis\u00e9s \u201dCl\u00e9 Verte\u201d \u00e0 Bruxelles - Christos Doulkeridis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Six nouveaux h\u00e9bergements touristiques labellis\u00e9s \u201dCl\u00e9 Verte\u201d \u00e0 Bruxelles - Christos Doulkeridis\" \/>\n<meta property=\"og:description\" content=\"L\u2019\u00e9colabel international \u00ab Cl\u00e9 Verte \u00bb distinguant les \u00e9tablissements touristiques pour leurs performances environnementales vient d\u2019\u00eatre octroy\u00e9 \u00e0 6 nouveaux candidats bruxellois, ce qui porte \u00e0 28 le nombre de labellis\u00e9s dans la R\u00e9gion de Bruxelles-Capitale. 80% des auberges de jeunesse et centres d\u2019h\u00e9bergements pour jeunes bruxellois reconnus par la Commission communautaire fran\u00e7aise (COCOF) sont d\u00e9sormais \u00ab Cl\u00e9 Verte \u00bb. On le sait, la durabilit\u00e9 compte d\u00e9sormais \u00e9galement en mati\u00e8re de tourisme o\u00f9 des acheteurs institutionnels (pour les s\u00e9minaires) et certains visiteurs (voyages d\u2019agr\u00e9ment) cherchent des produits plus \u00ab verts \u00bb. Face \u00e0 ce ph\u00e9nom\u00e8ne, les \u00e9colabels et autres certifications se sont multipli\u00e9s, au risque de semer la confusion dans les esprits. Pour r\u00e9pondre \u00e0 l\u2019int\u00e9r\u00eat du secteur h\u00f4telier et d\u2019autres types d\u2019\u00e9tablissements touristiques implant\u00e9s en R\u00e9gion de Bruxelles-Capitale, en tant que Ministre bruxellois du Tourisme, j&rsquo;ai souhait\u00e9 instaurer un label clair et reconnu permettant de positionner Bruxelles en tant que destination durable d\u2019ici 2014. Au terme d\u2019une proc\u00e9dure de r\u00e9flexion et d\u2019analyse ind\u00e9pendante, son choix s\u2019est port\u00e9 fin 2010 sur le label international \u00ab Cl\u00e9 Verte \u00bb (ou \u00ab Green Key \u00bb, en anglais) repr\u00e9sent\u00e9 en Wallonie et \u00e0 Bruxelles par la F\u00e9d\u00e9ration Inter-Environnement Wallonie (IEW). Le label Cl\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/\" \/>\n<meta property=\"og:site_name\" content=\"Christos Doulkeridis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/doulkeridis\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-30T14:35:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/cl\u00e9-verte1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"482\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christos Doulkeridis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christos Doulkeridis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/30\\\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/30\\\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\\\/\"},\"author\":{\"name\":\"Christos Doulkeridis\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\"},\"headline\":\"Six nouveaux h\u00e9bergements touristiques labellis\u00e9s \u201dCl\u00e9 Verte\u201d \u00e0 Bruxelles\",\"datePublished\":\"2013-05-30T14:35:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/30\\\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\\\/\"},\"wordCount\":948,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/30\\\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/cl\u00e9-verte1.jpg\",\"keywords\":[\"cl\u00e9 verte\",\"\u00e9colabel\",\"\u00e9colabellis\u00e9\",\"F\u00e9d\u00e9ration Inter-Environnement Wallonie\",\"IEW\"],\"articleSection\":[\"Tourisme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/30\\\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/30\\\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/30\\\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\\\/\",\"name\":\"Six nouveaux h\u00e9bergements touristiques labellis\u00e9s \u201dCl\u00e9 Verte\u201d \u00e0 Bruxelles - Christos Doulkeridis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/30\\\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/30\\\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/cl\u00e9-verte1.jpg\",\"datePublished\":\"2013-05-30T14:35:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/30\\\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/30\\\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/30\\\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/cl\u00e9-verte1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/05\\\/cl\u00e9-verte1.jpg\",\"width\":482,\"height\":315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/05\\\/30\\\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Six nouveaux h\u00e9bergements touristiques labellis\u00e9s \u201dCl\u00e9 Verte\u201d \u00e0 Bruxelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"name\":\"Christos Doulkeridis\",\"description\":\"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\",\"name\":\"Ulyse\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"width\":1024,\"height\":728,\"caption\":\"Ulyse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/doulkeridis\",\"https:\\\/\\\/www.facebook.com\\\/christosdoulkeridis2\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\",\"name\":\"Christos Doulkeridis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"caption\":\"Christos Doulkeridis\"},\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/author\\\/christos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Six nouveaux h\u00e9bergements touristiques labellis\u00e9s \u201dCl\u00e9 Verte\u201d \u00e0 Bruxelles - Christos Doulkeridis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/","og_locale":"fr_FR","og_type":"article","og_title":"Six nouveaux h\u00e9bergements touristiques labellis\u00e9s \u201dCl\u00e9 Verte\u201d \u00e0 Bruxelles - Christos Doulkeridis","og_description":"L\u2019\u00e9colabel international \u00ab Cl\u00e9 Verte \u00bb distinguant les \u00e9tablissements touristiques pour leurs performances environnementales vient d\u2019\u00eatre octroy\u00e9 \u00e0 6 nouveaux candidats bruxellois, ce qui porte \u00e0 28 le nombre de labellis\u00e9s dans la R\u00e9gion de Bruxelles-Capitale. 80% des auberges de jeunesse et centres d\u2019h\u00e9bergements pour jeunes bruxellois reconnus par la Commission communautaire fran\u00e7aise (COCOF) sont d\u00e9sormais \u00ab Cl\u00e9 Verte \u00bb. On le sait, la durabilit\u00e9 compte d\u00e9sormais \u00e9galement en mati\u00e8re de tourisme o\u00f9 des acheteurs institutionnels (pour les s\u00e9minaires) et certains visiteurs (voyages d\u2019agr\u00e9ment) cherchent des produits plus \u00ab verts \u00bb. Face \u00e0 ce ph\u00e9nom\u00e8ne, les \u00e9colabels et autres certifications se sont multipli\u00e9s, au risque de semer la confusion dans les esprits. Pour r\u00e9pondre \u00e0 l\u2019int\u00e9r\u00eat du secteur h\u00f4telier et d\u2019autres types d\u2019\u00e9tablissements touristiques implant\u00e9s en R\u00e9gion de Bruxelles-Capitale, en tant que Ministre bruxellois du Tourisme, j&rsquo;ai souhait\u00e9 instaurer un label clair et reconnu permettant de positionner Bruxelles en tant que destination durable d\u2019ici 2014. Au terme d\u2019une proc\u00e9dure de r\u00e9flexion et d\u2019analyse ind\u00e9pendante, son choix s\u2019est port\u00e9 fin 2010 sur le label international \u00ab Cl\u00e9 Verte \u00bb (ou \u00ab Green Key \u00bb, en anglais) repr\u00e9sent\u00e9 en Wallonie et \u00e0 Bruxelles par la F\u00e9d\u00e9ration Inter-Environnement Wallonie (IEW). Le label Cl\u00e9 [&hellip;]","og_url":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/","og_site_name":"Christos Doulkeridis","article_publisher":"https:\/\/www.facebook.com\/doulkeridis","article_published_time":"2013-05-30T14:35:22+00:00","og_image":[{"width":482,"height":315,"url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/cl\u00e9-verte1.jpg","type":"image\/jpeg"}],"author":"Christos Doulkeridis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Christos Doulkeridis","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/#article","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/"},"author":{"name":"Christos Doulkeridis","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365"},"headline":"Six nouveaux h\u00e9bergements touristiques labellis\u00e9s \u201dCl\u00e9 Verte\u201d \u00e0 Bruxelles","datePublished":"2013-05-30T14:35:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/"},"wordCount":948,"commentCount":1,"publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/cl\u00e9-verte1.jpg","keywords":["cl\u00e9 verte","\u00e9colabel","\u00e9colabellis\u00e9","F\u00e9d\u00e9ration Inter-Environnement Wallonie","IEW"],"articleSection":["Tourisme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/","url":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/","name":"Six nouveaux h\u00e9bergements touristiques labellis\u00e9s \u201dCl\u00e9 Verte\u201d \u00e0 Bruxelles - Christos Doulkeridis","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/#primaryimage"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/cl\u00e9-verte1.jpg","datePublished":"2013-05-30T14:35:22+00:00","breadcrumb":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/#primaryimage","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/cl\u00e9-verte1.jpg","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/05\/cl\u00e9-verte1.jpg","width":482,"height":315},{"@type":"BreadcrumbList","@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/05\/30\/six-nouveaux-hebergements-touristiques-labellises-cle-verte-a-bruxelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.doulkeridis.be\/blog\/"},{"@type":"ListItem","position":2,"name":"Six nouveaux h\u00e9bergements touristiques labellis\u00e9s \u201dCl\u00e9 Verte\u201d \u00e0 Bruxelles"}]},{"@type":"WebSite","@id":"https:\/\/www.doulkeridis.be\/blog\/#website","url":"https:\/\/www.doulkeridis.be\/blog\/","name":"Christos Doulkeridis","description":"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations","publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doulkeridis.be\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.doulkeridis.be\/blog\/#organization","name":"Ulyse","url":"https:\/\/www.doulkeridis.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","width":1024,"height":728,"caption":"Ulyse"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/doulkeridis","https:\/\/www.facebook.com\/christosdoulkeridis2"]},{"@type":"Person","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365","name":"Christos Doulkeridis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","caption":"Christos Doulkeridis"},"url":"https:\/\/www.doulkeridis.be\/blog\/author\/christos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/9419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/comments?post=9419"}],"version-history":[{"count":2,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/9419\/revisions"}],"predecessor-version":[{"id":9423,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/9419\/revisions\/9423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media\/9421"}],"wp:attachment":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media?parent=9419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/categories?post=9419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/tags?post=9419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}