{"id":9747,"date":"2013-06-25T14:00:33","date_gmt":"2013-06-25T13:00:33","guid":{"rendered":"http:\/\/www.doulkeridis.be\/blog\/?p=9747"},"modified":"2013-06-27T15:09:05","modified_gmt":"2013-06-27T14:09:05","slug":"52-logements-renoves-a-koekelberg","status":"publish","type":"post","link":"https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/","title":{"rendered":"52 logements r\u00e9nov\u00e9s \u00e0 Koekelberg"},"content":{"rendered":"<p><a href=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/06\/52-logements-r\u00e9nov\u00e9s-du-Foyer-Koekelbergeois-056.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-9756\" alt=\"52 logements r\u00e9nov\u00e9s du Foyer Koekelbergeois 056\" src=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/06\/52-logements-r\u00e9nov\u00e9s-du-Foyer-Koekelbergeois-056-300x200.jpg\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/06\/52-logements-r\u00e9nov\u00e9s-du-Foyer-Koekelbergeois-056-300x200.jpg 300w, https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/06\/52-logements-r\u00e9nov\u00e9s-du-Foyer-Koekelbergeois-056-1024x685.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Ce midi, en tant que Secr\u00e9taire d&rsquo;Etat au Logement, j&rsquo;ai particip\u00e9 \u00e0 l&rsquo;inauguration de 52 logements apr\u00e8s une r\u00e9novation lourde \u00e0 Koekelberg. Cet ensemble &#8211; avec une valeur patrimoniale certaine &#8211; est l&rsquo;oeuvre notamment des c\u00e9l\u00e8bres architectes modernistes Brunfaut et Bourgeois. Ce sont l\u00e0 des architectes qui s&rsquo;engageaient pour une architecture sociale, un engagement que j&rsquo;ai le plaisir de rencontrer parmi certains de nos architectes bruxellois d&rsquo;aujourd&rsquo;hui.<\/p>\n<p>La r\u00e9novation de ce type de patrimoine rencontre plusieurs difficult\u00e9s : d&rsquo;une part, le complexe se compose de 7 immeubles de styles diff\u00e9rents et d&rsquo;autre part, le d\u00e9fi est aussi de remettre aux normes contemporaines de confort des appartements construits au d\u00e9but des ann\u00e9es 20. En effet, cette r\u00e9novation s\u2019inscrit dans la politique de remise en \u00e9tat des logements les plus anciens du patrimoine du Foyer Koekelbergeois qui pour la plupart ne disposaient m\u00eame pas de salle de bain, ni de chauffage central.<\/p>\n<p>Bien que ce projet de r\u00e9novation lanc\u00e9 en 2005 ne tienne pas compte des normes basse \u00e9nergie obligatoires aujourd&rsquo;hui, on peut constater cependant un int\u00e9r\u00eat pour l&rsquo;\u00e9conomie d&rsquo;\u00e9nergie\u00a0: installation de chaudi\u00e8res collectives \u00e0 condensation (haut rendement) pour la production de chaleur et d\u2019eau chaude\u00a0; remise en \u00e9tat de l\u2019\u00e9tanch\u00e9it\u00e9 des toitures et l\u2019am\u00e9lioration de leur isolation par le placement de 10cm de verre cellulaire ( les 10 cm \u00a0apparaissent aujourd\u2019hui insuffisants pour r\u00e9pondre aux crit\u00e8res de \u00ab\u00a0hautes performances \u00e9nerg\u00e9tiques\u00a0\u00bb); l\u2019installation de 4 citernes d\u2019eaux de pluies alimentant les sanitaires\u00a0; le placement d\u2019\u00e9clairages \u00e9conomiques.<\/p>\n<p>Je f\u00e9licite les auteurs du projet qui ont travaill\u00e9 sur le respect des structures et des volumes existants.<\/p>\n<p>Les principes retenus pour ce projet sont d&rsquo;ordre \u00ab\u00e9conomique\u00bb. En plus de garder les structures existantes, de moderniser les installations techniques (chauffage, \u00e9lectricit\u00e9), de placer une salle de bain, une attention particuli\u00e8re \u00e9tait de garder le m\u00eame nombre de logements au minimum.<\/p>\n<p><b><i>Phasage<\/i><\/b><\/p>\n<p>Pour des raisons pratiques et \u00e9conomiques donc, le chantier a \u00e9t\u00e9 r\u00e9alis\u00e9 en 4 phases (8-16-16-11 logements). Ce phasage a \u00e9t\u00e9 conjoint d\u2019une op\u00e9ration tiroir. La taille de la soci\u00e9t\u00e9 et le taux de rotation (moins de 10% par\/an) ne permet par de reloger en quelques mois 51 familles dans des logements adapt\u00e9s \u00e0 leur composition de m\u00e9nage.<\/p>\n<p>La configuration des b\u00e2timents concern\u00e9s ici, se pr\u00eatait tr\u00e8s bien \u00e0 ce phasage et aux op\u00e9rations tiroir. Cela afin d\u2019\u00e9viter de trop longues p\u00e9riodes d\u2019inoccupation.<\/p>\n<p>Je f\u00e9licite le Foyer Koekelbergeois pour sa bonne strat\u00e9gie globale de r\u00e9novation de son patrimoine. C&rsquo;est une vision \u00e0 long terme qui porte des r\u00e9sultats. Le Foyer a programm\u00e9 la r\u00e9novation de tout son patrimoine en\u00a0 phases, tenant compte des r\u00e9alit\u00e9s de relogement, des r\u00e9alit\u00e9s financi\u00e8res et pratiques des chantiers.<\/p>\n<p><b><i>Bonne gestion <\/i><\/b><\/p>\n<p>Outre les projets de r\u00e9novation, je souhaite \u00e9galement f\u00e9liciter le FK pour le d\u00e9veloppement de ses projets de coh\u00e9sion sociale privil\u00e9giant le durable (compost, culture biologique, permacultures, etc.), l\u2019interculturel, la solidarit\u00e9 (entre les jardiniers notamment), et l\u2019interg\u00e9n\u00e9rationnel (activit\u00e9s en collaboration avec le home du CPAS et les \u00e9coles). Voici une gestion coh\u00e9rente sur le plan immobilier et social\u00a0!<\/p>\n<p><b><i>Logement 1 chambre<\/i><\/b><\/p>\n<p>Nous inaugurons ici 44 logements de 2 chambres et 8 appartements d\u20191 chambre. Une particularit\u00e9 que je voudrais souligner davantage\u00a0!<\/p>\n<p>Bien que la demande des familles nombreuses (plus de trois enfants) pour obtenir un grand logement est criante, il est important de constater que la demande des studios et logements 1 chambre est grandissante.<\/p>\n<p>C&rsquo;est pourquoi il me semble int\u00e9ressant d&rsquo;aborder \u00e0 cette occasion la question de l\u2019int\u00e9r\u00eat de conserver et de cr\u00e9er \u00e9galement des logements de petites tailles, comme c&rsquo;est le cas aujourd&rsquo;hui. (130% de demande par rapport \u00e0 l\u2019offre). C&rsquo;est une caract\u00e9ristique des grands centres urbains, donc la demande est importante. Les statistiques de demandes de logement social en 2012 , crois\u00e9es avec le patrimoine disponible en 2011 font clairement appara\u00eetre une insuffisance de petits logements.<\/p>\n<p>Aujourd&rsquo;hui, 45% des demandes concernent des studios ou appartements une chambre. Par contre, ce type de logement ne repr\u00e9sente que 33% de l&rsquo;offre au sein du patrimoine des SISP.\u00a0 Le r\u00f4le des pouvoirs publics est de proposer des solutions. C&rsquo;est pourquoi il importe de mettre en place de r\u00e9formes adapt\u00e9s \u00e0 la r\u00e9alit\u00e9 actuelle afin de permettre \u00e0 de nouvelles familles d&rsquo;acc\u00e9der \u00e0 un logement social.<\/p>\n<p>J&rsquo;ai ainsi mis en place diff\u00e9rentes mesures\u00a0:<\/p>\n<ul>\n<li><b>Adoption du bail \u00e0 dur\u00e9e d\u00e9termin\u00e9e<\/b>\u00a0:<\/li>\n<\/ul>\n<p>Depuis janvier 2013, les nouveaux contrats de bail dans le logement social seront \u00e9tablis pour une dur\u00e9e de 9 ans. Jusqu&rsquo;\u00e0 pr\u00e9sent, les baux dans le logement social \u00e9taient conclus \u00e0 dur\u00e9e ind\u00e9termin\u00e9e et seuls les loyers \u00e9voluaient en fonction des revenus des locataires.<\/p>\n<ul>\n<li><b>Assouplissement des normes d\u2019occupation<\/b><\/li>\n<\/ul>\n<p>Le Gouvernement s&rsquo;appr\u00eate \u00e0 adopter un arr\u00eat\u00e9\u00a0: locatif qui assouplira les r\u00e8gles d\u2019occupation et facilitera l&rsquo;acc\u00e8s \u00e0 un logement social pour les familles nombreuses. L&rsquo;accord stipule que deux enfants du m\u00eame sexe pourront d\u00e9sormais partager la m\u00eame chambre jusqu&rsquo;\u00e0 18 ans (avant 12 ans).\u00a0 Cet \u00e2ge \u00e9tant limit\u00e9 \u00e0 12 ans (avant 9 ans) s&rsquo;ils sont de sexes diff\u00e9rents.<\/p>\n<ul>\n<li>\u00a0<b>Renforcement des mutations rendues obligatoires<\/b><\/li>\n<\/ul>\n<p>La r\u00e9forme du Code du logement pr\u00e9voit que les mutations vers un logement plus petit seront d\u00e9sormais obligatoires lorsque les locataires occupent un logement comportant plus de deux chambres exc\u00e9dentaires. Et que la Sisp est en mesure de leur proposer un logement adapt\u00e9 \u00e0 la taille de leur m\u00e9nage, pr\u00e9sentant les m\u00eames conditions de confort et situ\u00e9 dans la m\u00eame commune ou dans un rayon de 5 km.Ne plus laisser des chambres vides<\/p>\n<p>Enfin, \u00e0 Koekelberg, en\u00a0mati\u00e8re de \u00ab\u00a0logements de qualit\u00e9 \u00e0 gestion publique et \u00e0 finalit\u00e9 sociale\u00a0\u00bb, le taux de l\u2019emprise publique sur le parc du logement s\u2019\u00e9l\u00e8ve actuellement \u00e0 14.9% (8\u00e8me). On avance dans la bonne direction puisque nous nous sommes fix\u00e9 comme objectif d&rsquo;atteindre les 15% de logements public \u00e0 finalit\u00e9 sociale sur l&rsquo;ensemble de la R\u00e9gion et des communes bruxelloises\u00a0! Dans le cadre du Plan r\u00e9gional du logement, le projet de construction de 25 logements sur un terrain de la commune (investissement estim\u00e9 \u00e0 3.425.000\u20ac)a eu l&rsquo;approbation du gouvernement et est actuellement \u00e0 l&rsquo;instruction par la SLRB.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce midi, en tant que Secr\u00e9taire d&rsquo;Etat au Logement, j&rsquo;ai particip\u00e9 \u00e0 l&rsquo;inauguration de 52 logements apr\u00e8s une r\u00e9novation lourde \u00e0 Koekelberg. Cet ensemble &#8211; avec une valeur patrimoniale certaine &#8211; est l&rsquo;oeuvre notamment des c\u00e9l\u00e8bres architectes modernistes Brunfaut et Bourgeois. Ce sont l\u00e0 des architectes qui s&rsquo;engageaient pour une architecture sociale, un engagement que j&rsquo;ai le plaisir de rencontrer parmi certains de nos architectes bruxellois d&rsquo;aujourd&rsquo;hui. La r\u00e9novation de ce type de patrimoine rencontre plusieurs difficult\u00e9s : d&rsquo;une part, le complexe se compose de 7 immeubles de styles diff\u00e9rents et d&rsquo;autre part, le d\u00e9fi est aussi de remettre aux normes contemporaines de confort des appartements construits au d\u00e9but des ann\u00e9es 20. En effet, cette r\u00e9novation s\u2019inscrit dans la politique de remise en \u00e9tat des logements les plus anciens du patrimoine du Foyer Koekelbergeois qui pour la plupart ne disposaient m\u00eame pas de salle de bain, ni de chauffage central. Bien que ce projet de r\u00e9novation lanc\u00e9 en 2005 ne tienne pas compte des normes basse \u00e9nergie obligatoires aujourd&rsquo;hui, on peut constater cependant un int\u00e9r\u00eat pour l&rsquo;\u00e9conomie d&rsquo;\u00e9nergie\u00a0: installation de chaudi\u00e8res collectives \u00e0 condensation (haut rendement) pour la production de chaleur et d\u2019eau chaude\u00a0; remise en \u00e9tat de l\u2019\u00e9tanch\u00e9it\u00e9 des [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9764,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[647,648,649,24],"class_list":["post-9747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-logement","tag-foyer-koekelbergeois","tag-koekelberg","tag-logement-une-chambre","tag-renovation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>52 logements r\u00e9nov\u00e9s \u00e0 Koekelberg - Christos Doulkeridis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"52 logements r\u00e9nov\u00e9s \u00e0 Koekelberg - Christos Doulkeridis\" \/>\n<meta property=\"og:description\" content=\"Ce midi, en tant que Secr\u00e9taire d&rsquo;Etat au Logement, j&rsquo;ai particip\u00e9 \u00e0 l&rsquo;inauguration de 52 logements apr\u00e8s une r\u00e9novation lourde \u00e0 Koekelberg. Cet ensemble &#8211; avec une valeur patrimoniale certaine &#8211; est l&rsquo;oeuvre notamment des c\u00e9l\u00e8bres architectes modernistes Brunfaut et Bourgeois. Ce sont l\u00e0 des architectes qui s&rsquo;engageaient pour une architecture sociale, un engagement que j&rsquo;ai le plaisir de rencontrer parmi certains de nos architectes bruxellois d&rsquo;aujourd&rsquo;hui. La r\u00e9novation de ce type de patrimoine rencontre plusieurs difficult\u00e9s : d&rsquo;une part, le complexe se compose de 7 immeubles de styles diff\u00e9rents et d&rsquo;autre part, le d\u00e9fi est aussi de remettre aux normes contemporaines de confort des appartements construits au d\u00e9but des ann\u00e9es 20. En effet, cette r\u00e9novation s\u2019inscrit dans la politique de remise en \u00e9tat des logements les plus anciens du patrimoine du Foyer Koekelbergeois qui pour la plupart ne disposaient m\u00eame pas de salle de bain, ni de chauffage central. Bien que ce projet de r\u00e9novation lanc\u00e9 en 2005 ne tienne pas compte des normes basse \u00e9nergie obligatoires aujourd&rsquo;hui, on peut constater cependant un int\u00e9r\u00eat pour l&rsquo;\u00e9conomie d&rsquo;\u00e9nergie\u00a0: installation de chaudi\u00e8res collectives \u00e0 condensation (haut rendement) pour la production de chaleur et d\u2019eau chaude\u00a0; remise en \u00e9tat de l\u2019\u00e9tanch\u00e9it\u00e9 des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/\" \/>\n<meta property=\"og:site_name\" content=\"Christos Doulkeridis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/doulkeridis\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-25T13:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-06-27T14:09:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/06\/52-logements-r\u00e9nov\u00e9s-du-Foyer-Koekelbergeois-0111-1024x685.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"685\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christos Doulkeridis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christos Doulkeridis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/06\\\/25\\\/52-logements-renoves-a-koekelberg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/06\\\/25\\\/52-logements-renoves-a-koekelberg\\\/\"},\"author\":{\"name\":\"Christos Doulkeridis\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\"},\"headline\":\"52 logements r\u00e9nov\u00e9s \u00e0 Koekelberg\",\"datePublished\":\"2013-06-25T13:00:33+00:00\",\"dateModified\":\"2013-06-27T14:09:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/06\\\/25\\\/52-logements-renoves-a-koekelberg\\\/\"},\"wordCount\":1094,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/06\\\/25\\\/52-logements-renoves-a-koekelberg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/52-logements-r\u00e9nov\u00e9s-du-Foyer-Koekelbergeois-0111.jpg\",\"keywords\":[\"Foyer Koekelbergeois\",\"Koekelberg\",\"logement une chambre\",\"r\u00e9novation\"],\"articleSection\":[\"Logement\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/06\\\/25\\\/52-logements-renoves-a-koekelberg\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/06\\\/25\\\/52-logements-renoves-a-koekelberg\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/06\\\/25\\\/52-logements-renoves-a-koekelberg\\\/\",\"name\":\"52 logements r\u00e9nov\u00e9s \u00e0 Koekelberg - Christos Doulkeridis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/06\\\/25\\\/52-logements-renoves-a-koekelberg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/06\\\/25\\\/52-logements-renoves-a-koekelberg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/52-logements-r\u00e9nov\u00e9s-du-Foyer-Koekelbergeois-0111.jpg\",\"datePublished\":\"2013-06-25T13:00:33+00:00\",\"dateModified\":\"2013-06-27T14:09:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/06\\\/25\\\/52-logements-renoves-a-koekelberg\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/06\\\/25\\\/52-logements-renoves-a-koekelberg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/06\\\/25\\\/52-logements-renoves-a-koekelberg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/52-logements-r\u00e9nov\u00e9s-du-Foyer-Koekelbergeois-0111.jpg\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/52-logements-r\u00e9nov\u00e9s-du-Foyer-Koekelbergeois-0111.jpg\",\"width\":3872,\"height\":2592},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/2013\\\/06\\\/25\\\/52-logements-renoves-a-koekelberg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"52 logements r\u00e9nov\u00e9s \u00e0 Koekelberg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"name\":\"Christos Doulkeridis\",\"description\":\"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#organization\",\"name\":\"Ulyse\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"contentUrl\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2-5.png\",\"width\":1024,\"height\":728,\"caption\":\"Ulyse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/doulkeridis\",\"https:\\\/\\\/www.facebook.com\\\/christosdoulkeridis2\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/#\\\/schema\\\/person\\\/9f03f3459f0a4ba4db02aabbba098365\",\"name\":\"Christos Doulkeridis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g\",\"caption\":\"Christos Doulkeridis\"},\"url\":\"https:\\\/\\\/www.doulkeridis.be\\\/blog\\\/author\\\/christos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"52 logements r\u00e9nov\u00e9s \u00e0 Koekelberg - Christos Doulkeridis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/","og_locale":"fr_FR","og_type":"article","og_title":"52 logements r\u00e9nov\u00e9s \u00e0 Koekelberg - Christos Doulkeridis","og_description":"Ce midi, en tant que Secr\u00e9taire d&rsquo;Etat au Logement, j&rsquo;ai particip\u00e9 \u00e0 l&rsquo;inauguration de 52 logements apr\u00e8s une r\u00e9novation lourde \u00e0 Koekelberg. Cet ensemble &#8211; avec une valeur patrimoniale certaine &#8211; est l&rsquo;oeuvre notamment des c\u00e9l\u00e8bres architectes modernistes Brunfaut et Bourgeois. Ce sont l\u00e0 des architectes qui s&rsquo;engageaient pour une architecture sociale, un engagement que j&rsquo;ai le plaisir de rencontrer parmi certains de nos architectes bruxellois d&rsquo;aujourd&rsquo;hui. La r\u00e9novation de ce type de patrimoine rencontre plusieurs difficult\u00e9s : d&rsquo;une part, le complexe se compose de 7 immeubles de styles diff\u00e9rents et d&rsquo;autre part, le d\u00e9fi est aussi de remettre aux normes contemporaines de confort des appartements construits au d\u00e9but des ann\u00e9es 20. En effet, cette r\u00e9novation s\u2019inscrit dans la politique de remise en \u00e9tat des logements les plus anciens du patrimoine du Foyer Koekelbergeois qui pour la plupart ne disposaient m\u00eame pas de salle de bain, ni de chauffage central. Bien que ce projet de r\u00e9novation lanc\u00e9 en 2005 ne tienne pas compte des normes basse \u00e9nergie obligatoires aujourd&rsquo;hui, on peut constater cependant un int\u00e9r\u00eat pour l&rsquo;\u00e9conomie d&rsquo;\u00e9nergie\u00a0: installation de chaudi\u00e8res collectives \u00e0 condensation (haut rendement) pour la production de chaleur et d\u2019eau chaude\u00a0; remise en \u00e9tat de l\u2019\u00e9tanch\u00e9it\u00e9 des [&hellip;]","og_url":"https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/","og_site_name":"Christos Doulkeridis","article_publisher":"https:\/\/www.facebook.com\/doulkeridis","article_published_time":"2013-06-25T13:00:33+00:00","article_modified_time":"2013-06-27T14:09:05+00:00","og_image":[{"width":1024,"height":685,"url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/06\/52-logements-r\u00e9nov\u00e9s-du-Foyer-Koekelbergeois-0111-1024x685.jpg","type":"image\/jpeg"}],"author":"Christos Doulkeridis","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Christos Doulkeridis","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/#article","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/"},"author":{"name":"Christos Doulkeridis","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365"},"headline":"52 logements r\u00e9nov\u00e9s \u00e0 Koekelberg","datePublished":"2013-06-25T13:00:33+00:00","dateModified":"2013-06-27T14:09:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/"},"wordCount":1094,"commentCount":0,"publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/06\/52-logements-r\u00e9nov\u00e9s-du-Foyer-Koekelbergeois-0111.jpg","keywords":["Foyer Koekelbergeois","Koekelberg","logement une chambre","r\u00e9novation"],"articleSection":["Logement"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/","url":"https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/","name":"52 logements r\u00e9nov\u00e9s \u00e0 Koekelberg - Christos Doulkeridis","isPartOf":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/#primaryimage"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/#primaryimage"},"thumbnailUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/06\/52-logements-r\u00e9nov\u00e9s-du-Foyer-Koekelbergeois-0111.jpg","datePublished":"2013-06-25T13:00:33+00:00","dateModified":"2013-06-27T14:09:05+00:00","breadcrumb":{"@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/#primaryimage","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/06\/52-logements-r\u00e9nov\u00e9s-du-Foyer-Koekelbergeois-0111.jpg","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2013\/06\/52-logements-r\u00e9nov\u00e9s-du-Foyer-Koekelbergeois-0111.jpg","width":3872,"height":2592},{"@type":"BreadcrumbList","@id":"https:\/\/www.doulkeridis.be\/blog\/2013\/06\/25\/52-logements-renoves-a-koekelberg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.doulkeridis.be\/blog\/"},{"@type":"ListItem","position":2,"name":"52 logements r\u00e9nov\u00e9s \u00e0 Koekelberg"}]},{"@type":"WebSite","@id":"https:\/\/www.doulkeridis.be\/blog\/#website","url":"https:\/\/www.doulkeridis.be\/blog\/","name":"Christos Doulkeridis","description":"Coach | Consultant en solutions, gestion de crise, n\u00e9gociations","publisher":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.doulkeridis.be\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.doulkeridis.be\/blog\/#organization","name":"Ulyse","url":"https:\/\/www.doulkeridis.be\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","contentUrl":"https:\/\/www.doulkeridis.be\/blog\/wp-content\/uploads\/2026\/04\/2-5.png","width":1024,"height":728,"caption":"Ulyse"},"image":{"@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/doulkeridis","https:\/\/www.facebook.com\/christosdoulkeridis2"]},{"@type":"Person","@id":"https:\/\/www.doulkeridis.be\/blog\/#\/schema\/person\/9f03f3459f0a4ba4db02aabbba098365","name":"Christos Doulkeridis","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/71cb6e4369ca0615d93730ef3bc5f54642df4f6bcc59b92763d2ac434abf103e?s=96&d=mm&r=g","caption":"Christos Doulkeridis"},"url":"https:\/\/www.doulkeridis.be\/blog\/author\/christos\/"}]}},"_links":{"self":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/9747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/comments?post=9747"}],"version-history":[{"count":11,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/9747\/revisions"}],"predecessor-version":[{"id":9760,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/posts\/9747\/revisions\/9760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media\/9764"}],"wp:attachment":[{"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/media?parent=9747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/categories?post=9747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.doulkeridis.be\/blog\/wp-json\/wp\/v2\/tags?post=9747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}